{"id":2742,"date":"2020-05-08T10:00:33","date_gmt":"2020-05-08T08:00:33","guid":{"rendered":"https:\/\/comunicacity.net\/solofra\/?p=2742"},"modified":"2020-05-07T10:28:46","modified_gmt":"2020-05-07T08:28:46","slug":"09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/","title":{"rendered":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza."},"content":{"rendered":"<div>in allegato comunicato della Solofra Servizi.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>in allegato comunicato della Solofra Servizi.<\/p>\n","protected":false},"author":194,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2742","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra\" \/>\n<meta property=\"og:description\" content=\"in allegato comunicato della Solofra Servizi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/\" \/>\n<meta property=\"og:site_name\" content=\"Solofra\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-08T08:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/solofra\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pasqualecorreale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pasqualecorreale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/\"},\"author\":{\"name\":\"pasqualecorreale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"headline\":\"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza.\",\"datePublished\":\"2020-05-08T08:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/\"},\"wordCount\":16,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/\",\"name\":\"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\"},\"datePublished\":\"2020-05-08T08:00:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/08\\\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\",\"name\":\"Solofra\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\",\"name\":\"pasqualecorreale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"caption\":\"pasqualecorreale\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/author\\\/pasqualecorreale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/","og_locale":"it_IT","og_type":"article","og_title":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra","og_description":"in allegato comunicato della Solofra Servizi.","og_url":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/","og_site_name":"Solofra","article_published_time":"2020-05-08T08:00:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/solofra\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"pasqualecorreale","twitter_misc":{"Scritto da":"pasqualecorreale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/"},"author":{"name":"pasqualecorreale","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"headline":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza.","datePublished":"2020-05-08T08:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/"},"wordCount":16,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/","url":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/","name":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza. - Solofra","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/#website"},"datePublished":"2020-05-08T08:00:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/08\/09-05-2020-interruzione-energia-elettrica-pozzo-in-via-nuova-scorza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/solofra\/"},{"@type":"ListItem","position":2,"name":"09-05-2020 Interruzione energia elettrica POZZO in via Nuova Scorza."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/solofra\/#website","url":"https:\/\/comunicacity.net\/solofra\/","name":"Solofra","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/solofra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd","name":"pasqualecorreale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","caption":"pasqualecorreale"},"url":"https:\/\/comunicacity.net\/solofra\/author\/pasqualecorreale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/users\/194"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/comments?post=2742"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2742\/revisions"}],"predecessor-version":[{"id":2744,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2742\/revisions\/2744"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media?parent=2742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/categories?post=2742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/tags?post=2742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}