{"id":2768,"date":"2020-05-14T08:07:30","date_gmt":"2020-05-14T06:07:30","guid":{"rendered":"https:\/\/comunicacity.net\/solofra\/?p=2768"},"modified":"2020-05-14T08:07:30","modified_gmt":"2020-05-14T06:07:30","slug":"intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/","title":{"rendered":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30"},"content":{"rendered":"<p>Le vie interessate (intervalli dei civici &#8220;da&#8221; &#8220;a&#8221; raggruppati per pari e\/o dispari) sono:<\/p>\n<p>&#8211; Vi aldo moro da 2 a 4, da 8 a 20, da 26 a 26b, da 1 a 13,17, da 25 a 35, sn<br \/>\n&#8211; Via Lavinaio da 2 a16, da 1D a 3, 9, da 23 a 27, sn, tim<br \/>\n&#8211; Via Ronca da 2 a 10 , da 14 a 30, 1 , da 5 a 7, da 11 a 25<br \/>\n&#8211; Via della libert\u00e0 da 2 a 8, 18, da 23 a 27, sn<br \/>\n&#8211; Piazza umberto I da 24 a 32, da 1c a 9, 13, sn<br \/>\n&#8211; Via de stefano 20, da 26 a 30, 11, 29,55<br \/>\n&#8211; Via landolfi da 2 a 4, 3, da 11 a 15<br \/>\n&#8211; Via maffei 9,13, tim<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vie interessate (intervalli dei civici &#8220;da&#8221; &#8220;a&#8221; raggruppati per pari e\/o dispari) sono: &#8211; Vi aldo moro da 2 a 4, da 8 a 20, da 26 a 26b, [&hellip;]<\/p>\n","protected":false},"author":194,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2768","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra\" \/>\n<meta property=\"og:description\" content=\"Le vie interessate (intervalli dei civici &#8220;da&#8221; &#8220;a&#8221; raggruppati per pari e\/o dispari) sono: &#8211; Vi aldo moro da 2 a 4, da 8 a 20, da 26 a 26b, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/\" \/>\n<meta property=\"og:site_name\" content=\"Solofra\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T06:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/solofra\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pasqualecorreale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pasqualecorreale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/\"},\"author\":{\"name\":\"pasqualecorreale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"headline\":\"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30\",\"datePublished\":\"2020-05-14T06:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/\"},\"wordCount\":101,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/\",\"name\":\"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\"},\"datePublished\":\"2020-05-14T06:07:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2020\\\/05\\\/14\\\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\",\"name\":\"Solofra\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\",\"name\":\"pasqualecorreale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"caption\":\"pasqualecorreale\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/author\\\/pasqualecorreale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/","og_locale":"it_IT","og_type":"article","og_title":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra","og_description":"Le vie interessate (intervalli dei civici &#8220;da&#8221; &#8220;a&#8221; raggruppati per pari e\/o dispari) sono: &#8211; Vi aldo moro da 2 a 4, da 8 a 20, da 26 a 26b, [&hellip;]","og_url":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/","og_site_name":"Solofra","article_published_time":"2020-05-14T06:07:30+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/solofra\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"pasqualecorreale","twitter_misc":{"Scritto da":"pasqualecorreale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/"},"author":{"name":"pasqualecorreale","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"headline":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30","datePublished":"2020-05-14T06:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/"},"wordCount":101,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/","url":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/","name":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30 - Solofra","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/#website"},"datePublished":"2020-05-14T06:07:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/solofra\/2020\/05\/14\/intervento-di-manutenzione-straordinaria-e-distribuzione-giovedi-14-maggio-dalle-ore-0930-alle-ore-1530\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/solofra\/"},{"@type":"ListItem","position":2,"name":"Intervento di manutenzione straordinaria E-distribuzione. GIoved\u00ec 14 maggio dalle ore 09:30 alle ore 15:30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/solofra\/#website","url":"https:\/\/comunicacity.net\/solofra\/","name":"Solofra","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/solofra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd","name":"pasqualecorreale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","caption":"pasqualecorreale"},"url":"https:\/\/comunicacity.net\/solofra\/author\/pasqualecorreale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/users\/194"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/comments?post=2768"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2768\/revisions"}],"predecessor-version":[{"id":2769,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2768\/revisions\/2769"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media?parent=2768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/categories?post=2768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/tags?post=2768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}