{"id":1790,"date":"2022-08-31T18:21:43","date_gmt":"2022-08-31T16:21:43","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=1790"},"modified":"2022-08-31T18:21:43","modified_gmt":"2022-08-31T16:21:43","slug":"autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/","title":{"rendered":"AUTOGUIDOVIE &#8211; SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana"},"content":{"rendered":"<p><strong>Comunichiamo che la societ\u00e0 AUTOGUIDOVIE ha aderito all\u2019istanza<\/strong> avanzata lo scorso mese di luglio dall\u2019amministrazione comunale di Sommo, con la quale si richiedeva la possibilit\u00e0 di <strong>far entrare in Sommo la corsa della linea 168\u00a0 PAVIA-DORNO con partenza da Pavia alle ore 13,00<\/strong> che normalmente non entrava a Sommo ma da Cava Manara proseguiva direttamente per Zinasco.<\/p>\n<p>L\u2019istanza era stata presentata dopo aver ricevuto diverse richieste da parte di cittadini residenti in merito alla possibilit\u00e0 di poter contare su un incremento delle corse di ritorno da Pavia.<\/p>\n<p>In modo particolare, parlando con loro, l\u2019esigenza pi\u00f9 ricorrente riguardava la copertura della fascia oraria tra le 11,18 e le 14,17 sul ritorno da Pavia. L\u2019incremento di una corsa sarebbe risultato molto utile per coloro che devono rientrare da Pavia dopo aver svolto durante la mattina visite mediche, sbrigato pratiche nei vari uffici sempre a Pavia o per chi svolge attivit\u00e0 lavorative a servizio ecc.<\/p>\n<p>Dopo aver consultato l&#8217;orario delle corse gi\u00e0 in vigore, ci siamo interfacciati con i Responsabili di AUTOGUIDOVIE chiedendo di valutare la possibilit\u00e0 di far entrare in Sommo la corsa gi\u00e0 prevista nel palinsesto, in partenza alle ore 13\u00a0 da Pavia, che si colloca appunto nella fascia oraria critica senza dovere in questo modo aumentare il numero delle corse del palinsesto stesso.<\/p>\n<p>Soprattutto in questo difficile momento storico, caratterizzato dai rincari energetici e dei carburanti che inevitabilmente si ripercuotono pesantemente sui bilanci familiari, abbiamo sottolineato l\u2019importanza dell\u2019accoglimento della richiesta.<\/p>\n<p>L&#8217;aumento del prezzo dei carburanti evidentemente spinge i cittadini a riconsiderare le opportunit\u00e0 di utilizzo del trasporto pubblico &#8211; se efficiente \u2013\u00a0 in grado di andare incontro alle necessit\u00e0 dei residenti.<\/p>\n<p>I Responsabili di AUTOGUIDOVIE hanno aderito alla nostra richiesta dapprima limitandola al solo periodo estivo (mesi di luglio e agosto) ma, all\u2019inizio del mese di agosto hanno aderito anche alla richiesta di prolungare il servizio anche oltre il periodo estivo, <strong>comunicando e confermando che la corsa delle ore 13 (da Pavia) continuer\u00e0 ad entrare in Sommo anche per tutto il prossimo periodo \u201cINVERNALE \u00a0e SCOLASTICO\u201d che inizier\u00e0 il prossimo 12 settembre.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Pertanto di seguito indichiamo gli orari delle fermate <u>della <strong>corsa LINEA 168 PAVIA-DORNO con partenza da Pavia alle ore 13:<\/strong><\/u><\/p>\n<p><strong>PAVIA<\/strong> autostazione partenza\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13<\/p>\n<p>S.MARTINO SP.35 \u2013 Turati\/Togliatti\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13.07<\/p>\n<p>S.MARTINO SP.35 \u2013 Giovi\/Gramsci,8\u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13.10<\/p>\n<p>CAVA M. XXV Aprile\/Olivelli\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13.11<\/p>\n<p>CAVA M. Gramsci\/Vitt.Emanuele II\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13.12<\/p>\n<p>CAVA M. Garibaldi\/Costa\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ore 13.14<\/p>\n<p>CAVA M. SP193 Alessandria\/Moro\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ore 13.15<\/p>\n<p><strong>e arrivo a Sommo:<\/strong><\/p>\n<p><strong>S.Fedele ore 13,19<\/strong><\/p>\n<p><strong>Municipio ore 13,18<\/strong><\/p>\n<p>per proseguire per Zinasco e poi sino al capolinea.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche a nome di tutta la cittadinanza ringraziamo AUTOGUIDOVIE per la sensibilit\u00e0 e la disponibilit\u00e0 dimostrata. Un particolare ringraziamento al\u00a0 Responsabile di Esercizio \/ Gestore dei Trasporti Ambito Urbano ed Extraurbano della Provincia di Pavia sig. \u00a0Oscar PETRIS e al Responsabile di zona sig. Salvatore LENTINI.<\/p>\n<p>Riepilogando,\u00a0 complessivamente <strong>le <u>corse giornaliere di ANDATA\u00a0 da SOMMO per Pavia della linea 168 attualmente sono complessivamente\u00a0 9<\/u> <\/strong>e rispettano il seguente orario INVERNALE e SCOLASTICO (dal luned\u00ec al venerd\u00ec) pubblicato anche sul sito di AUTOGUIDOVIE :<br \/>\n<strong><u>partenza da SOMMO:<\/u><\/strong><\/p>\n<p>SOMMO\u00a0 Municipio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a006.38\u00a0 \u00a007.09\u00a0 \u00a008.29\u00a0 \u00a010.24\u00a0 13.26\u00a0 \u00a015.24\u00a0 \u00a016.46 \u00a0\u00a017.24 \u00a0\u00a018.26<\/p>\n<p>SOMMO S.Fedele\/Laudi\u00a0 06.40\u00a0 \u00a007.11\u00a0 \u00a008.31 \u00a0\u00a010.25\u00a0 13.27\u00a0 \u00a015.25\u00a0 \u00a016.47\u00a0 \u00a017.25\u00a0 \u00a018.27<\/p>\n<p>&nbsp;<\/p>\n<p>Mentre <strong><u>le corse giornaliere di RITORNO da PAVIA per SOMMO della linea 168 attualmente sono complessivamente\u00a0 8<\/u>\u00a0 <\/strong>e rispettano il seguente orario INVERNALE e SCOLASTICO (dal luned\u00ec al venerd\u00ec) :<\/p>\n<p><strong>arrivo a SOMMO<\/strong>:<\/p>\n<p>SOMMO Municipio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 08.08 \u00a0\u00a011.18 \u00a0\u00a013.18 \u00a0\u00a014.17 \u00a0\u00a015.02 \u00a0\u00a016.17 \u00a0\u00a018.25 \u00a0\u00a019.22<\/p>\n<p>SOMMO S.Fedele\/Laudi\u00a0\u00a0 08.09\u00a0 \u00a011.19 \u00a0\u00a013.19 \u00a0\u00a014.18\u00a0 \u00a015.03 \u00a0\u00a016.18 \u00a0\u00a018.26 \u00a0\u00a019.23<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunichiamo che la societ\u00e0 AUTOGUIDOVIE ha aderito all\u2019istanza avanzata lo scorso mese di luglio dall\u2019amministrazione comunale di Sommo, con la quale si richiedeva la possibilit\u00e0 di far entrare in Sommo [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":1056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo\" \/>\n<meta property=\"og:description\" content=\"Comunichiamo che la societ\u00e0 AUTOGUIDOVIE ha aderito all\u2019istanza avanzata lo scorso mese di luglio dall\u2019amministrazione comunale di Sommo, con la quale si richiedeva la possibilit\u00e0 di far entrare in Sommo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T16:21:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"303\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"AUTOGUIDOVIE &#8211; SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana\",\"datePublished\":\"2022-08-31T16:21:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/\"},\"wordCount\":555,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2020\\\/07\\\/index_1.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/\",\"name\":\"AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2020\\\/07\\\/index_1.jpg\",\"datePublished\":\"2022-08-31T16:21:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2020\\\/07\\\/index_1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2020\\\/07\\\/index_1.jpg\",\"width\":303,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/08\\\/31\\\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUTOGUIDOVIE &#8211; SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/","og_locale":"it_IT","og_type":"article","og_title":"AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo","og_description":"Comunichiamo che la societ\u00e0 AUTOGUIDOVIE ha aderito all\u2019istanza avanzata lo scorso mese di luglio dall\u2019amministrazione comunale di Sommo, con la quale si richiedeva la possibilit\u00e0 di far entrare in Sommo [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-08-31T16:21:43+00:00","og_image":[{"width":303,"height":166,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"AUTOGUIDOVIE &#8211; SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana","datePublished":"2022-08-31T16:21:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/"},"wordCount":555,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/","url":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/","name":"AUTOGUIDOVIE - SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg","datePublished":"2022-08-31T16:21:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2020\/07\/index_1.jpg","width":303,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2022\/08\/31\/autoguidovie-sommo-trasporto-pubblico-locale-incremento-di-1-corsa-pomeridiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"AUTOGUIDOVIE &#8211; SOMMO Trasporto Pubblico Locale incremento di 1 corsa pomeridiana"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=1790"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1790\/revisions"}],"predecessor-version":[{"id":1791,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1790\/revisions\/1791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/1056"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=1790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=1790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=1790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}