{"id":1926,"date":"2022-11-01T18:42:19","date_gmt":"2022-11-01T17:42:19","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=1926"},"modified":"2022-11-01T18:42:19","modified_gmt":"2022-11-01T17:42:19","slug":"trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/","title":{"rendered":"Trentennale della Fondazione Museo &#8220;Angela e Luisa De Luigi&#8221; &#8211; Domenica 6 novembre  2022"},"content":{"rendered":"<p>Domenica 6 novembre 2022, in occasione del trentennale della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d appuntamento presso la sede della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d <strong>alle ore 10.30 in Piazza del Municipio a Sommo<\/strong> per assistere alla presentazione del libro<\/p>\n<p style=\"text-align: center\"><strong>\u201cIL MAESTRO RACCONTA\u201d<\/strong> da un\u2019idea di Angela De Luigi<\/p>\n<p style=\"text-align: center\">\u00a0a cura di Chiara Costa e Luciano Zanoni<\/p>\n<p>A seguire : aperitivo Sapori d\u2019Autunno<\/p>\n<p>Nel pomeriggio sar\u00e0 possibile visitare il Museo di Sommo \u201cPovere cose di povera gente\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1927\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-1024x725.jpg\" alt=\"\" width=\"640\" height=\"453\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-1024x725.jpg 1024w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-300x212.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-768x544.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-1536x1087.jpg 1536w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2-2048x1450.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Domenica 6 novembre 2022, in occasione del trentennale della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d appuntamento presso la sede della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d alle ore [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":1927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trentennale della Fondazione Museo &quot;Angela e Luisa De Luigi&quot; - Domenica 6 novembre 2022 - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trentennale della Fondazione Museo &quot;Angela e Luisa De Luigi&quot; - Domenica 6 novembre 2022 - Sommo\" \/>\n<meta property=\"og:description\" content=\"Domenica 6 novembre 2022, in occasione del trentennale della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d appuntamento presso la sede della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d alle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-01T17:42:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2318\" \/>\n\t<meta property=\"og:image:height\" content=\"1641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Trentennale della Fondazione Museo &#8220;Angela e Luisa De Luigi&#8221; &#8211; Domenica 6 novembre 2022\",\"datePublished\":\"2022-11-01T17:42:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/\"},\"wordCount\":90,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/IMG_20221101_182028090_HDR2-2.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/\",\"name\":\"Trentennale della Fondazione Museo \\\"Angela e Luisa De Luigi\\\" - Domenica 6 novembre 2022 - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/IMG_20221101_182028090_HDR2-2.jpg\",\"datePublished\":\"2022-11-01T17:42:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/IMG_20221101_182028090_HDR2-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/IMG_20221101_182028090_HDR2-2.jpg\",\"width\":2318,\"height\":1641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/01\\\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trentennale della Fondazione Museo &#8220;Angela e Luisa De Luigi&#8221; &#8211; Domenica 6 novembre 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trentennale della Fondazione Museo \"Angela e Luisa De Luigi\" - Domenica 6 novembre 2022 - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Trentennale della Fondazione Museo \"Angela e Luisa De Luigi\" - Domenica 6 novembre 2022 - Sommo","og_description":"Domenica 6 novembre 2022, in occasione del trentennale della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d appuntamento presso la sede della Fondazione Museo \u201cAngela e Luisa De Luigi\u201d alle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-01T17:42:19+00:00","og_image":[{"width":2318,"height":1641,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Trentennale della Fondazione Museo &#8220;Angela e Luisa De Luigi&#8221; &#8211; Domenica 6 novembre 2022","datePublished":"2022-11-01T17:42:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/"},"wordCount":90,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/","url":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/","name":"Trentennale della Fondazione Museo \"Angela e Luisa De Luigi\" - Domenica 6 novembre 2022 - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg","datePublished":"2022-11-01T17:42:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/IMG_20221101_182028090_HDR2-2.jpg","width":2318,"height":1641},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/01\/trentennale-della-fondazione-museo-angela-e-luisa-de-luigi-domenica-6-novembre-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Trentennale della Fondazione Museo &#8220;Angela e Luisa De Luigi&#8221; &#8211; Domenica 6 novembre 2022"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"17"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=1926"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1926\/revisions"}],"predecessor-version":[{"id":1928,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1926\/revisions\/1928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/1927"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=1926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=1926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=1926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}