{"id":1929,"date":"2022-11-04T09:01:49","date_gmt":"2022-11-04T08:01:49","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=1929"},"modified":"2022-11-04T09:01:49","modified_gmt":"2022-11-04T08:01:49","slug":"commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/","title":{"rendered":"Commemorazione dei Caduti di tutte le guerre, dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane"},"content":{"rendered":"<p>Per onorare e\u00a0 commemorare i sacrifici dei sommesi Soldati caduti a difesa della Patria e insieme a loro tutti i Soldati Italiani caduti di tutte le guerre e caduti in operazioni di Pace, per celebrare la giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane\u00a0 si terr\u00e0 una breve cerimonia nella Piazza del Municipio<\/p>\n<p style=\"text-align: center\"><strong>domenica 6 novembre 2022 alle ore 9,45 prima dell&#8217;inizio della S. Messa domenicale<\/strong><\/p>\n<p>con la benedizione delle corone deposte alle lapidi commemorative in fregio all&#8217;ingresso della Casa Comunale.<\/p>\n<p>Programma:<\/p>\n<p>ore 9,40 &#8211; ritrovo in Piazza del Comune<\/p>\n<p>ore 9,45 &#8211; benedizione delle corone e delle lapidi da parte del nostro parroco Arciprete don Juri Molinaro<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Per onorare e\u00a0 commemorare i sacrifici dei sommesi Soldati caduti a difesa della Patria e insieme a loro tutti i Soldati Italiani caduti di tutte le guerre e caduti in [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Commemorazione dei Caduti di tutte le guerre, dell&#039;Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commemorazione dei Caduti di tutte le guerre, dell&#039;Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo\" \/>\n<meta property=\"og:description\" content=\"Per onorare e\u00a0 commemorare i sacrifici dei sommesi Soldati caduti a difesa della Patria e insieme a loro tutti i Soldati Italiani caduti di tutte le guerre e caduti in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T08:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Commemorazione dei Caduti di tutte le guerre, dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane\",\"datePublished\":\"2022-11-04T08:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/\"},\"wordCount\":118,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/\",\"name\":\"Commemorazione dei Caduti di tutte le guerre, dell'Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png\",\"datePublished\":\"2022-11-04T08:01:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2022\\\/11\\\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png\",\"width\":450,\"height\":318},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2022\\\/11\\\/04\\\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commemorazione dei Caduti di tutte le guerre, dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commemorazione dei Caduti di tutte le guerre, dell'Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/","og_locale":"it_IT","og_type":"article","og_title":"Commemorazione dei Caduti di tutte le guerre, dell'Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo","og_description":"Per onorare e\u00a0 commemorare i sacrifici dei sommesi Soldati caduti a difesa della Patria e insieme a loro tutti i Soldati Italiani caduti di tutte le guerre e caduti in [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-04T08:01:49+00:00","og_image":[{"width":450,"height":318,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png","type":"image\/png"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Commemorazione dei Caduti di tutte le guerre, dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane","datePublished":"2022-11-04T08:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/"},"wordCount":118,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/","url":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/","name":"Commemorazione dei Caduti di tutte le guerre, dell'Unit\u00e0 Nazionale e delle Forze Armate Italiane - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png","datePublished":"2022-11-04T08:01:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2022\/11\/4-novembre-giorno-dell-unita-nazionale-e-giornata-delle-forze-armate.png","width":450,"height":318},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2022\/11\/04\/commemorazione-dei-caduti-di-tutte-le-guerre-dellunita-nazionale-e-delle-forze-armate-italiane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Commemorazione dei Caduti di tutte le guerre, dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate Italiane"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"predecessor-version":[{"id":1934,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/1929\/revisions\/1934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}