{"id":2414,"date":"2024-03-14T19:18:46","date_gmt":"2024-03-14T18:18:46","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=2414"},"modified":"2024-03-14T19:18:46","modified_gmt":"2024-03-14T18:18:46","slug":"il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/","title":{"rendered":"Il &#8220;Chorus Sanctii Laurentii&#8221; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &#8220;Domenica delle Palme&#8221; in concerto a Sommo"},"content":{"rendered":"<p>24 marzo 2024 &#8211;\u00a0 &#8220;Domenica delle Palme&#8221; speciale in chiesa parrocchiale a Sommo.<\/p>\n<p>In occasione della festivit\u00e0 religiosa che ci condurr\u00e0 alla celebrazione della Santa Pasqua, siamo tutti invitati al concerto del &#8220;Chorus Sanctii Laurentii&#8221; &#8211;\u00a0 in forma di\u00a0 prova antigenerale\u00a0 &#8211; diretto magistralmente dal Direttore Yuko BOVERIO, che ancora una volta ci regaler\u00e0 una rappresentazione di musica sacra di livello unico.<\/p>\n<p>Il concert\u00f2 si terr\u00e0 nel pomeriggio di domenica 24 marzo in chiesa parrocchiale a Sommo, con inizio alle ore 16,45.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2415\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627-709x1024.png\" alt=\"\" width=\"640\" height=\"924\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>24 marzo 2024 &#8211;\u00a0 &#8220;Domenica delle Palme&#8221; speciale in chiesa parrocchiale a Sommo. In occasione della festivit\u00e0 religiosa che ci condurr\u00e0 alla celebrazione della Santa Pasqua, siamo tutti invitati al [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":2415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il &quot;Chorus Sanctii Laurentii&quot; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &quot;Domenica delle Palme&quot; in concerto a Sommo - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il &quot;Chorus Sanctii Laurentii&quot; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &quot;Domenica delle Palme&quot; in concerto a Sommo - Sommo\" \/>\n<meta property=\"og:description\" content=\"24 marzo 2024 &#8211;\u00a0 &#8220;Domenica delle Palme&#8221; speciale in chiesa parrocchiale a Sommo. In occasione della festivit\u00e0 religiosa che ci condurr\u00e0 alla celebrazione della Santa Pasqua, siamo tutti invitati al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-14T18:18:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627.png\" \/>\n\t<meta property=\"og:image:width\" content=\"972\" \/>\n\t<meta property=\"og:image:height\" content=\"1403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Il &#8220;Chorus Sanctii Laurentii&#8221; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &#8220;Domenica delle Palme&#8221; in concerto a Sommo\",\"datePublished\":\"2024-03-14T18:18:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/\"},\"wordCount\":99,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2024\\\/03\\\/Screenshot_20240314-191242-627-e1712081910524.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/\",\"name\":\"Il \\\"Chorus Sanctii Laurentii\\\" diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della \\\"Domenica delle Palme\\\" in concerto a Sommo - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2024\\\/03\\\/Screenshot_20240314-191242-627-e1712081910524.png\",\"datePublished\":\"2024-03-14T18:18:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2024\\\/03\\\/Screenshot_20240314-191242-627-e1712081910524.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2024\\\/03\\\/Screenshot_20240314-191242-627-e1712081910524.png\",\"width\":816,\"height\":446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2024\\\/03\\\/14\\\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il &#8220;Chorus Sanctii Laurentii&#8221; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &#8220;Domenica delle Palme&#8221; in concerto a Sommo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il \"Chorus Sanctii Laurentii\" diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della \"Domenica delle Palme\" in concerto a Sommo - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/","og_locale":"it_IT","og_type":"article","og_title":"Il \"Chorus Sanctii Laurentii\" diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della \"Domenica delle Palme\" in concerto a Sommo - Sommo","og_description":"24 marzo 2024 &#8211;\u00a0 &#8220;Domenica delle Palme&#8221; speciale in chiesa parrocchiale a Sommo. In occasione della festivit\u00e0 religiosa che ci condurr\u00e0 alla celebrazione della Santa Pasqua, siamo tutti invitati al [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-03-14T18:18:46+00:00","og_image":[{"width":972,"height":1403,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627.png","type":"image\/png"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Il &#8220;Chorus Sanctii Laurentii&#8221; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &#8220;Domenica delle Palme&#8221; in concerto a Sommo","datePublished":"2024-03-14T18:18:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/"},"wordCount":99,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627-e1712081910524.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/","url":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/","name":"Il \"Chorus Sanctii Laurentii\" diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della \"Domenica delle Palme\" in concerto a Sommo - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627-e1712081910524.png","datePublished":"2024-03-14T18:18:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627-e1712081910524.png","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2024\/03\/Screenshot_20240314-191242-627-e1712081910524.png","width":816,"height":446},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2024\/03\/14\/il-chorus-sanctii-laurentii-diretto-da-yuko-boverio-nel-pomeriggio-della-festivita-religiosa-della-domenica-delle-palme-in-concerto-a-sommo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Il &#8220;Chorus Sanctii Laurentii&#8221; diretto da Yuko BOVERIO nel pomeriggio della festivit\u00e0 religiosa della &#8220;Domenica delle Palme&#8221; in concerto a Sommo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=2414"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2414\/revisions"}],"predecessor-version":[{"id":2416,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2414\/revisions\/2416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/2415"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=2414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=2414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=2414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}