{"id":2789,"date":"2025-04-18T17:26:52","date_gmt":"2025-04-18T15:26:52","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=2789"},"modified":"2025-04-18T17:27:22","modified_gmt":"2025-04-18T15:27:22","slug":"avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/","title":{"rendered":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO"},"content":{"rendered":"<p>Permane attualmente e sino a domani mattina 19 aprile una situazione di ALLERTA ROSSA per Rischio Idraulico &#8211; piena del fiume PO in tutta l&#8217;area identificata come IM12 che comprende anche le nostre aree golenali e\u00a0 il nostro territorio.<\/p>\n<p>Dal primo pomeriggio di oggi \u00e8 stato rilevato il primo dato in diminuzione del livello delle acque presso l&#8217;idrometro della Chiavica di Santa Clara. Si tratta di un deflusso molto lento e che, si prevede, necessiter\u00e0 di almeno altre 24 ore per raggiungere la normalit\u00e0, salvo il mutare delle situazioni meteo soprattutto riguardo alla direzione dei venti.<\/p>\n<p>Si conferma pertanto la situazione di ALLERTA ROSSA per Rischio Idraulico &#8211; piena del fiume PO.<\/p>\n<p>Si raccomanda alla popolazione di evitare di addentrarsi lungo strade e\/o sentieri vicinali del fiume Po e di evitare di percorrere strade e\/o sentieri all&#8217;interno delle aree golenali del fiume Po, di non avvicinarsi alle sponde del fiume Po soprattutto nelle ore serali e notturne sino a quando l&#8217;allerta non sar\u00e0 rientrata.<\/p>\n<p>Salvo situazioni eccezionali, il prossimo aggiornamento da parte della Protezione Civile Regionale \u00e8 previsto per la mattina di domani 19 aprile 2025.<\/p>\n<p>In allegato : Avviso di criticit\u00e0 Regione Lombardia del 18\/04\/2025 Allerta Rossa per Rischio Idraulico<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Inizio<\/h4>\n<p>17\/04\/2025 15:27<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>19\/04\/2025 15:27<\/p>\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2790\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/2025.24.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/2025.24.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>2025.24<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Permane attualmente e sino a domani mattina 19 aprile una situazione di ALLERTA ROSSA per Rischio Idraulico &#8211; piena del fiume PO in tutta l&#8217;area identificata come IM12 che comprende [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":2780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo\" \/>\n<meta property=\"og:description\" content=\"Permane attualmente e sino a domani mattina 19 aprile una situazione di ALLERTA ROSSA per Rischio Idraulico &#8211; piena del fiume PO in tutta l&#8217;area identificata come IM12 che comprende [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T15:26:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T15:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"366\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\\\/04\\\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO\",\"datePublished\":\"2025-04-18T15:26:52+00:00\",\"dateModified\":\"2025-04-18T15:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/\"},\"wordCount\":211,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/04\\\/Immagine-2025-04-17-192457.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/\",\"name\":\"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\\\/04\\\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/04\\\/Immagine-2025-04-17-192457.jpg\",\"datePublished\":\"2025-04-18T15:26:52+00:00\",\"dateModified\":\"2025-04-18T15:27:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/04\\\/Immagine-2025-04-17-192457.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/04\\\/Immagine-2025-04-17-192457.jpg\",\"width\":366,\"height\":220},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/04\\\/18\\\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\\\/04\\\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo","og_description":"Permane attualmente e sino a domani mattina 19 aprile una situazione di ALLERTA ROSSA per Rischio Idraulico &#8211; piena del fiume PO in tutta l&#8217;area identificata come IM12 che comprende [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-18T15:26:52+00:00","article_modified_time":"2025-04-18T15:27:22+00:00","og_image":[{"width":366,"height":220,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO","datePublished":"2025-04-18T15:26:52+00:00","dateModified":"2025-04-18T15:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/"},"wordCount":211,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/","url":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/","name":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg","datePublished":"2025-04-18T15:26:52+00:00","dateModified":"2025-04-18T15:27:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/04\/Immagine-2025-04-17-192457.jpg","width":366,"height":220},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2025\/04\/18\/avviso-di-criticita-r-l-del-18-04-2025-allerta-rossa-per-rischio-idraulico-piena-del-fiume-po\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento Avviso di criticit\u00e0 R. L. del 18\/04\/2025 Allerta Rossa per Rischio Idraulico \u2013 piena del fiume PO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"17\/04\/2025 15:27","cc4_urg_data_fine":"19\/04\/2025 15:27","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=2789"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2789\/revisions"}],"predecessor-version":[{"id":2791,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2789\/revisions\/2791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/2780"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=2789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=2789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=2789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}