{"id":2863,"date":"2025-07-11T16:50:36","date_gmt":"2025-07-11T14:50:36","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=2863"},"modified":"2025-07-11T16:50:36","modified_gmt":"2025-07-11T14:50:36","slug":"sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/","title":{"rendered":"SOMMO DA MARTEDI&#8217; 15 LUGLIO &#8211; inizio asfaltature di alcuni tratti delle strade comunali"},"content":{"rendered":"<p>Ritenendo di fare cosa utile, si informa che <strong>MARTEDI&#8217; 15\u00a0 LUGLIO<\/strong> avr\u00e0 inizio una prima parte di lavori di riasfaltatura in alcune zone del territorio comunale e per questo motivo verr\u00e0 modificata temporaneamente e per la sola durata dei lavori, la normale viabilit\u00e0 stradale in prossimit\u00e0 dei tratti interessati. I lavori dovrebbero svolgersi in circa una settimana lavorativa, salvo imprevisti o condizioni atmosferiche avverse.<\/p>\n<p>Gli interventi sono previsti sulle seguenti tratte di strada di propriet\u00e0 comunale :<\/p>\n<p>F.NE RONCHI &#8211; sistemazione tratto passante il sottopasso della linea ferroviaria MI-GE + 1 tratto zona C. na Luini<\/p>\n<p>STRADA PER TRAVEDO &#8211; sistemazione 2 tratte<\/p>\n<p>STRADA ARGINALE PER GERONE sistemazione di n. 2 tratte<\/p>\n<p><strong>CENTRO ABITATO DI SOMMO:\u00a0<\/strong><\/p>\n<p>VIA PASSERINI &#8211; marciapiedi<\/p>\n<p><strong>Si indicano di seguito gli orari\u00a0 della variazioni della normale viabilit\u00e0\u00a0 previste per i giorni di esecuzione dei lavori\u00a0<\/strong><strong>sulle tratte interessate<\/strong><strong>.<\/strong><\/p>\n<p>A seguire in ordine <strong>cronologico<\/strong> gli interventi previsti giornate di MARTEDI&#8217; 15 &#8211; MERCOLEDI&#8217; 16 e GIOVEDI&#8217; 17 LUGLIO :<\/p>\n<p><strong>1)inizio marted\u00ec 15 luglio dalle ore 7,30<\/strong>\u00a0&#8211;<strong> RONCHI tratto stradale sottopasso ferroviario linea MI-GE\u00a0 <\/strong>\u21d2\u00a0 Prevista la messa in sicurezza con riasfaltatura del tratto passante sotto il sottopasso. Durante l&#8217;esecuzione dei lavori sar\u00e0 apportata una modifica alle normali condizioni di viabilit\u00e0 con l&#8217;istituzione di senso unico alternato. <strong>Termine dei lavori previsto Gioved\u00ec 17 luglio 2025.<\/strong><\/p>\n<p><strong>\u00a02)Mercoled\u00ec 16 luglio dalle ore 7,30 &#8211; RONCHI tratto stradale strada bassa dei Ronchi in zona C.na Luini<\/strong><strong>. <\/strong>Prevista la risagomatura con riasfaltatura di un tratto della strada bassa dei Ronchi con ripristino della cunetta per scaricare le acque di pioggia.\u00a0 Per il predetto intervento, considerata la ridotta larghezza della carreggiata, durante l&#8217;esecuzione dei lavori, si consiglia il transito dalla strada arginale dei Ronchi anche a tutti i residenti della zona comprese le macchine agricole per il tempo necessario all&#8217;esecuzione dell&#8217;intervento. <strong>Termine dei lavori previsto Gioved\u00ec 17 luglio 2025.<\/strong><\/p>\n<p><strong>3) Gioved\u00ec 17 luglio dalle ore 7,30 &#8211; strada per Travedo loc. C.na Fornace. <\/strong>Prevista la messa in sicurezza con risagomatura e riasfaltatura di due tratte in loc. C.na Fornace nei pressi dei civici n. 1 e n. 3. Durante l&#8217;esecuzione dei predetti interventi, sar\u00e0 apportata una modifica alle normali condizioni di viabilit\u00e0 con l&#8217;istituzione di senso unico alternato per il tempo necessario all&#8217;esecuzione dei lavori. <strong>Termine dei lavori previsto Venerd\u00ec 18 luglio 2025.<\/strong><\/p>\n<p><strong>4)<\/strong><strong> Luned\u00ec 21 luglio dalle ore 7,30- strada arginale per Gerone &#8211; rampa strada per C.NA PIGNACCA a seguire rampa strada per C.NA GRAVA.<\/strong> Prevista la messa in sicurezza con risagomatura e riasfaltatura della rampa strada per cascina Pignacca e rampa strada per casacina GRAVA. Durante l&#8217;esecuzione dei lavori sar\u00e0 apportata una modifica alle normali condizioni di viabilit\u00e0 con l&#8217;istituzione di senso unico alternato per il solo tempo necessario all&#8217;esecuzione dei lavori. <strong>Termine dei lavori previsto Marted\u00ec 22 luglio 2025.<\/strong><\/p>\n<p><strong>5) Luned\u00ec 21 luglio dalle ore &#8211; Via Passerini &#8211; <\/strong>ripristino alcuni tratti di marciapiede e manutenzione aiuola centrale. <strong>Considerata la tipologia dell&#8217;intervento, sar\u00e0 consentita la circolazione a tutti i residenti in via Passerini per l&#8217;uscita e il rientro presso la propria abitazione. Durante l&#8217;esecuzioni dei lavori \u00e8 prevista l&#8217;istituzione del DIVIETO DI SOSTA in tutta la via anche per i residenti in via Passerini. Termine dei lavori previsto Marted\u00ec 22 luglio 2025.<\/strong><\/p>\n<p>I lavori di asfaltatura e riasfaltatura sulle carreggiate di piccole dimensioni come quelle interessate, condizionano gli operanti all&#8217;adozione di particolari soluzioni di modifica della viabilit\u00e0 poco piacevoli che tuttavia, per poter lavorare in sicurezza, si rendono necessarie. Ci scusiamo con tutti i residenti per i disagi arrecati, che cercheremo di rendere il meno gravosi possibile.<\/p>\n<p><strong>Da marted\u00ec 12 luglio seguiranno aggiornamenti giornalieri<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ritenendo di fare cosa utile, si informa che MARTEDI&#8217; 15\u00a0 LUGLIO avr\u00e0 inizio una prima parte di lavori di riasfaltatura in alcune zone del territorio comunale e per questo motivo [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":1441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOMMO DA MARTEDI&#039; 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOMMO DA MARTEDI&#039; 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo\" \/>\n<meta property=\"og:description\" content=\"Ritenendo di fare cosa utile, si informa che MARTEDI&#8217; 15\u00a0 LUGLIO avr\u00e0 inizio una prima parte di lavori di riasfaltatura in alcune zone del territorio comunale e per questo motivo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-11T14:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"521\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"SOMMO DA MARTEDI&#8217; 15 LUGLIO &#8211; inizio asfaltature di alcuni tratti delle strade comunali\",\"datePublished\":\"2025-07-11T14:50:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/\"},\"wordCount\":580,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2021\\\/09\\\/l_71abeddb8c-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/\",\"name\":\"SOMMO DA MARTEDI' 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2021\\\/09\\\/l_71abeddb8c-1.jpg\",\"datePublished\":\"2025-07-11T14:50:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2021\\\/09\\\/l_71abeddb8c-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2021\\\/09\\\/l_71abeddb8c-1.jpg\",\"width\":480,\"height\":521},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/07\\\/11\\\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOMMO DA MARTEDI&#8217; 15 LUGLIO &#8211; inizio asfaltature di alcuni tratti delle strade comunali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOMMO DA MARTEDI' 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/","og_locale":"it_IT","og_type":"article","og_title":"SOMMO DA MARTEDI' 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo","og_description":"Ritenendo di fare cosa utile, si informa che MARTEDI&#8217; 15\u00a0 LUGLIO avr\u00e0 inizio una prima parte di lavori di riasfaltatura in alcune zone del territorio comunale e per questo motivo [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-11T14:50:36+00:00","og_image":[{"width":480,"height":521,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"SOMMO DA MARTEDI&#8217; 15 LUGLIO &#8211; inizio asfaltature di alcuni tratti delle strade comunali","datePublished":"2025-07-11T14:50:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/"},"wordCount":580,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/","url":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/","name":"SOMMO DA MARTEDI' 15 LUGLIO - inizio asfaltature di alcuni tratti delle strade comunali - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg","datePublished":"2025-07-11T14:50:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2021\/09\/l_71abeddb8c-1.jpg","width":480,"height":521},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2025\/07\/11\/sommo-da-martedi-15-luglio-inizio-asfaltature-di-alcuni-tratti-delle-strade-comunali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"SOMMO DA MARTEDI&#8217; 15 LUGLIO &#8211; inizio asfaltature di alcuni tratti delle strade comunali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=2863"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2863\/revisions"}],"predecessor-version":[{"id":2864,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2863\/revisions\/2864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/1441"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=2863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=2863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=2863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}