{"id":2982,"date":"2025-12-15T16:28:53","date_gmt":"2025-12-15T15:28:53","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=2982"},"modified":"2025-12-15T16:28:53","modified_gmt":"2025-12-15T15:28:53","slug":"da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/","title":{"rendered":"Da MERCOLEDI&#8217; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &#8220;SACCHETTI CONFORMI&#8221;"},"content":{"rendered":"<p>Da mercoled\u00ec 17 dicembre per tutti gli utenti residenti e iscritti alla\u00a0Tassa rifiuti (TARI) di Sommo sar\u00e0 possibile ritirare presso gli uffici comunali il NUOVO CALENDARIO RIFIUTI ANNO 2026 e la nuova fornitura gratuita dei SACCHETTI AZZURRI CONFORMI.\u00a0 Il calendario rifiuti sar\u00e0 pubblicato anche sul sito internet comunale.<\/p>\n<p>Dal giorno 17, dalle ore 9,30,\u00a0 sar\u00e0 possibile ritirare il proprio quantitativo di sacchetti conformi e il nuovo calendario rifiuti recandosi in comune, tutti i giorni, negli orari di apertura degli Uffici come di seguito indicato:<\/p>\n<p>Luned\u00ec\u00a0 8.30 &#8211; 13.00<\/p>\n<p>Marted\u00ec 14.30 &#8211; 17.50<\/p>\n<p>Mercoled\u00ec 9.30 &#8211; 13.00<\/p>\n<p>Gioved\u00ec 8.30 &#8211; 13.00<\/p>\n<p>Venerd\u00ec 9.30 &#8211; 12 e 14.30 &#8211; 17.50<\/p>\n<p>Per coloro che non saranno nella possibilit\u00e0 di effettuare il ritiro personalmente, come per gli anni scorsi \u00e8 possibile delegare un\u2019altra persona (un amico o un parente, o un vicino di casa) che compiler\u00e0 il modulo di conferimento della delega allegato al presente avviso. Il modulo compilato e firmato da parte della persona da voi incaricata del ritiro dei Vostri sacchetti, dovr\u00e0 essere consegnato allo sportello comunale al momento del ritiro della fornitura.<\/p>\n<p>Rimangono in vigore le disposizioni riguardo al riconoscimento di sacchetti aggiuntivi per le famiglie con presenza di bambini sino ai 3 anni di et\u00e0 e per le famiglie con presenza di anziani utilizzatori di ausili.<\/p>\n<p>Per tutti coloro che stanno ospitando presso la propria abitazione una o pi\u00f9 persone non residenti, per poter avere la fornitura dei sacchetti anche per le persone ospitate, \u00e8 possibile regolarizzare la presenza dell\u2019ospite chiedendo di inserirlo nel proprio nucleo familiare anchesenza che l\u2019ospite trasferisca la propria residenza a Sommo.<\/p>\n<p>Come anche lo scorso anno il numero dei sacchetti sar\u00e0 consegnato ai residenti nel Comune di Sommo in base al numero dei componenti per nucleo familiare che risultano iscritti nella denuncia TARI.<\/p>\n<p><strong>Perch\u00e9 abbiamo puntato sul progetto dell\u2019uso del \u00a0\u201csacchetto conforme\u201d<\/strong><\/p>\n<p>Se prendiamo come anno iniziale di riferimento il 2013, la percentuale di raccolta differenziata a Sommo era quasi insignificante (36,79%). Quel sistema di smaltimento riscontrava all\u2019interno dei sacchi del rifiuto secco ritirato settimanalmente una grande quantit\u00e0 di materiale riutilizzabile e da valorizzare. E\u2019 stato pertanto importante intraprendere un percorso per sensibilizzare tutti a dividere meglio i rifiuti per categorie, partendo dalle categorie principali quali \u00a0carta \u2013 plastica \u2013 vetro.<\/p>\n<p>L\u2019adozione \u201csacchetto conforme\u201d \u00e8 un sistema di misurazione e gestione del rifiuto secco pro-capite basato sulla distribuzione agli utenti di un numero di sacchetti in proporzione al numero dei componenti del nucleo famigliare, in base a parametri differenti per utenze domestiche.<\/p>\n<p>Statisticamente il quantitativo annuale di rifiuti prodotti da ciascun residente \u00e8 aumentato e di molto rispetto al 2013, basta osservare il grafico che riporta i consumi dal 2015 al 2024 per vedere come siamo passati da 290,53 kg di rifiuto urbano (rifiuto differenziato+rifiuto non differenziato) pro-capite nel 2015 a un quantitativo molto superiore nel 2024 pari a kg. 398,07.<\/p>\n<p>Anche per questo \u00e8 stato molto importante intraprendere un cammino di consapevolezza da parte dell\u2019utente su come differenziare, seguendo alcune semplici regole che hanno consentito di consolidare anno dopo anno l\u2019aumento delle percentuali dei rifiuti riutilizzabili e nuovamente valorizzabili rispetto a tutto il resto.<\/p>\n<p>Si possono verificare i dati degli ultimi anni dal grafico (fonte ISPRA) allegato.<\/p>\n<p><strong>Lo scorso anno, 2024<\/strong>, la percentuale media finale di raccolta differenziata raggiunta nei dodici mesi \u00e8 risultata del <strong>76,27%,<\/strong> con andamento praticamente costante rispetto al 2023. Abbiamo consolidato infatti un leggerissimo incremento in percentuale pari allo 0,09% annuo in pi\u00f9. Con questa percentuale siamo rientrati nel gruppo di comuni lombardi\u00a0ai quali Regione Lombardia riconosce un contributo economico per l\u2019impegno e la diligenza profusi durante l\u2019anno nella gestione dei rifiuti urbani che ha una ricaduta diretta sul ricircolo delle materie prime riutilizzabili.<\/p>\n<p><strong>Quest\u2019anno, 2025,<\/strong> le nostre percentuali mensili di raccolta differenziata nei primi 9 mesi stanno rispettando la media dello scorso anno, riscontrando anzi un discreto miglioramento. La percentuale sino <strong>al mese di settembre 2025 era infatti del 78,39 %<\/strong> (dati ASM). Speriamo che venga confermata anche al 31 dicembre, sarebbe un egregio risultato.<\/p>\n<p>Possiamo certamente migliorare ancora, oltre che mantenere ovviamente questa media, differenziando sempre di pi\u00f9 e sempre meglio, eliminando ad esempio, la quantit\u00e0 di\u00a0carta asciugatutto e di lattine che vediamo spesso all\u2019interno dei sacchi conformi. Differenziare meglio, vorrebbe dire fare un ulteriore passo avanti, questo \u00e8 l\u2019appello che facciamo ancora una volta a tutti.<\/p>\n<p>A beneficio di tutti riepiloghiamo le istruzioni per una corretta raccolta differenziata:<\/p>\n<p><strong>la carta<\/strong>\u00a0 (tranne gli scontrini dei negozi perch\u00e9 \u00e8 carta termica) anche quella non pulita, il cartone (anche i contenitori della pizza) e gli imballaggi in carta devono essere smaltiti il marted\u00ec quando \u00e8 prevista la raccolta della carta. La carta asciugatutto sporca di cibo o i fazzoletti di carta vanno smaltiti nell&#8217;umido, in questo modo \u00e8 favorito inoltre l&#8217;assorbimento di liquidi ed aiuta a mantenere integro il sacchetto dell&#8217;umido. Solo la carta assorbente sporca di prodotti per le pulizie deve essere conferita nel secco indifferenziato (raccolta del mercoledi&#8217;)<\/p>\n<p><strong>la plastica<\/strong>, compresi i contenitori dello yogurt, gli imballaggi in plastica, i contenitori in plastica dei cibi, anche se non puliti, devono essere smaltiti il marted\u00ec quando \u00e8 prevista la raccolta della plastica;<\/p>\n<p><strong>le lattine<\/strong> e l\u2019alluminio in genere, comprese le lattine dei cibi per cani e\/o gatti, devono essere smaltiti il marted\u00ec insieme alla plastica;<\/p>\n<p><strong>il vetro<\/strong>, tutti i contenitori di vetro privi di coperchio in alluminio, devono essere smaltiti all\u2019interno delle campane del vetro distribuite sul territorio.<\/p>\n<p>Seguendo queste poche regole, rimanendo sempre attivi sulla differenziazione dei rifiuti, potremo fare un ulteriore passo avanti.<\/p>\n<p>Infine, rinnoviamo un appello rivolto a tutti, per favore:<\/p>\n<ul>\n<li>non gettate i sacchetti dei rifiuti domestici all\u2019interno dei cestini stradali, quelli non sono cassonetti. In quel modo riempite il cestino stradale e chi arriva dopo trova il cestino pieno;<\/li>\n<li>esponete il rifiuto umido di casa vostra all\u2019interno di secchi o piccoli contenitori, evitate di esporre su strada o sul marciapiede i sacchetti dell\u2019umido privi di contenitori. Il sacchetto privo di contenitore \u00e8 preda degli animali che lo rompono spargendo il contenuto sulla strada o sul marciapiede;<\/li>\n<li>per la raccolta del mercoled\u00ec dell\u2019indifferenziata utilizzate SOLO i sacchetti conformi distribuiti dal comune. I sacchetti \u201csimili\u201d saranno contrassegnati e non saranno ritirati da ASM;<\/li>\n<li>quando comprate un nuovo elettrodomestico, ad esempio una nuova lavatrice o frigorifero o un mobile (un divano, un armadio, etc) Vi ricordiamo che presso il negozio o il supermercato dove lo comprate sono obbligati a ritirare gratuitamente la vecchia lavatrice\/frigorifero\/divano;<\/li>\n<li>Lo stesso avviene se comprate elettrodomestici o arredi sui siti online.\u00a0 Approfittare del servizio di ritiro gratuito comporta 2 vantaggi; 1- non dovete tenere in casa il vecchio divano\/frigorifero ecc. sino al giorno previsto per la raccolta degli ingombranti\/rae , 2- risparmiate un costo di smaltimento al comune che inevitabilmente poi ricade sul costo della tassa rifiuti. Pertanto conviene sempre usare il servizio di ritiro gratuito dei vecchi mobili ed elettrodomestici dei venditori, \u00e8 previsto dalla legge, \u00e8 gratuito e, non essendo fatto dal servizio comunale di ASM ritiro ingombranti, non rappresenta un costo a carico del comune che andrebbe a ricadere sul calcolo annuale della tassa rifiuti.<\/li>\n<\/ul>\n<p>Per chiarimenti o informazioni, il personale \u00e8 a disposizione negli orari di apertura degli uffici comunali.<\/p>\n<p><strong>IN ALLEGATO IL CALENDARIO RIFIUTI 2026<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2983\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-160729.jpg\" alt=\"\" width=\"842\" height=\"575\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-160729.jpg 842w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-160729-300x205.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-160729-768x524.jpg 768w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2984 aligncenter\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite-1024x484.jpg\" alt=\"\" width=\"640\" height=\"303\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite-1024x484.jpg 1024w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite-300x142.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite-768x363.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite-1536x726.jpg 1536w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/andamento-produzione-rifiuti-pro-capite.jpg 1541w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2985\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Sommo_2026.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Sommo_2026.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Sommo_2026<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2986\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/autocertificazione_sacchetti.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/autocertificazione_sacchetti.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>autocertificazione_sacchetti<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Da mercoled\u00ec 17 dicembre per tutti gli utenti residenti e iscritti alla\u00a0Tassa rifiuti (TARI) di Sommo sar\u00e0 possibile ritirare presso gli uffici comunali il NUOVO CALENDARIO RIFIUTI ANNO 2026 e [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":2987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da MERCOLEDI&#039; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &quot;SACCHETTI CONFORMI&quot; - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da MERCOLEDI&#039; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &quot;SACCHETTI CONFORMI&quot; - Sommo\" \/>\n<meta property=\"og:description\" content=\"Da mercoled\u00ec 17 dicembre per tutti gli utenti residenti e iscritti alla\u00a0Tassa rifiuti (TARI) di Sommo sar\u00e0 possibile ritirare presso gli uffici comunali il NUOVO CALENDARIO RIFIUTI ANNO 2026 e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T15:28:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"915\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Da MERCOLEDI&#8217; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &#8220;SACCHETTI CONFORMI&#8221;\",\"datePublished\":\"2025-12-15T15:28:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/\"},\"wordCount\":1198,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/12\\\/Immagine-2025-12-15-161658.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/\",\"name\":\"Da MERCOLEDI' 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei \\\"SACCHETTI CONFORMI\\\" - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/12\\\/Immagine-2025-12-15-161658.jpg\",\"datePublished\":\"2025-12-15T15:28:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/12\\\/Immagine-2025-12-15-161658.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2025\\\/12\\\/Immagine-2025-12-15-161658.jpg\",\"width\":585,\"height\":915},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2025\\\/12\\\/15\\\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da MERCOLEDI&#8217; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &#8220;SACCHETTI CONFORMI&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da MERCOLEDI' 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei \"SACCHETTI CONFORMI\" - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/","og_locale":"it_IT","og_type":"article","og_title":"Da MERCOLEDI' 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei \"SACCHETTI CONFORMI\" - Sommo","og_description":"Da mercoled\u00ec 17 dicembre per tutti gli utenti residenti e iscritti alla\u00a0Tassa rifiuti (TARI) di Sommo sar\u00e0 possibile ritirare presso gli uffici comunali il NUOVO CALENDARIO RIFIUTI ANNO 2026 e [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-12-15T15:28:53+00:00","og_image":[{"width":585,"height":915,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Da MERCOLEDI&#8217; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &#8220;SACCHETTI CONFORMI&#8221;","datePublished":"2025-12-15T15:28:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/"},"wordCount":1198,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/","url":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/","name":"Da MERCOLEDI' 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei \"SACCHETTI CONFORMI\" - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg","datePublished":"2025-12-15T15:28:53+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2025\/12\/Immagine-2025-12-15-161658.jpg","width":585,"height":915},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2025\/12\/15\/da-mercoledi-17-dicembre-in-distribuzione-il-calendario-rifiuti-2026-e-la-nuova-fornitura-gratuita-dei-sacchetti-conformi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Da MERCOLEDI&#8217; 17 DICEMBRE in distribuzione il CALENDARIO RIFIUTI 2026 e la nuova fornitura gratuita dei &#8220;SACCHETTI CONFORMI&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=2982"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2982\/revisions"}],"predecessor-version":[{"id":2988,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/2982\/revisions\/2988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/2987"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=2982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}