{"id":444,"date":"2018-09-05T14:25:00","date_gmt":"2018-09-05T12:25:00","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=444"},"modified":"2018-09-06T16:32:41","modified_gmt":"2018-09-06T14:32:41","slug":"444","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/","title":{"rendered":"Piazza F. lli Balzi &#8211; campana vetro e cassone abiti usati"},"content":{"rendered":"<div style=\"color: #1c2024;text-indent: 0px;letter-spacing: normal;font-family: 'Titillium Web', HelveticaNeue-Light, 'Helvetica Neue Light', 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;font-size: medium;font-style: normal;font-weight: 400;background-color: #ffffff\">Negli ultimi tempi gli operatori comunali sono intervenuti diverse volte in piazza F.LLI BALZI per togliere sacchi e borse contenenti vestiario di vario genere abbandonati ai piedi del cassone giallo di raccolta vestiti (che non dipende dal Comune ma che \u00e8 di propriet\u00e0 della Organizzazione Humana onlus). \u00a0La presenza di quei sacchi e di quelle borse abbandonate ha richiamato l\u2019abbandono di rifiuti di vario genere (giocattoli vecchi, attrezzi ginnici, indumenti da buttare ecc.). Il comune non ha un\u2019area dove conservare in modo adeguato i sacchi di indumenti che, per ovvi motivi se il cassone \u00e8 pieno, non entrano nel cassone giallo.<br \/>\nPer evitare che la zona circostante il cassone si trasformi in una probabile discarica di rifiuti, abbiamo messo degli avvisi, raccomandando di non abbandonare sacchi e borse.<\/div>\n<div style=\"color: #1c2024;text-indent: 0px;letter-spacing: normal;font-family: 'Titillium Web', HelveticaNeue-Light, 'Helvetica Neue Light', 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;font-size: medium;font-style: normal;font-weight: 400;background-color: #ffffff\">ESORTIAMO TUTTI A NON LASCIARE SACCHI O BORSE SE IL CASSONE E\u2019 PIENO. LA PRESENZA DI SACCHI CHE POSSONO ESSERE SCAMBIATI COME RIFIUTI, SONO UN POTENZIALE RICHIAMO PER L\u2019ABBANDONO DI ALTRI RIFIUTI.<\/div>\n<div style=\"color: #1c2024;text-indent: 0px;letter-spacing: normal;font-family: 'Titillium Web', HelveticaNeue-Light, 'Helvetica Neue Light', 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;font-size: medium;font-style: normal;font-weight: 400;background-color: #ffffff\">Sempre in piazza F.lli Balzi, accanto al cassone giallo dei vestiti, si trova una campana per la raccolta del vetro. Ancora pochi giorni fa, nonostante il fatto che la campana era stata appena svuotata e quindi i vetri e le lattine potevano essere tranquillamente sversati all\u2019interno della campana, qualcuno ha per l\u2019ennesima volta abbandonato scatole e borse contenenti bottiglie e lattine ai piedi della campana.<br \/>\nCome \u00e8 stato scritto anche sull\u2019avviso messo sul posto, per chi non lo sapesse, piazza F.LLI BALZI e&#8217; adiacente la scuola comunale, di fatto \u00e8 il parcheggio della scuola, dove ogni giorno c&#8217;\u00e8 costante presenza di bambini e la presenza al suolo di vetro o latte taglienti, sono un potenziale pericolo per tutti gli utenti in genere ma soprattutto per i bambini.<br \/>\nBasta davvero poco, un po\u2019 di senso civico, le campane per il vetro sono messe per contenere il vetro che ogni cittadino deve smaltire inserendole all\u2019interno delle campane stesse e non lasciarlo fuori ai piedi del contenitore.<br \/>\nSe la campana di piazza F.lli Balzi \u00e8 piena, RICORDIAMO che a poca distanza nelle vie Laudi, Arrigo e XXV Aprile sono a disposizione altre 6 campane dove poter depositare il vetro o l&#8217;alluminio.<br \/>\nCome \u00e8 noto, sul territorio di Sommo, quando ha avuto inizio il servizio di raccolta dei rifiuti, non sono state previste zone riservate dove poter posizionare cassonetti e campane al di fuori della pubblica via. E&#8217; questa una carenza che stiamo cercando di colmare, andando ad individuare porzioni di territorio dove collocare i cassonetti e le campane al di fuori della sede stradale.<br \/>\nAncora di pi\u00f9 quindi e&#8217; importante osservare semplici norme igieniche e di sicurezza, senso civico e rispetto vuol dire non abbandonare i rifiuti all&#8217;esterno dei contenitori, sull\u2019asfalto delle piazze o sull\u2019asfalto delle strade.<br \/>\nQuesta Amministrazione, in caso di ulteriori abbandoni di vetro o alluminio\u00a0\u00a0 all&#8217;esterno della campana, si vedr\u00e0 costretta a spostare la campana di piazza F.lli Balzi in via XXV aprile per motivi di sicurezza e di igiene.<\/div>\n<div style=\"color: #1c2024;text-indent: 0px;letter-spacing: normal;font-family: 'Titillium Web', HelveticaNeue-Light, 'Helvetica Neue Light', 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;font-size: medium;font-style: normal;font-weight: 400;background-color: #ffffff\"><strong>Tanto si \u00e8 fatto e tanto si sta facendo per mantenere ordine e pulizia, la Vostra collaborazione \u00e8 importante!<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Negli ultimi tempi gli operatori comunali sono intervenuti diverse volte in piazza F.LLI BALZI per togliere sacchi e borse contenenti vestiario di vario genere abbandonati ai piedi del cassone giallo [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":44,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo\" \/>\n<meta property=\"og:description\" content=\"Negli ultimi tempi gli operatori comunali sono intervenuti diverse volte in piazza F.LLI BALZI per togliere sacchi e borse contenenti vestiario di vario genere abbandonati ai piedi del cassone giallo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-05T12:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-06T14:32:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"160\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Piazza F. lli Balzi &#8211; campana vetro e cassone abiti usati\",\"datePublished\":\"2018-09-05T12:25:00+00:00\",\"dateModified\":\"2018-09-06T14:32:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/\"},\"wordCount\":525,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/images-differ.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/\",\"name\":\"Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/images-differ.jpeg\",\"datePublished\":\"2018-09-05T12:25:00+00:00\",\"dateModified\":\"2018-09-06T14:32:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/images-differ.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/images-differ.jpeg\",\"width\":160,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/09\\\/05\\\/444\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piazza F. lli Balzi &#8211; campana vetro e cassone abiti usati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/","og_locale":"it_IT","og_type":"article","og_title":"Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo","og_description":"Negli ultimi tempi gli operatori comunali sono intervenuti diverse volte in piazza F.LLI BALZI per togliere sacchi e borse contenenti vestiario di vario genere abbandonati ai piedi del cassone giallo [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-09-05T12:25:00+00:00","article_modified_time":"2018-09-06T14:32:41+00:00","og_image":[{"width":160,"height":160,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Piazza F. lli Balzi &#8211; campana vetro e cassone abiti usati","datePublished":"2018-09-05T12:25:00+00:00","dateModified":"2018-09-06T14:32:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/"},"wordCount":525,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/","url":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/","name":"Piazza F. lli Balzi - campana vetro e cassone abiti usati - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg","datePublished":"2018-09-05T12:25:00+00:00","dateModified":"2018-09-06T14:32:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/images-differ.jpeg","width":160,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2018\/09\/05\/444\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Piazza F. lli Balzi &#8211; campana vetro e cassone abiti usati"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"predecessor-version":[{"id":449,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/444\/revisions\/449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/44"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}