{"id":460,"date":"2018-10-16T21:45:15","date_gmt":"2018-10-16T19:45:15","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=460"},"modified":"2018-10-16T21:45:49","modified_gmt":"2018-10-16T19:45:49","slug":"ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/","title":{"rendered":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo"},"content":{"rendered":"<p>Domenica 14 ottobre alcuni volontari del Gruppo Comunale di Protezione Civile di Sommo hanno partecipato ad una prova di soccorso e test delle procedure di evacuazione di alcune zone a rischio idrogeologico alluvionale, organizzato nel vicino comune di Carbonare Ticino.<\/p>\n<p>Alla prova hanno partecipato i Gruppi Comunali dell\u2019Ufficio Associato per la Gestione del Servizio di Protezione Civile.<\/p>\n<p>Con l\u2019occasione sono stati testati gli apparati radio in dotazione ai Gruppi Comunali, collegati tramite il nuovo ponte radio.<\/p>\n<p>Il Gruppo Comunale di Sommo era rappresentato dai volontari;<\/p>\n<p>Diego SACCHI \u2013 Assessore con delega alla Protezione Civile;<\/p>\n<p>Mario GABETTA \u2013 Responsabile coordinatore Gruppo Comunale di P.C. di Sommo;<\/p>\n<p>Fabrizio MECCA \u2013 Volontario.<\/p>\n<p>&nbsp;<\/p>\n<p>In precedenza, sabato 22 e domenica 23 settembre scorso, il nostro Gruppo Comunale di Protezione Civile con la partecipazione di alcuni volontari, si \u00e8 registrato tra i partecipanti all\u2019 \u201cEsercitazione Provinciale di Protezione Civile \u2013 ESERVOL 2018\u201d svoltasi a Certosa di Pavia.<\/p>\n<p>Durante l\u2019esercitazione, che prevedeva anche l\u2019allestimento ed il montaggio di un campo base, sono stati affrontati diversi scenari di primo intervento diurni e notturni\u00a0 nei quali i volontari hanno avuto modo di mettere in atto tecniche di intervento gi\u00e0 note, perfezionandole<\/p>\n<p>Il Gruppo Comunale di Sommo era rappresentato dai volontari;<\/p>\n<p>Diego SACCHI \u2013 Assessore con delega alla Protezione Civile;<\/p>\n<p>Mario GABETTA \u2013 Responsabile coordinatore del Gruppo Comunale di P.C. di Sommo;<\/p>\n<p>Marta SPAIRANI \u2013 Volontaria.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Sindaco e l\u2019Amministrazione Comunale di Sommo unitamente all\u2019Assessore Sacchi, ringraziano il Responsabile ed i volontari che hanno dato la loro disponibilit\u00e0 a partecipare alle esercitazioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Di seguito pubblichiamo alcune fotografie relative all\u2019esercitazione del 22 e 23 settembre che si \u00e8 conclusa con la celebrazione della S. Messa nel monastero della Certosa di Pavia ed a seguire, con la premiazione dei gruppi comunali partecipanti.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-461\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012-300x225.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012-768x576.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012-1024x768.jpg 1024w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012-680x510.jpg 680w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0012.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-463\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016-300x225.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016-768x576.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016-1024x768.jpg 1024w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016-680x510.jpg 680w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0016.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-464\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002-300x225.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002-768x576.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002-1024x768.jpg 1024w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002-680x510.jpg 680w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180922-WA0002.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-465\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024-300x284.jpg\" alt=\"\" width=\"300\" height=\"284\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024-300x284.jpg 300w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024-768x728.jpg 768w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024-680x645.jpg 680w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024-800x758.jpg 800w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0024.jpg 844w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-462\" src=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0003-287x300.jpg\" alt=\"\" width=\"287\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0003-287x300.jpg 287w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0003-680x712.jpg 680w, https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2018\/10\/IMG-20180923-WA0003.jpg 764w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 14 ottobre alcuni volontari del Gruppo Comunale di Protezione Civile di Sommo hanno partecipato ad una prova di soccorso e test delle procedure di evacuazione di alcune zone a [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":29,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo\" \/>\n<meta property=\"og:description\" content=\"Domenica 14 ottobre alcuni volontari del Gruppo Comunale di Protezione Civile di Sommo hanno partecipato ad una prova di soccorso e test delle procedure di evacuazione di alcune zone a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-16T19:45:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-16T19:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"642\" \/>\n\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo\",\"datePublished\":\"2018-10-16T19:45:15+00:00\",\"dateModified\":\"2018-10-16T19:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/\"},\"wordCount\":298,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/Diapositiva1.gif\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/\",\"name\":\"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/Diapositiva1.gif\",\"datePublished\":\"2018-10-16T19:45:15+00:00\",\"dateModified\":\"2018-10-16T19:45:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/Diapositiva1.gif\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2016\\\/10\\\/Diapositiva1.gif\",\"width\":642,\"height\":642},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2018\\\/10\\\/16\\\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/","og_locale":"it_IT","og_type":"article","og_title":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo","og_description":"Domenica 14 ottobre alcuni volontari del Gruppo Comunale di Protezione Civile di Sommo hanno partecipato ad una prova di soccorso e test delle procedure di evacuazione di alcune zone a [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-10-16T19:45:15+00:00","article_modified_time":"2018-10-16T19:45:49+00:00","og_image":[{"width":642,"height":642,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif","type":"image\/gif"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo","datePublished":"2018-10-16T19:45:15+00:00","dateModified":"2018-10-16T19:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/"},"wordCount":298,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/","url":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/","name":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif","datePublished":"2018-10-16T19:45:15+00:00","dateModified":"2018-10-16T19:45:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2016\/10\/Diapositiva1.gif","width":642,"height":642},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2018\/10\/16\/ultime-attivita-del-gruppo-comunale-di-protezione-civile-di-sommo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"Ultime attivit\u00e0 del Gruppo Comunale di Protezione Civile di Sommo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":466,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/460\/revisions\/466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/29"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}