{"id":541,"date":"2019-01-29T13:55:55","date_gmt":"2019-01-29T12:55:55","guid":{"rendered":"https:\/\/comunicacity.net\/sommo\/?p=541"},"modified":"2019-01-29T13:55:55","modified_gmt":"2019-01-29T12:55:55","slug":"attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/","title":{"rendered":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#8217; 30 GENNAIO"},"content":{"rendered":"<p>Previsione Meteo &#8211; probabile nevicata prevista per domani 30 gennaio.<\/p>\n<p>Come gi\u00e0 anticipato da alcuni giorni dagli organi di informazione, nelle prossime ore anche il nostro territorio sar\u00e0 interessato da una perturbazione che porter\u00e0 neve anche in pianura.<\/p>\n<p>Considerate le attuali condizioni metereologiche con temperature rigide soprattutto la notte e nelle prime ore del mattino, non si escludono sporadiche nevicate anche a quote basse e di pianura che potrebbero interessare anche il nostro territorio comunale, con conseguente formazione di tratti ghiacciati sul fondo stradale,\u00a0<span style=\"font-size: 1rem\">nonostante l&#8217;intervento dei mezzi spargisale,<\/span><span style=\"font-size: 1rem\">\u00a0<\/span><span style=\"font-size: 1rem\">.<\/span><\/p>\n<p>Come anche in altre occasioni, si consiglia di transitare con la massima prudenza, in particolar modo nelle ore serali, notturne e di prima mattina, soprattutto nei seguenti tratti stradali:<\/p>\n<p>ARGINE RONCHI e relative rampe di accesso \u2013 RAMPA per TRAVEDO \u2013 RAMPA per GERONE \u2013 RAMPE per c.na GRAVA \u2013 c.na VOLPARA \u2013 c.na PIGNACCA \u2013 c.na MORONI.<\/p>\n<p>MODERATE LA VELOCITA\u2019 e GUIDATE CON PRUDENZA!!<\/p>\n<p><strong>Di seguito vengono riportate le previsioni meteo fornite da ARPA Lombardia per la giornata di domani mercoled\u00ec 30 gennaio:<\/strong><\/p>\n<p>L&#8217;ingresso di una veloce perturbazione fredda dalla Francia determiner\u00e0 nella giornata di domani 30\/01 un debole e rapido peggioramento sui settori occidentali della regione. Nelle prime sei ore di domani, deboli nevicate possibili su tutti i settori (ad esclusione della pianura orientale), tendenti a<br \/>\ndiventare pi\u00f9 diffuse tra le ore 6:00 e le ore 12:00 quando coinvolgeranno anche la pianura centrale. Considerata la quota dello zero termico prossima al suolo saranno possibili accumuli di 3-5 cm sulle zone di pianura occidentali, pi\u00f9 probabili su Lomellina-Pavese. Nella seconda parte del giorno rapida<br \/>\nattenuazione delle nevicate sulla pianura e settori Alpini e Prealpini centro-occidentali, nevicate ancora diffuse sull&#8217;Appennino Pavese e fascia collinare limitrofa dove a fine giornata saranno possibili accumuli localmente superiori ai 10 cm; deboli precipitazioni tenderanno a confinarsi sulla pianura orientale dove risulteranno a prevalente carattere di pioggia o pioggia mista a neve. In serata cessano i fenomeni su tutte le zone occidentali, mentre permarranno deboli precipitazioni sulla pianura orientale (prevalentemente pioggia mista a neve) e sui settori alpini-prealpini orientali, dove risulteranno nevose fino al fondovalle ma con accumuli in prevalenza scarsi. Sui settori di Nord-ovest accumuli al suolo prossimi o localmente superiori ai 10 cm, registrati soprattutto al mattino.<br \/>\nGioved\u00ec 31\/01, flusso in rotazione da ovest con temporaneo miglioramento e assenza di precipitazioni fino al pomeriggio, dalla sera nuova rotazione delle correnti da sud-ovest con peggioramento esteso a tutta la regione.<\/p>\n<p>In particolare, sulla base dello scenario di rischio neve ad oggi pi\u00f9 probabile, le possibili situazioni di criticit\u00e0 potrebbero essere legate soprattutto a difficolt\u00e0, rallentamenti e blocchi del traffico stradale, ferroviario e aeroportuale.<br \/>\nIn ogni caso, anche se i quantitativi di neve prevista al suolo saranno contenuti, ad oggi non si pu\u00f2 escludere la possibile formazione di ghiaccio sia durante la fase pi\u00f9 probabile delle precipitazioni (dalle ore 00 alle ore 12 del 30\/01), sia nel corso della serata-notte tra domani 30\/01 e gioved\u00ec 31\/01, con possibili valori negativi di temperatura a tutte le quote<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Previsione Meteo &#8211; probabile nevicata prevista per domani 30 gennaio. Come gi\u00e0 anticipato da alcuni giorni dagli organi di informazione, nelle prossime ore anche il nostro territorio sar\u00e0 interessato da [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#039; 30 GENNAIO - Sommo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#039; 30 GENNAIO - Sommo\" \/>\n<meta property=\"og:description\" content=\"Previsione Meteo &#8211; probabile nevicata prevista per domani 30 gennaio. Come gi\u00e0 anticipato da alcuni giorni dagli organi di informazione, nelle prossime ore anche il nostro territorio sar\u00e0 interessato da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sommo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-29T12:55:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"191\" \/>\n\t<meta property=\"og:image:height\" content=\"229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bottiroligiuseppina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bottiroligiuseppina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/\"},\"author\":{\"name\":\"bottiroligiuseppina\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"headline\":\"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#8217; 30 GENNAIO\",\"datePublished\":\"2019-01-29T12:55:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/\"},\"wordCount\":495,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2017\\\/12\\\/formazione-ghiaccio.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/\",\"name\":\"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI' 30 GENNAIO - Sommo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2017\\\/12\\\/formazione-ghiaccio.jpg\",\"datePublished\":\"2019-01-29T12:55:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2017\\\/12\\\/formazione-ghiaccio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/wp-content\\\/uploads\\\/sites\\\/67\\\/2017\\\/12\\\/formazione-ghiaccio.jpg\",\"width\":191,\"height\":229},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/2019\\\/01\\\/29\\\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#8217; 30 GENNAIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/\",\"name\":\"Sommo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/#\\\/schema\\\/person\\\/7310b6500325b1bcac00b4c3a409df0b\",\"name\":\"bottiroligiuseppina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g\",\"caption\":\"bottiroligiuseppina\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sommo\\\/author\\\/bottiroligiuseppina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI' 30 GENNAIO - Sommo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/","og_locale":"it_IT","og_type":"article","og_title":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI' 30 GENNAIO - Sommo","og_description":"Previsione Meteo &#8211; probabile nevicata prevista per domani 30 gennaio. Come gi\u00e0 anticipato da alcuni giorni dagli organi di informazione, nelle prossime ore anche il nostro territorio sar\u00e0 interessato da [&hellip;]","og_url":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/","og_site_name":"Sommo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-29T12:55:55+00:00","og_image":[{"width":191,"height":229,"url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg","type":"image\/jpeg"}],"author":"bottiroligiuseppina","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"bottiroligiuseppina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/"},"author":{"name":"bottiroligiuseppina","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"headline":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#8217; 30 GENNAIO","datePublished":"2019-01-29T12:55:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/"},"wordCount":495,"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/","url":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/","name":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI' 30 GENNAIO - Sommo","isPartOf":{"@id":"https:\/\/comunicacity.net\/sommo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg","datePublished":"2019-01-29T12:55:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#primaryimage","url":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg","contentUrl":"https:\/\/comunicacity.net\/sommo\/wp-content\/uploads\/sites\/67\/2017\/12\/formazione-ghiaccio.jpg","width":191,"height":229},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sommo\/2019\/01\/29\/attenzione-a-neve-e-ghiaccio-previsti-per-domani-mercoledi-30-gennaio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sommo\/"},{"@type":"ListItem","position":2,"name":"ATTENZIONE!! A NEVE E GHIACCIO PREVISTI PER DOMANI MERCOLEDI&#8217; 30 GENNAIO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sommo\/#website","url":"https:\/\/comunicacity.net\/sommo\/","name":"Sommo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sommo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sommo\/#\/schema\/person\/7310b6500325b1bcac00b4c3a409df0b","name":"bottiroligiuseppina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c65db506f53d5a8be2343400a4c85282c06a8b1588f57d424ba10549d4672c8f?s=96&d=mm&r=g","caption":"bottiroligiuseppina"},"url":"https:\/\/comunicacity.net\/sommo\/author\/bottiroligiuseppina\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/541\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/posts\/541\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media\/294"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/media?parent=541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/categories?post=541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sommo\/wp-json\/wp\/v2\/tags?post=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}