{"id":1016,"date":"2018-11-27T10:44:11","date_gmt":"2018-11-27T09:44:11","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1016"},"modified":"2018-11-27T10:44:11","modified_gmt":"2018-11-27T09:44:11","slug":"dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/","title":{"rendered":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30"},"content":{"rendered":"<p>Da mercoled\u00ec 28 novembre<span style=\"font-size: 1rem\">\u00a0<\/span><span style=\"font-size: 1rem\">e fino al termine di\u00a0<\/span><span style=\"font-size: 1rem\">lavori<\/span><span style=\"font-size: 1rem\">\u00a0per sostituzione tratto condotta fognaria\u00a0<\/span><span style=\"font-size: 1rem\">a cura di Ato Frusinate S.c.a.r.l., \u00e8 stata disposta con opportuna <a href=\"https:\/\/sora.trasparenza-valutazione-merito.it\/web\/trasparenza\/papca-ap?p_p_id=jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet&amp;p_p_lifecycle=2&amp;p_p_state=pop_up&amp;p_p_mode=view&amp;p_p_resource_id=downloadAllegato&amp;p_p_cacheability=cacheLevelPage&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_downloadSigned=false&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_id=2030787&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_action=mostraDettaglio&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_fromAction=recuperaDettaglio\">ordinanza<\/a>,<\/span><span style=\"font-size: 1rem\">\u00a0la chiusura al traffico veicolare\u00a0<\/span><span style=\"font-size: 1rem\">Via Grignano<\/span><span style=\"font-size: 1rem\">\u00a0 dalle ore 07.30 alle ore\u00a0<\/span><span style=\"font-size: 1rem\">17.30.\u00a0I lavori avranno una durata di circa 15 gg. salvo imprevisti e condizioni meteo avverse.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da mercoled\u00ec 28 novembre\u00a0e fino al termine di\u00a0lavori\u00a0per sostituzione tratto condotta fognaria\u00a0a cura di Ato Frusinate S.c.a.r.l., \u00e8 stata disposta con opportuna ordinanza,\u00a0la chiusura al traffico veicolare\u00a0Via Grignano\u00a0 dalle ore [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora\" \/>\n<meta property=\"og:description\" content=\"Da mercoled\u00ec 28 novembre\u00a0e fino al termine di\u00a0lavori\u00a0per sostituzione tratto condotta fognaria\u00a0a cura di Ato Frusinate S.c.a.r.l., \u00e8 stata disposta con opportuna ordinanza,\u00a0la chiusura al traffico veicolare\u00a0Via Grignano\u00a0 dalle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-27T09:44:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30\",\"datePublished\":\"2018-11-27T09:44:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/\"},\"wordCount\":68,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/\",\"name\":\"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"datePublished\":\"2018-11-27T09:44:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/11\\\/27\\\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora","og_description":"Da mercoled\u00ec 28 novembre\u00a0e fino al termine di\u00a0lavori\u00a0per sostituzione tratto condotta fognaria\u00a0a cura di Ato Frusinate S.c.a.r.l., \u00e8 stata disposta con opportuna ordinanza,\u00a0la chiusura al traffico veicolare\u00a0Via Grignano\u00a0 dalle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-27T09:44:11+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30","datePublished":"2018-11-27T09:44:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/"},"wordCount":68,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/","url":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/","name":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30 - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","datePublished":"2018-11-27T09:44:11+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/11\/27\/dal-28-novembre-e-per-15-giorni-chiusa-al-traffio-via-grignano-dalle-ore-7-30-alle-ore-17-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Dal 28 novembre e per 15 giorni chiusa al traffio via Grignano dalle ore 7.30 alle ore 17.30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1016\/revisions"}],"predecessor-version":[{"id":1017,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1016\/revisions\/1017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/281"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}