{"id":105,"date":"2018-02-13T09:22:28","date_gmt":"2018-02-13T08:22:28","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=105"},"modified":"2018-02-13T09:22:28","modified_gmt":"2018-02-13T08:22:28","slug":"carnevale-del-liri-manifestazione-rimandata-per-il-maltempo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/","title":{"rendered":"Carnevale del Liri: manifestazione rimandata per il maltempo"},"content":{"rendered":"<p>A causa delle avverse condizioni metereologiche, la tradizionale manifestazione del Carnevale del Liri, prevista marted\u00ec grasso 13 febbraio, \u00e8 stata rimandata a domenica 18 febbraio.<\/p>\n<p>Non \u00e8 stata revocata l&#8217;ordinanza per il termine delle lezioni scolastiche alle ore 12.00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa delle avverse condizioni metereologiche, la tradizionale manifestazione del Carnevale del Liri, prevista marted\u00ec grasso 13 febbraio, \u00e8 stata rimandata a domenica 18 febbraio. Non \u00e8 stata revocata l&#8217;ordinanza [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":68,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carnevale del Liri: manifestazione rimandata per il maltempo - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carnevale del Liri: manifestazione rimandata per il maltempo - Sora\" \/>\n<meta property=\"og:description\" content=\"A causa delle avverse condizioni metereologiche, la tradizionale manifestazione del Carnevale del Liri, prevista marted\u00ec grasso 13 febbraio, \u00e8 stata rimandata a domenica 18 febbraio. Non \u00e8 stata revocata l&#8217;ordinanza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-13T08:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"534\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Carnevale del Liri: manifestazione rimandata per il maltempo\",\"datePublished\":\"2018-02-13T08:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/\"},\"wordCount\":42,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/carnevaleedizione2014.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/\",\"name\":\"Carnevale del Liri: manifestazione rimandata per il maltempo - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/carnevaleedizione2014.jpg\",\"datePublished\":\"2018-02-13T08:22:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/carnevaleedizione2014.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/carnevaleedizione2014.jpg\",\"width\":534,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/02\\\/13\\\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carnevale del Liri: manifestazione rimandata per il maltempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carnevale del Liri: manifestazione rimandata per il maltempo - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/","og_locale":"it_IT","og_type":"article","og_title":"Carnevale del Liri: manifestazione rimandata per il maltempo - Sora","og_description":"A causa delle avverse condizioni metereologiche, la tradizionale manifestazione del Carnevale del Liri, prevista marted\u00ec grasso 13 febbraio, \u00e8 stata rimandata a domenica 18 febbraio. Non \u00e8 stata revocata l&#8217;ordinanza [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-02-13T08:22:28+00:00","og_image":[{"width":534,"height":800,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Carnevale del Liri: manifestazione rimandata per il maltempo","datePublished":"2018-02-13T08:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/"},"wordCount":42,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/","url":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/","name":"Carnevale del Liri: manifestazione rimandata per il maltempo - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg","datePublished":"2018-02-13T08:22:28+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/carnevaleedizione2014.jpg","width":534,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/02\/13\/carnevale-del-liri-manifestazione-rimandata-per-il-maltempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Carnevale del Liri: manifestazione rimandata per il maltempo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/105\/revisions"}],"predecessor-version":[{"id":106,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/105\/revisions\/106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/68"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}