{"id":1135,"date":"2019-01-04T12:52:33","date_gmt":"2019-01-04T11:52:33","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1135"},"modified":"2019-01-04T12:52:33","modified_gmt":"2019-01-04T11:52:33","slug":"natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/","title":{"rendered":"&#8220;Natale 2018&#8230; Magica atmosfera&#8221; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &#8220;Simoncelli&#8221; proiezione film &#8220;Supercuccioli a Natale&#8221;."},"content":{"rendered":"<p>Sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0 presso la sala &#8220;Simoncelli&#8221; della Biblioteca comunale, proiezione del film per bambini &#8220;Supercuccioli a Natale&#8221;.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0 presso la sala &#8220;Simoncelli&#8221; della Biblioteca comunale, proiezione del film per bambini &#8220;Supercuccioli a Natale&#8221;.<\/p>\n","protected":false},"author":250,"featured_media":1136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Natale 2018... Magica atmosfera&quot; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &quot;Simoncelli&quot; proiezione film &quot;Supercuccioli a Natale&quot;. - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Natale 2018... Magica atmosfera&quot; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &quot;Simoncelli&quot; proiezione film &quot;Supercuccioli a Natale&quot;. - Sora\" \/>\n<meta property=\"og:description\" content=\"Sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0 presso la sala &#8220;Simoncelli&#8221; della Biblioteca comunale, proiezione del film per bambini &#8220;Supercuccioli a Natale&#8221;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-04T11:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"&#8220;Natale 2018&#8230; Magica atmosfera&#8221; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &#8220;Simoncelli&#8221; proiezione film &#8220;Supercuccioli a Natale&#8221;.\",\"datePublished\":\"2019-01-04T11:52:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/\"},\"wordCount\":39,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/01\\\/SUPERCUCCIOLI-A-NATALE.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/\",\"name\":\"\\\"Natale 2018... Magica atmosfera\\\" sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala \\\"Simoncelli\\\" proiezione film \\\"Supercuccioli a Natale\\\". - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/01\\\/SUPERCUCCIOLI-A-NATALE.jpg\",\"datePublished\":\"2019-01-04T11:52:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/01\\\/SUPERCUCCIOLI-A-NATALE.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/01\\\/SUPERCUCCIOLI-A-NATALE.jpg\",\"width\":150,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/01\\\/04\\\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Natale 2018&#8230; Magica atmosfera&#8221; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &#8220;Simoncelli&#8221; proiezione film &#8220;Supercuccioli a Natale&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Natale 2018... Magica atmosfera\" sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala \"Simoncelli\" proiezione film \"Supercuccioli a Natale\". - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/","og_locale":"it_IT","og_type":"article","og_title":"\"Natale 2018... Magica atmosfera\" sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala \"Simoncelli\" proiezione film \"Supercuccioli a Natale\". - Sora","og_description":"Sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0 presso la sala &#8220;Simoncelli&#8221; della Biblioteca comunale, proiezione del film per bambini &#8220;Supercuccioli a Natale&#8221;.","og_url":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-04T11:52:33+00:00","og_image":[{"width":150,"height":210,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"&#8220;Natale 2018&#8230; Magica atmosfera&#8221; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &#8220;Simoncelli&#8221; proiezione film &#8220;Supercuccioli a Natale&#8221;.","datePublished":"2019-01-04T11:52:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/"},"wordCount":39,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/","url":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/","name":"\"Natale 2018... Magica atmosfera\" sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala \"Simoncelli\" proiezione film \"Supercuccioli a Natale\". - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg","datePublished":"2019-01-04T11:52:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/01\/SUPERCUCCIOLI-A-NATALE.jpg","width":150,"height":210},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/01\/04\/natale-2018-magica-atmosfera-sabato-5-gennaio-dalle-ore-16-00-e-fino-alle-18-00-sala-simoncelli-proiezione-film-supercuccioli-a-natale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"&#8220;Natale 2018&#8230; Magica atmosfera&#8221; sabato 5 gennaio dalle ore 16.00 e fino alle 18.00,\u00a0sala &#8220;Simoncelli&#8221; proiezione film &#8220;Supercuccioli a Natale&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1135\/revisions\/1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1136"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}