{"id":1173,"date":"2019-02-18T10:41:00","date_gmt":"2019-02-18T09:41:00","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1173"},"modified":"2019-02-18T10:41:00","modified_gmt":"2019-02-18T09:41:00","slug":"venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/","title":{"rendered":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata"},"content":{"rendered":"<p>Acea Ato 5 comunica che per lavori di manutenzione programmata da effettuarsi sulla rete idrica sottoferrovia, finalizzati al miglioramento del servizio idrico del Comune di Sora,<strong> venerd\u00ec 22 febbraio dalle ore 8.00 fino a tarda mattinata si verificher\u00e0 una sospensione del flusso idrico<\/strong>, in particolare le zone interessate sono:<\/p>\n<ul>\n<li><strong>via Sottoferrovia<\/strong><\/li>\n<li><strong>parte di via Madonna della Quercia<\/strong><\/li>\n<li><strong>via Camangi<\/strong><\/li>\n<li><strong>via Trecce<\/strong><\/li>\n<li><strong>via Annibale Petricca<\/strong><\/li>\n<li><strong>via San Giuliano Sura.<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Acea Ato 5 comunica che per lavori di manutenzione programmata da effettuarsi sulla rete idrica sottoferrovia, finalizzati al miglioramento del servizio idrico del Comune di Sora, venerd\u00ec 22 febbraio dalle [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora\" \/>\n<meta property=\"og:description\" content=\"Acea Ato 5 comunica che per lavori di manutenzione programmata da effettuarsi sulla rete idrica sottoferrovia, finalizzati al miglioramento del servizio idrico del Comune di Sora, venerd\u00ec 22 febbraio dalle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T09:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2481\" \/>\n\t<meta property=\"og:image:height\" content=\"3510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata\",\"datePublished\":\"2019-02-18T09:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/\"},\"wordCount\":76,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/interruzione-idrica-22-febbraio.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/\",\"name\":\"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/interruzione-idrica-22-febbraio.jpg\",\"datePublished\":\"2019-02-18T09:41:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/interruzione-idrica-22-febbraio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/interruzione-idrica-22-febbraio.jpg\",\"width\":2481,\"height\":3510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/18\\\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/","og_locale":"it_IT","og_type":"article","og_title":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora","og_description":"Acea Ato 5 comunica che per lavori di manutenzione programmata da effettuarsi sulla rete idrica sottoferrovia, finalizzati al miglioramento del servizio idrico del Comune di Sora, venerd\u00ec 22 febbraio dalle [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-18T09:41:00+00:00","og_image":[{"width":2481,"height":3510,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata","datePublished":"2019-02-18T09:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/"},"wordCount":76,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/","url":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/","name":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg","datePublished":"2019-02-18T09:41:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/interruzione-idrica-22-febbraio.jpg","width":2481,"height":3510},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/18\/venerdi-22-febbraio-interruzione-flusso-idrico-dalle-ore-8-00-fino-a-tarda-mattinata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Venerd\u00ec 22 febbraio interruzione flusso idrico dalle ore 8.00 fino a tarda mattinata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"predecessor-version":[{"id":1175,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1173\/revisions\/1175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1174"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}