{"id":1185,"date":"2019-02-23T11:42:48","date_gmt":"2019-02-23T10:42:48","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1185"},"modified":"2019-02-23T11:42:48","modified_gmt":"2019-02-23T10:42:48","slug":"rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/","title":{"rendered":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30"},"content":{"rendered":"<p>A causa delle avverse condizioni meteo, il concerto dell&#8217;orchestra da camera di Roma, previsto per oggi <strong>sabato 23 febbraio alle ore 18.30 nella Chiesa di S. Francesco, \u00e8 rimandato a data da destinarsi<\/strong><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>A causa delle avverse condizioni meteo, il concerto dell&#8217;orchestra da camera di Roma, previsto per oggi sabato 23 febbraio alle ore 18.30 nella Chiesa di S. Francesco, \u00e8 rimandato a [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora\" \/>\n<meta property=\"og:description\" content=\"A causa delle avverse condizioni meteo, il concerto dell&#8217;orchestra da camera di Roma, previsto per oggi sabato 23 febbraio alle ore 18.30 nella Chiesa di S. Francesco, \u00e8 rimandato a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-23T10:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30\",\"datePublished\":\"2019-02-23T10:42:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/\"},\"wordCount\":42,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/52609048_2224626241128009_869482280437940224_n.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/\",\"name\":\"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/52609048_2224626241128009_869482280437940224_n.jpg\",\"datePublished\":\"2019-02-23T10:42:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/52609048_2224626241128009_869482280437940224_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/52609048_2224626241128009_869482280437940224_n.jpg\",\"width\":628,\"height\":896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/23\\\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/","og_locale":"it_IT","og_type":"article","og_title":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora","og_description":"A causa delle avverse condizioni meteo, il concerto dell&#8217;orchestra da camera di Roma, previsto per oggi sabato 23 febbraio alle ore 18.30 nella Chiesa di S. Francesco, \u00e8 rimandato a [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-23T10:42:48+00:00","og_image":[{"width":628,"height":896,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30","datePublished":"2019-02-23T10:42:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/"},"wordCount":42,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/","url":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/","name":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30 - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg","datePublished":"2019-02-23T10:42:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/52609048_2224626241128009_869482280437940224_n.jpg","width":628,"height":896},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/23\/rinviato-concerto-orchestra-da-camera-chiesa-di-san-francesco-previsto-23-febbraio-ore-18-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Rinviato concerto orchestra da camera chiesa di San Francesco previsto 23 febbraio ore 18.30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1185\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1185\/revisions\/1187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1186"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}