{"id":1213,"date":"2019-02-26T14:00:08","date_gmt":"2019-02-26T13:00:08","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1213"},"modified":"2019-02-26T14:00:08","modified_gmt":"2019-02-26T13:00:08","slug":"mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/","title":{"rendered":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl"},"content":{"rendered":"<p>La Societ\u00e0 Ambiente surl ha comunicato al Comune di Sora la necessit\u00e0 di sostituire i mastelli andati perduti a causa del maltempo che ha flagellato nei giorni scorsi il territorio. In accordo con l\u2019Ente ed in via del tutto eccezionale e provvisoria, nell\u2019attesa di censire il numero dei mastelli necessari per organizzarne la sostituzione, sar\u00e0 possibile conferire i rifiuti per la raccolta porta a porta nelle buste ecologiche e trasparenti. Seguiranno aggiornamenti in merito al censimento ed alla relativa sostituzione dei mastelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Societ\u00e0 Ambiente surl ha comunicato al Comune di Sora la necessit\u00e0 di sostituire i mastelli andati perduti a causa del maltempo che ha flagellato nei giorni scorsi il territorio. [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora\" \/>\n<meta property=\"og:description\" content=\"La Societ\u00e0 Ambiente surl ha comunicato al Comune di Sora la necessit\u00e0 di sostituire i mastelli andati perduti a causa del maltempo che ha flagellato nei giorni scorsi il territorio. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-26T13:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"183\" \/>\n\t<meta property=\"og:image:height\" content=\"58\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl\",\"datePublished\":\"2019-02-26T13:00:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/\"},\"wordCount\":95,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/\",\"name\":\"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente-1.png\",\"datePublished\":\"2019-02-26T13:00:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente-1.png\",\"width\":183,\"height\":58},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/02\\\/26\\\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/","og_locale":"it_IT","og_type":"article","og_title":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora","og_description":"La Societ\u00e0 Ambiente surl ha comunicato al Comune di Sora la necessit\u00e0 di sostituire i mastelli andati perduti a causa del maltempo che ha flagellato nei giorni scorsi il territorio. [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-26T13:00:08+00:00","og_image":[{"width":183,"height":58,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png","type":"image\/png"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl","datePublished":"2019-02-26T13:00:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/"},"wordCount":95,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/","url":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/","name":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png","datePublished":"2019-02-26T13:00:08+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente-1.png","width":183,"height":58},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/02\/26\/mastelli-persi-a-causa-del-maltempo-le-indicazioni-di-ambiente-surl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Mastelli persi a causa del maltempo: le indicazioni di Ambiente surl"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1213"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1213\/revisions"}],"predecessor-version":[{"id":1216,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1213\/revisions\/1216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1215"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}