{"id":1288,"date":"2019-03-13T14:04:37","date_gmt":"2019-03-13T13:04:37","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1288"},"modified":"2019-03-13T14:04:37","modified_gmt":"2019-03-13T13:04:37","slug":"sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/","title":{"rendered":"Sabato 16 marzo ore 11.00 auditorium &#8220;Baronio&#8221; evento &#8220;Valorizzazione dei fondi librari antichi&#8221;"},"content":{"rendered":"<p><strong style=\"font-size: 1rem\">Sabato 16 marzo ore 11.00\u00a0<\/strong><span style=\"font-size: 1rem\">presso l&#8217;Auditorium dell<\/span><strong style=\"font-size: 1rem\">\u2019IIS \u201cCesare Baronio\u201d Servizi per l\u2019Enogastronomia e l\u2019Ospitalit\u00e0 Alberghiera <\/strong>evento gastronomico e culturale nell&#8217;ambito della manifestazione\u00a0<strong>\u201cValorizzazione dei fondi librai antichi\u201d<\/strong>\u00a0progetto realizzato dalla Provincia di Frosinone e finanziato dalla Regione Lazio in collaborazione con il Comune di Sora ed il Centro Studi Sorani &#8220;V. Patriarca&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 16 marzo ore 11.00\u00a0presso l&#8217;Auditorium dell\u2019IIS \u201cCesare Baronio\u201d Servizi per l\u2019Enogastronomia e l\u2019Ospitalit\u00e0 Alberghiera evento gastronomico e culturale nell&#8217;ambito della manifestazione\u00a0\u201cValorizzazione dei fondi librai antichi\u201d\u00a0progetto realizzato dalla Provincia di [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sabato 16 marzo ore 11.00 auditorium &quot;Baronio&quot; evento &quot;Valorizzazione dei fondi librari antichi&quot; - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabato 16 marzo ore 11.00 auditorium &quot;Baronio&quot; evento &quot;Valorizzazione dei fondi librari antichi&quot; - Sora\" \/>\n<meta property=\"og:description\" content=\"Sabato 16 marzo ore 11.00\u00a0presso l&#8217;Auditorium dell\u2019IIS \u201cCesare Baronio\u201d Servizi per l\u2019Enogastronomia e l\u2019Ospitalit\u00e0 Alberghiera evento gastronomico e culturale nell&#8217;ambito della manifestazione\u00a0\u201cValorizzazione dei fondi librai antichi\u201d\u00a0progetto realizzato dalla Provincia di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-13T13:04:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1-704x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"704\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Sabato 16 marzo ore 11.00 auditorium &#8220;Baronio&#8221; evento &#8220;Valorizzazione dei fondi librari antichi&#8221;\",\"datePublished\":\"2019-03-13T13:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/\"},\"wordCount\":65,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/03\\\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/\",\"name\":\"Sabato 16 marzo ore 11.00 auditorium \\\"Baronio\\\" evento \\\"Valorizzazione dei fondi librari antichi\\\" - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/03\\\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg\",\"datePublished\":\"2019-03-13T13:04:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/03\\\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/03\\\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg\",\"width\":1299,\"height\":1889},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/13\\\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabato 16 marzo ore 11.00 auditorium &#8220;Baronio&#8221; evento &#8220;Valorizzazione dei fondi librari antichi&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sabato 16 marzo ore 11.00 auditorium \"Baronio\" evento \"Valorizzazione dei fondi librari antichi\" - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/","og_locale":"it_IT","og_type":"article","og_title":"Sabato 16 marzo ore 11.00 auditorium \"Baronio\" evento \"Valorizzazione dei fondi librari antichi\" - Sora","og_description":"Sabato 16 marzo ore 11.00\u00a0presso l&#8217;Auditorium dell\u2019IIS \u201cCesare Baronio\u201d Servizi per l\u2019Enogastronomia e l\u2019Ospitalit\u00e0 Alberghiera evento gastronomico e culturale nell&#8217;ambito della manifestazione\u00a0\u201cValorizzazione dei fondi librai antichi\u201d\u00a0progetto realizzato dalla Provincia di [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-03-13T13:04:37+00:00","og_image":[{"width":704,"height":1024,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1-704x1024.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Sabato 16 marzo ore 11.00 auditorium &#8220;Baronio&#8221; evento &#8220;Valorizzazione dei fondi librari antichi&#8221;","datePublished":"2019-03-13T13:04:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/"},"wordCount":65,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/","url":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/","name":"Sabato 16 marzo ore 11.00 auditorium \"Baronio\" evento \"Valorizzazione dei fondi librari antichi\" - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg","datePublished":"2019-03-13T13:04:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/03\/02-Locandina-16-marzo-20191-culturale-enogastronomico-1.jpg","width":1299,"height":1889},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/13\/sabato-16-marzo-ore-11-00-auditorium-baronio-evento-valorizzazione-dei-fondi-librari-antichi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Sabato 16 marzo ore 11.00 auditorium &#8220;Baronio&#8221; evento &#8220;Valorizzazione dei fondi librari antichi&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1288"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1288\/revisions"}],"predecessor-version":[{"id":1292,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1288\/revisions\/1292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1291"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}