{"id":1317,"date":"2019-03-29T19:35:22","date_gmt":"2019-03-29T18:35:22","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1317"},"modified":"2019-03-29T19:35:22","modified_gmt":"2019-03-29T18:35:22","slug":"mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/","title":{"rendered":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione"},"content":{"rendered":"<p><em>&#8220;La Societ\u00e0 Ambiente Surl a seguito dei disagi provocati dalle forte raffiche di vento che hanno causato la perdita o il danneggiamento dei mastelli,dopo aver censito il numero dei mastelli necessari,per ovviare a queste necessit\u00e0 provveder\u00e0 nel primo caso, alla riconsegna del secchio smarrito,nel secondo caso alla sostituzione dietro riconsegna del mastello danneggiato.<\/em><\/p>\n<p><em>Si precisa che:<\/em><\/p>\n<ul>\n<li><em>La riconsegna o sostituzione sar\u00e0 possibile nel giorni di Luned\u00ec, Marted\u00ec, Mercoled\u00ec,Venerd\u00ec, Sabato <u>e<\/u>scluso il Gioved\u00ec, dalle ore 9:00 alle 13:00 presso l&#8217;Eco-centro di Santa Rosalia<\/em><\/li>\n<li><em>Le operazioni di riconsegna o sostituzione verranno i<u>n via del tutto<\/u> <u>e<\/u>ccezionale in ragione della straordinariet\u00e0 delle raffiche di vento, pertanto si raccomanda per il futuro di avere maggior cura e di ancorare il mastello in caso di forte<\/em><\/li>\n<li><em>Per le operazioni di ritiro e sostituzione sar\u00e0 necessario munirsi di un valido documento di <\/em><em>identit\u00e0.<\/em><\/li>\n<\/ul>\n<p><em>Nello scusarci per Il temporaneo disagio, nell&#8217;ottica di un costante sforzo per migliorare ed ottimizzare il servizio,vi ringraziamo per la collaborazione.<\/em><\/p>\n<p><em>Invitiamo la cittadinanza a seguire gli aggiornamenti che verranno diramati nel consueti canali:<\/em><\/p>\n<p><em>Ambiente Surl\u00a0 \u00a0https:\/\/ambientesora .it\/<\/em><\/p>\n<p><em>https:\/\/www.facebook.com\/Ambiente-Surl<\/em><\/p>\n<p><em>Comune\u00a0\u00a0\u00a0 di\u00a0\u00a0\u00a0 Sora\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 https:www<a href=\"http:\/\/www\/\">.<\/a>comune.sora.fr.lt\/ https:\/\/www.facebook.com\/comunesora\/<\/em><\/p>\n<p><em>Comunica City-Sora\u00a0 <a href=\"http:\/\/comuni\/\">http:\/\/comuni<\/a>cacity.net\/sora\/&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La Societ\u00e0 Ambiente Surl a seguito dei disagi provocati dalle forte raffiche di vento che hanno causato la perdita o il danneggiamento dei mastelli,dopo aver censito il numero dei mastelli [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora\" \/>\n<meta property=\"og:description\" content=\"&#8220;La Societ\u00e0 Ambiente Surl a seguito dei disagi provocati dalle forte raffiche di vento che hanno causato la perdita o il danneggiamento dei mastelli,dopo aver censito il numero dei mastelli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-29T18:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"183\" \/>\n\t<meta property=\"og:image:height\" content=\"58\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Mastelli persi o danneggiati dal vento, le misure per la sostituzione\",\"datePublished\":\"2019-03-29T18:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/\"},\"wordCount\":215,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/\",\"name\":\"Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente.png\",\"datePublished\":\"2019-03-29T18:35:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/02\\\/ambiente.png\",\"width\":183,\"height\":58},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/03\\\/29\\\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mastelli persi o danneggiati dal vento, le misure per la sostituzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/","og_locale":"it_IT","og_type":"article","og_title":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora","og_description":"&#8220;La Societ\u00e0 Ambiente Surl a seguito dei disagi provocati dalle forte raffiche di vento che hanno causato la perdita o il danneggiamento dei mastelli,dopo aver censito il numero dei mastelli [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-03-29T18:35:22+00:00","og_image":[{"width":183,"height":58,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png","type":"image\/png"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione","datePublished":"2019-03-29T18:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/"},"wordCount":215,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/","url":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/","name":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png","datePublished":"2019-03-29T18:35:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/02\/ambiente.png","width":183,"height":58},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/03\/29\/mastelli-persi-o-danneggiati-dal-vento-le-misure-per-la-sostituzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Mastelli persi o danneggiati dal vento, le misure per la sostituzione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1317\/revisions"}],"predecessor-version":[{"id":1318,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1317\/revisions\/1318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1214"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}