{"id":1341,"date":"2019-04-08T23:05:54","date_gmt":"2019-04-08T21:05:54","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1341"},"modified":"2019-04-08T23:05:54","modified_gmt":"2019-04-08T21:05:54","slug":"venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/","title":{"rendered":"Venerd\u00ec 12 aprile inaugurazione parete d&#8217;arrampicata nella sede CAI Sora via Valleradice"},"content":{"rendered":"<p>La parete, che sar\u00e0 presentata venerd\u00ec 12 aprile alle ore 17.00 nella sede CAI in via Valleradice, \u00e8 suddivisa in tre moduli di diversa inclinazione di metri 4.5 d\u2019altezza e 7.25 di larghezza.<\/p>\n<p><span style=\"font-size: 1rem\">Nel corso dell\u2019 inaugurazione gli Istruttori della Scuola Cai d\u2019Alpinismo, Scialpinismo e Arrampicata libera \u201cLa Spada nella Roccia\u201d garantiranno prove d\u2019arrampicata gratuite per tutti.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La parete, che sar\u00e0 presentata venerd\u00ec 12 aprile alle ore 17.00 nella sede CAI in via Valleradice, \u00e8 suddivisa in tre moduli di diversa inclinazione di metri 4.5 d\u2019altezza e [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venerd\u00ec 12 aprile inaugurazione parete d&#039;arrampicata nella sede CAI Sora via Valleradice - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venerd\u00ec 12 aprile inaugurazione parete d&#039;arrampicata nella sede CAI Sora via Valleradice - Sora\" \/>\n<meta property=\"og:description\" content=\"La parete, che sar\u00e0 presentata venerd\u00ec 12 aprile alle ore 17.00 nella sede CAI in via Valleradice, \u00e8 suddivisa in tre moduli di diversa inclinazione di metri 4.5 d\u2019altezza e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-08T21:05:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"169\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Venerd\u00ec 12 aprile inaugurazione parete d&#8217;arrampicata nella sede CAI Sora via Valleradice\",\"datePublished\":\"2019-04-08T21:05:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/\"},\"wordCount\":66,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/inaugurazione-parete-cai.jpeg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/\",\"name\":\"Venerd\u00ec 12 aprile inaugurazione parete d'arrampicata nella sede CAI Sora via Valleradice - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/inaugurazione-parete-cai.jpeg\",\"datePublished\":\"2019-04-08T21:05:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/inaugurazione-parete-cai.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/inaugurazione-parete-cai.jpeg\",\"width\":169,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/08\\\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venerd\u00ec 12 aprile inaugurazione parete d&#8217;arrampicata nella sede CAI Sora via Valleradice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venerd\u00ec 12 aprile inaugurazione parete d'arrampicata nella sede CAI Sora via Valleradice - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/","og_locale":"it_IT","og_type":"article","og_title":"Venerd\u00ec 12 aprile inaugurazione parete d'arrampicata nella sede CAI Sora via Valleradice - Sora","og_description":"La parete, che sar\u00e0 presentata venerd\u00ec 12 aprile alle ore 17.00 nella sede CAI in via Valleradice, \u00e8 suddivisa in tre moduli di diversa inclinazione di metri 4.5 d\u2019altezza e [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-08T21:05:54+00:00","og_image":[{"width":169,"height":240,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Venerd\u00ec 12 aprile inaugurazione parete d&#8217;arrampicata nella sede CAI Sora via Valleradice","datePublished":"2019-04-08T21:05:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/"},"wordCount":66,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/","url":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/","name":"Venerd\u00ec 12 aprile inaugurazione parete d'arrampicata nella sede CAI Sora via Valleradice - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg","datePublished":"2019-04-08T21:05:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/inaugurazione-parete-cai.jpeg","width":169,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/08\/venerdi-12-aprile-inaugurazione-parete-darrampicata-nella-sede-cai-sora-via-valleradice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Venerd\u00ec 12 aprile inaugurazione parete d&#8217;arrampicata nella sede CAI Sora via Valleradice"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1341"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1341\/revisions"}],"predecessor-version":[{"id":1343,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1341\/revisions\/1343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1342"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}