{"id":1348,"date":"2019-04-09T19:06:35","date_gmt":"2019-04-09T17:06:35","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1348"},"modified":"2019-04-09T19:06:35","modified_gmt":"2019-04-09T17:06:35","slug":"10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/","title":{"rendered":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura"},"content":{"rendered":"<p>Con apposita <a href=\"https:\/\/sora.trasparenza-valutazione-merito.it\/web\/trasparenza\/papca-ap?p_p_id=jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet&amp;p_p_lifecycle=2&amp;p_p_state=pop_up&amp;p_p_mode=view&amp;p_p_resource_id=downloadAllegato&amp;p_p_cacheability=cacheLevelPage&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_downloadSigned=false&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_id=2941787&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_action=mostraDettaglio&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_fromAction=recuperaDettaglio\">ordinanza<\/a> \u00e8 stata disposta,\u00a0 nei giorni 10\/11\/12\/13 aprile 2019 dalle ore 8.00 alle ore 17.30, la chiusura al traffico veicolare in Via Madonna Della Figura per procedere alla messa in sicurezza di n\u00b0 5 alberi di quercia che insistono sulla strada comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con apposita ordinanza \u00e8 stata disposta,\u00a0 nei giorni 10\/11\/12\/13 aprile 2019 dalle ore 8.00 alle ore 17.30, la chiusura al traffico veicolare in Via Madonna Della Figura per procedere alla [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora\" \/>\n<meta property=\"og:description\" content=\"Con apposita ordinanza \u00e8 stata disposta,\u00a0 nei giorni 10\/11\/12\/13 aprile 2019 dalle ore 8.00 alle ore 17.30, la chiusura al traffico veicolare in Via Madonna Della Figura per procedere alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-09T17:06:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"10\\\/11\\\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura\",\"datePublished\":\"2019-04-09T17:06:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/\"},\"wordCount\":51,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/12\\\/paletta-stop-traffico.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/\",\"name\":\"10\\\/11\\\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/12\\\/paletta-stop-traffico.jpg\",\"datePublished\":\"2019-04-09T17:06:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/12\\\/paletta-stop-traffico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/12\\\/paletta-stop-traffico.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/09\\\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10\\\/11\\\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/","og_locale":"it_IT","og_type":"article","og_title":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora","og_description":"Con apposita ordinanza \u00e8 stata disposta,\u00a0 nei giorni 10\/11\/12\/13 aprile 2019 dalle ore 8.00 alle ore 17.30, la chiusura al traffico veicolare in Via Madonna Della Figura per procedere alla [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-09T17:06:35+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura","datePublished":"2019-04-09T17:06:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/"},"wordCount":51,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/","url":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/","name":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg","datePublished":"2019-04-09T17:06:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/12\/paletta-stop-traffico.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/09\/10-11-12-aprile-dalle-ore-8-00-alle-ore17-30-chiusura-al-traffico-in-via-madonna-della-figura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"10\/11\/12 aprile dalle ore 8.00 alle ore17.30 chiusura al traffico in via Madonna della Figura"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1348\/revisions"}],"predecessor-version":[{"id":1349,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1348\/revisions\/1349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1065"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}