{"id":1369,"date":"2019-04-17T08:57:00","date_gmt":"2019-04-17T06:57:00","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1369"},"modified":"2019-04-17T08:57:00","modified_gmt":"2019-04-17T06:57:00","slug":"convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/","title":{"rendered":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30"},"content":{"rendered":"<p style=\"text-align: left\">Il presidente del Consiglio Comunale\u00a0 Antonio Lecce, ha disposto la convocazione della massima assise cittadina in seduta pubblica, ordinaria, presso la sala Consiliare ubicata in Corso Volsci n. 111, in prima convocazione per il giorno:<\/p>\n<p style=\"text-align: center\"><strong>MARTEDI\u2019 23 APRILE 2019 ORE 17.30<\/strong><\/p>\n<p style=\"text-align: left\">e, in caso di mancanza del numero legale, in seconda convocazione per il giorno:<\/p>\n<p style=\"text-align: center\"><strong>mercoled\u00ec 24 aprile 2019 ore 18.30<\/strong><\/p>\n<p style=\"text-align: left\">per la trattazione del seguente ordine del giorno:<br \/>\n1) Piano di razionalizzazione delle Societ\u00e0 Partecipate.<br \/>\n2) Approvazione Bilancio consolidato anno 2017.<br \/>\n3) Approvazione Bilancio di previsione 2019-2021.<br \/>\n4) Riconoscimento dei debiti fuori bilancio, ai sensi dell\u2019art. 194 D.Lgs. 267\/2000.<br \/>\n5) Adeguamento compenso Collegio dei Revisori dei Conti ai sensi del Decreto Ministero<br \/>\ndell\u2019Interno di concerto con il MEF \u2013 Ministero dell\u2019Economia e delle Finanze del<br \/>\n21.12.2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente del Consiglio Comunale\u00a0 Antonio Lecce, ha disposto la convocazione della massima assise cittadina in seduta pubblica, ordinaria, presso la sala Consiliare ubicata in Corso Volsci n. 111, in [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora\" \/>\n<meta property=\"og:description\" content=\"Il presidente del Consiglio Comunale\u00a0 Antonio Lecce, ha disposto la convocazione della massima assise cittadina in seduta pubblica, ordinaria, presso la sala Consiliare ubicata in Corso Volsci n. 111, in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-17T06:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30\",\"datePublished\":\"2019-04-17T06:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/\"},\"wordCount\":120,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/\",\"name\":\"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"datePublished\":\"2019-04-17T06:57:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"width\":400,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/04\\\/17\\\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora","og_description":"Il presidente del Consiglio Comunale\u00a0 Antonio Lecce, ha disposto la convocazione della massima assise cittadina in seduta pubblica, ordinaria, presso la sala Consiliare ubicata in Corso Volsci n. 111, in [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-17T06:57:00+00:00","og_image":[{"width":400,"height":277,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30","datePublished":"2019-04-17T06:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/"},"wordCount":120,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/","url":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/","name":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30 - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","datePublished":"2019-04-17T06:57:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","width":400,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/04\/17\/convocazione-consiglio-comunale-martedi-23-aprile-2019-ore-17-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio Comunale, marted\u00ec 23 aprile 2019 ore 17.30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1369\/revisions"}],"predecessor-version":[{"id":1370,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1369\/revisions\/1370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}