{"id":1482,"date":"2019-06-13T09:46:26","date_gmt":"2019-06-13T07:46:26","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1482"},"modified":"2019-06-13T16:52:30","modified_gmt":"2019-06-13T14:52:30","slug":"convocazione-consiglio-comunale-18-giugno-2019-ore-18-00","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/","title":{"rendered":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00"},"content":{"rendered":"<p>Il Presidente Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in I convocazione, per il giorno:<\/p>\n<p style=\"text-align: center\"><strong>MARTEDI\u2019 18 GIUGNO 2019 ORE 18.00<\/strong><\/p>\n<p>e, in caso di mancanza del numero legale, in II convocazione, per il giorno mercoled\u00ec 19 giugno 2019 ore 19.00<br \/>\nper la trattazione del seguente ordine del giorno:<\/p>\n<p>1) Interrogazione presentata dal Consigliere Fabrizio Pintori, avente ad oggetto: \u201cFrana in zona<br \/>\nCompre Alte\u201d (prot. n. 2656 del 24.01.2019);<br \/>\n2) Interrogazione presentata dai Consiglieri Petricca Serena e Farina Antonio, avente ad<br \/>\noggetto problematiche inerenti le \u201cDiscariche abusive\u201d (prot. n. 6418 del 19.02.2019);<br \/>\n3) Interrogazione presentata dal Consigliere Valter Tersigni, avente ad oggetto: \u201cAffidamento<br \/>\ngestione dei Servizi bibliotecari archivistici ed attivit\u00e0 connesse allo Sportello delle politiche<br \/>\ngiovanili\u201d (prot. n. 8624 dell\u201911.03.2019);<br \/>\n4) Designazione Amministratore Unico Societ\u00e0 in house \u201cAMBIENTE S.u.r.l.\u201d;<br \/>\n5) Riconoscimento debito fuori bilancio ai sensi dell\u2019art. 194, comma 1, lett. E) del D.Lgs.<br \/>\n267\/2000;<br \/>\n6) Approvazione schemi del Bilancio consolidato anno 2017 &#8211; art. 18 del D.Lgs. 118\/2011;<br \/>\n7) Contrasto al fenomeno delle micro-discariche abusive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in I convocazione, per il [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Presidente Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in I convocazione, per il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-13T07:46:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-13T14:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00\",\"datePublished\":\"2019-06-13T07:46:26+00:00\",\"dateModified\":\"2019-06-13T14:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/\"},\"wordCount\":169,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/\",\"name\":\"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"datePublished\":\"2019-06-13T07:46:26+00:00\",\"dateModified\":\"2019-06-13T14:52:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"width\":400,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/06\\\/13\\\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora","og_description":"Il Presidente Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in I convocazione, per il [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-06-13T07:46:26+00:00","article_modified_time":"2019-06-13T14:52:30+00:00","og_image":[{"width":400,"height":277,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00","datePublished":"2019-06-13T07:46:26+00:00","dateModified":"2019-06-13T14:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/"},"wordCount":169,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/","url":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/","name":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00 - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","datePublished":"2019-06-13T07:46:26+00:00","dateModified":"2019-06-13T14:52:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","width":400,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/06\/13\/convocazione-consiglio-comunale-18-giugno-2019-ore-18-00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio Comunale 18 giugno 2019 ore 18.00"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1482"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1482\/revisions"}],"predecessor-version":[{"id":1489,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1482\/revisions\/1489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}