{"id":1611,"date":"2019-09-16T11:12:04","date_gmt":"2019-09-16T09:12:04","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1611"},"modified":"2019-09-16T11:12:04","modified_gmt":"2019-09-16T09:12:04","slug":"cure-termali-2019-attivato-il-servizio-di-trasporto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/","title":{"rendered":"Cure termali 2019, attivato il servizio di trasporto"},"content":{"rendered":"<p>Il Comune di Sora organizza, in collaborazione con le Terme di Pompeo di Ferentino, il servizio di trasporto a favore degli anziani ed invalidi residenti che vogliono usufruire di un ciclo di cure termali. Il periodo in cui si potr\u00e0 fruire di questo servizio \u00e8 di dodici giorni, dal 22 ottobre al 7 novembre 2019, esclusi sabato, domenica e giorni festivi.<br \/>\nTutti i cittadini interessati dovranno presentare specifica istanza, tramite l\u2019apposito modulo, disponibile presso l\u2019Ufficio Servizi Sociali, Ufficio Relazioni con il Pubblico e sul sito web del comune.<br \/>\nLe istanze, debitamente compilate e corredate dalla documentazione richiesta, dovranno pervenire all\u2019Ufficio Servizi Sociali di questo Ente, sito in Corso Volsci n. 1, entro e non oltre le ore 17.00 del 07 0ttobre 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Sora organizza, in collaborazione con le Terme di Pompeo di Ferentino, il servizio di trasporto a favore degli anziani ed invalidi residenti che vogliono usufruire di un [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cure termali 2019, attivato il servizio di trasporto - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cure termali 2019, attivato il servizio di trasporto - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Sora organizza, in collaborazione con le Terme di Pompeo di Ferentino, il servizio di trasporto a favore degli anziani ed invalidi residenti che vogliono usufruire di un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-16T09:12:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Cure termali 2019, attivato il servizio di trasporto\",\"datePublished\":\"2019-09-16T09:12:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/\"},\"wordCount\":124,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/09\\\/Terme-Pompeo-Ferentino.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/\",\"name\":\"Cure termali 2019, attivato il servizio di trasporto - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/09\\\/Terme-Pompeo-Ferentino.jpg\",\"datePublished\":\"2019-09-16T09:12:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/09\\\/Terme-Pompeo-Ferentino.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/09\\\/Terme-Pompeo-Ferentino.jpg\",\"width\":722,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/09\\\/16\\\/cure-termali-2019-attivato-il-servizio-di-trasporto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cure termali 2019, attivato il servizio di trasporto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cure termali 2019, attivato il servizio di trasporto - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/","og_locale":"it_IT","og_type":"article","og_title":"Cure termali 2019, attivato il servizio di trasporto - Sora","og_description":"Il Comune di Sora organizza, in collaborazione con le Terme di Pompeo di Ferentino, il servizio di trasporto a favore degli anziani ed invalidi residenti che vogliono usufruire di un [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-09-16T09:12:04+00:00","og_image":[{"width":722,"height":392,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Cure termali 2019, attivato il servizio di trasporto","datePublished":"2019-09-16T09:12:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/"},"wordCount":124,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/","url":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/","name":"Cure termali 2019, attivato il servizio di trasporto - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg","datePublished":"2019-09-16T09:12:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/09\/Terme-Pompeo-Ferentino.jpg","width":722,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/09\/16\/cure-termali-2019-attivato-il-servizio-di-trasporto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Cure termali 2019, attivato il servizio di trasporto"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1611"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1611\/revisions"}],"predecessor-version":[{"id":1613,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1611\/revisions\/1613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1612"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}