{"id":1652,"date":"2019-10-07T16:17:44","date_gmt":"2019-10-07T14:17:44","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1652"},"modified":"2019-10-07T16:17:44","modified_gmt":"2019-10-07T14:17:44","slug":"venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/","title":{"rendered":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;"},"content":{"rendered":"<p>&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;, primo appuntamento fissato per venerd\u00ec 11 ottobre alle ore 21.00 in Sala Consiliare con il concerto del grande violinista di fama internazionale Ralph Evans che guider\u00e0 il &#8220;TRIO D&#8217;ARCHI WILLIENCOURT di PARIGI&#8221; con i maestri Gerard Cousse alla viola e Dominique De Williencourt al violoncello. Saranno eseguiti brani di: L. Van Beethoven, D. De Williencourt e J. Francais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;, primo appuntamento fissato per venerd\u00ec 11 ottobre alle ore 21.00 in Sala Consiliare con il concerto del grande violinista di fama internazionale Ralph Evans [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&quot;Lazio delle Meraviglie Plastic Free 2019&quot; - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&quot;Lazio delle Meraviglie Plastic Free 2019&quot; - Sora\" \/>\n<meta property=\"og:description\" content=\"&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;, primo appuntamento fissato per venerd\u00ec 11 ottobre alle ore 21.00 in Sala Consiliare con il concerto del grande violinista di fama internazionale Ralph Evans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-07T14:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;\",\"datePublished\":\"2019-10-07T14:17:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/\"},\"wordCount\":72,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/plastic-free.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/\",\"name\":\"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0\\\"Lazio delle Meraviglie Plastic Free 2019\\\" - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/plastic-free.jpg\",\"datePublished\":\"2019-10-07T14:17:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/plastic-free.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/plastic-free.jpg\",\"width\":620,\"height\":622},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/10\\\/07\\\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0\"Lazio delle Meraviglie Plastic Free 2019\" - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0\"Lazio delle Meraviglie Plastic Free 2019\" - Sora","og_description":"&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;, primo appuntamento fissato per venerd\u00ec 11 ottobre alle ore 21.00 in Sala Consiliare con il concerto del grande violinista di fama internazionale Ralph Evans [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-10-07T14:17:44+00:00","og_image":[{"width":620,"height":622,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;","datePublished":"2019-10-07T14:17:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/"},"wordCount":72,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/","url":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/","name":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0\"Lazio delle Meraviglie Plastic Free 2019\" - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg","datePublished":"2019-10-07T14:17:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/plastic-free.jpg","width":620,"height":622},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/10\/07\/venerdi-11-ottobre-ore-21-00-sala-consiliare-concerto-lazio-delle-meraviglie-plastic-free-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Venerd\u00ec 11 ottobre ore 21.00 sala consiliare concerto \u00a0&#8220;Lazio delle Meraviglie Plastic Free 2019&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":1654,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1652\/revisions\/1654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1653"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}