{"id":1730,"date":"2019-11-20T13:32:52","date_gmt":"2019-11-20T12:32:52","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1730"},"modified":"2019-11-20T13:32:52","modified_gmt":"2019-11-20T12:32:52","slug":"go-blue-il-municipio-illuminato-di-blu-per-lunicef","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/","title":{"rendered":"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#8217;Unicef"},"content":{"rendered":"<p>Anche L\u2019Amministrazione comunale di Sora aderisce alla campagna di sensibilizzazione \u201cGo blue\u201d, lanciata dall\u2019Unicef per celebrare la Giornata mondiale dell\u2019Infanzia e dell\u2019Adolescenza, illuminando di blu la facciata del Municipio la serata di mercoled\u00ec 20 novembre 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche L\u2019Amministrazione comunale di Sora aderisce alla campagna di sensibilizzazione \u201cGo blue\u201d, lanciata dall\u2019Unicef per celebrare la Giornata mondiale dell\u2019Infanzia e dell\u2019Adolescenza, illuminando di blu la facciata del Municipio la [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cGo blue\u201d, il Municipio illuminato di blu per l&#039;Unicef - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#039;Unicef - Sora\" \/>\n<meta property=\"og:description\" content=\"Anche L\u2019Amministrazione comunale di Sora aderisce alla campagna di sensibilizzazione \u201cGo blue\u201d, lanciata dall\u2019Unicef per celebrare la Giornata mondiale dell\u2019Infanzia e dell\u2019Adolescenza, illuminando di blu la facciata del Municipio la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T12:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"87\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#8217;Unicef\",\"datePublished\":\"2019-11-20T12:32:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/\"},\"wordCount\":47,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/11\\\/GO-BLUE-300x87.gif\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/\",\"name\":\"\u201cGo blue\u201d, il Municipio illuminato di blu per l'Unicef - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/11\\\/GO-BLUE-300x87.gif\",\"datePublished\":\"2019-11-20T12:32:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/11\\\/GO-BLUE-300x87.gif\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/11\\\/GO-BLUE-300x87.gif\",\"width\":300,\"height\":87},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/11\\\/20\\\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#8217;Unicef\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cGo blue\u201d, il Municipio illuminato di blu per l'Unicef - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cGo blue\u201d, il Municipio illuminato di blu per l'Unicef - Sora","og_description":"Anche L\u2019Amministrazione comunale di Sora aderisce alla campagna di sensibilizzazione \u201cGo blue\u201d, lanciata dall\u2019Unicef per celebrare la Giornata mondiale dell\u2019Infanzia e dell\u2019Adolescenza, illuminando di blu la facciata del Municipio la [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-11-20T12:32:52+00:00","og_image":[{"width":300,"height":87,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif","type":"image\/gif"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#8217;Unicef","datePublished":"2019-11-20T12:32:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/"},"wordCount":47,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/","url":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/","name":"\u201cGo blue\u201d, il Municipio illuminato di blu per l'Unicef - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif","datePublished":"2019-11-20T12:32:52+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/11\/GO-BLUE-300x87.gif","width":300,"height":87},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/11\/20\/go-blue-il-municipio-illuminato-di-blu-per-lunicef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"\u201cGo blue\u201d, il Municipio illuminato di blu per l&#8217;Unicef"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1730"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1730\/revisions"}],"predecessor-version":[{"id":1732,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1730\/revisions\/1732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1731"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}