{"id":1773,"date":"2019-12-11T09:25:00","date_gmt":"2019-12-11T08:25:00","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1773"},"modified":"2019-12-11T09:25:00","modified_gmt":"2019-12-11T08:25:00","slug":"convocazione-consiglio-comunale-lunedi-16-dicembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/","title":{"rendered":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre"},"content":{"rendered":"<p>Il Presidente del Consiglio Comunale Antonio Lecce ha disposto la convocazione della massima assise cittadina in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in prima a convocazione, per il giorno:<br \/>\n<strong>LUNEDI&#8217; 16 DICEMBRE 2019 ALLE ORE 16,30<\/strong><br \/>\ne, in caso di mancanza del numero legale, in seconda convocazione, per il giorno:<br \/>\n<strong>marted\u00ec 17 dicembre 2019 alle ore 17,00<\/strong><br \/>\nper la trattazione del seguente ordine del giorno:<\/p>\n<ol>\n<li>Comunicazione atto di G.C. n. 219 del 06.12.2019, avente ad oggetto: &#8220;Prelevamento dal fondo<br \/>\ndi -art. 166 D.Lgs. 267\/2000&#8221;<\/li>\n<li>Interrogazione presentata dal Consigliere Fabrizio Pintori, avente ad oggetto: &#8220;Definizione<br \/>\nagevolata per le entrate tributarie non riscosse tramite ingiunzioni fiscali notificate dal 2000 al<br \/>\n2017&#8221; (prot. 27233 del 30.09.2019);<\/li>\n<li>Interrogazione presentata dal Consigliere Fabrizio Pintori, avente ad oggetto: &#8220;Mancata<br \/>\ncostituzione del Comune innanzi al TAR&#8221; (prot. 32460 del 18.112019);<\/li>\n<li>Mozione presentata dal Consigliere Di Stefano Luca, riguardante le problematiche relative alla<br \/>\n&#8220;Toponomastica cittadina&#8221; (prot. 33227 del 26.11 2019);<\/li>\n<li>Mozione presentata dal Consigliere Coletta Natalino, avente ad oggetto: &#8221; Misure per il<br \/>\ncontrasto alla violenza di genere. alle discriminazioni basate sul sesso e alla valorizzazione delle<br \/>\ncompetenze delle donne&#8221; (prot. 34456 del 09.12.2019);<\/li>\n<li>Approvazione Bilancio consolidato anno 2018 \u2014 afl. 18 D.Lgs. 118\/2011;<\/li>\n<li>Disciplina per la collocazione su suolo pubblico, nonch\u00e9 su suolo privato d&#8217;uso pubblico di elementi di arredo tipo &#8220;DEHORS&#8221;, annessi a locali di pubblico esercizio di somministrazione di alimenti e bevande ed esercizi artigianali da asporto&#8221; \u2014 Approvazione nuovo Regolamento;<\/li>\n<li>Regolamento Corpo Polizia Locale come adeguato al Regolamento regionale concernente le<br \/>\nuniformi, i gradi, i segni distintivi, i veicoli e gli strumenti di autotutela delle Polizie Locali del<br \/>\nLazio con deliberazione di C.C. n. 44 del 30.07.2018 \u2014 Modifica;<\/li>\n<li>Acquisto terreno localit\u00e0 pantano;<\/li>\n<li>P.R.U.S.S.T. \u2014 Programmi di riqualificazione urbana e di sviluppo sostenibile del territorio dei Comuni del &#8220;Medio Bacino del Liri&#8221; \u2014 &#8216;Realizzazione di due edifici uso commerciale per vendita autoveicoli&#8221; in variante al P.R.G. \u2014 Ditta: Ianni Onorio Massimo Leg. Rapp. della Soc. &#8220;0&amp;0 New Auto Srl&#8221; \u2014 Ratifica Accordo di ai sensi dell&#8217;art. 34 D.Lgs. 267\/2000;<\/li>\n<li>P.R.U.S.S.T- \u2014 Programmi di riqualificazione urbana e di sviluppo sostenibile del territorio dei Comuni del &#8220;Medio Bacino del Liri&#8221; \u2014 &#8220;Rimodulazione per adeguamento funzionale per la realizzazione fabbricato commerciale monopiano&#8221; Cod. 08.44.17 \u2014 Ditta: Soc. Edilcomit Srl \u2014 Ratifica Accordo di programma ai sensi dell&#8217;art. 34 D.Lgs. 267\/2000&#8243;.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente del Consiglio Comunale Antonio Lecce ha disposto la convocazione della massima assise cittadina in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in prima a [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Presidente del Consiglio Comunale Antonio Lecce ha disposto la convocazione della massima assise cittadina in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in prima a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-11T08:25:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre\",\"datePublished\":\"2019-12-11T08:25:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/\"},\"wordCount\":368,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/\",\"name\":\"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"datePublished\":\"2019-12-11T08:25:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"width\":400,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/convocazione-consiglio-comunale-lunedi-16-dicembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora","og_description":"Il Presidente del Consiglio Comunale Antonio Lecce ha disposto la convocazione della massima assise cittadina in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in prima a [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-12-11T08:25:00+00:00","og_image":[{"width":400,"height":277,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre","datePublished":"2019-12-11T08:25:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/"},"wordCount":368,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/","url":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/","name":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","datePublished":"2019-12-11T08:25:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","width":400,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/convocazione-consiglio-comunale-lunedi-16-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio Comunale, luned\u00ec 16 dicembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1773"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1773\/revisions"}],"predecessor-version":[{"id":1774,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1773\/revisions\/1774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}