{"id":1775,"date":"2019-12-11T09:40:20","date_gmt":"2019-12-11T08:40:20","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1775"},"modified":"2019-12-11T09:40:20","modified_gmt":"2019-12-11T08:40:20","slug":"giovedi-12-dicembre-laboratori-natalizi-in-biblioteca","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/","title":{"rendered":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca"},"content":{"rendered":"<p><strong>Gioved\u00ec 12 DICEMBRE alle ore 16.00 presso la\u00a0 Biblioteca comunale<\/strong> si terranno i\u00a0LABORATORI NATALIZI PER BAMBINI a cura degli operatori bibliotecari dedicati ai bambini di et\u00e0 compresa tra i 4 e gli 8 anni. L&#8217; attivit\u00e0 prevede una lettura animata e la realizzazione di lavoretti di tema natalizio con materiali di riciclo, materiali naturali, colori naturali, con l\u2019abbattimento dell\u2019uso della plastica.<\/p>\n<p>I posti sono limitati, pertanto, per partecipare al laboratorio \u00e8 necessario prenotare contattando le operatrici allo <strong>0776828301<\/strong> o inviando una mail all\u2019indirizzo <strong>biblio.sora@comune.sora.fr.it.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 12 DICEMBRE alle ore 16.00 presso la\u00a0 Biblioteca comunale si terranno i\u00a0LABORATORI NATALIZI PER BAMBINI a cura degli operatori bibliotecari dedicati ai bambini di et\u00e0 compresa tra i 4 [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 12 DICEMBRE alle ore 16.00 presso la\u00a0 Biblioteca comunale si terranno i\u00a0LABORATORI NATALIZI PER BAMBINI a cura degli operatori bibliotecari dedicati ai bambini di et\u00e0 compresa tra i 4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-11T08:40:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca\",\"datePublished\":\"2019-12-11T08:40:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/\"},\"wordCount\":93,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/biblioteca-150x150.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/\",\"name\":\"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/biblioteca-150x150.jpg\",\"datePublished\":\"2019-12-11T08:40:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/biblioteca-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/04\\\/biblioteca-150x150.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2019\\\/12\\\/11\\\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/","og_locale":"it_IT","og_type":"article","og_title":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora","og_description":"Gioved\u00ec 12 DICEMBRE alle ore 16.00 presso la\u00a0 Biblioteca comunale si terranno i\u00a0LABORATORI NATALIZI PER BAMBINI a cura degli operatori bibliotecari dedicati ai bambini di et\u00e0 compresa tra i 4 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-12-11T08:40:20+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca","datePublished":"2019-12-11T08:40:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/"},"wordCount":93,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/","url":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/","name":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg","datePublished":"2019-12-11T08:40:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/04\/biblioteca-150x150.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2019\/12\/11\/giovedi-12-dicembre-laboratori-natalizi-in-biblioteca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Gioved\u00ec 12 dicembre Laboratori Natalizi in Biblioteca"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1775"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1775\/revisions"}],"predecessor-version":[{"id":1776,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1775\/revisions\/1776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1372"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}