{"id":1818,"date":"2020-03-06T14:30:06","date_gmt":"2020-03-06T13:30:06","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1818"},"modified":"2020-03-06T14:30:06","modified_gmt":"2020-03-06T13:30:06","slug":"uffici-comunali-si-consiglia-di-limitare-gli-accessi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/","title":{"rendered":"Uffici comunali, si consiglia di limitare gli accessi"},"content":{"rendered":"<p>Per la miglior tutela della cittadinanza e a titolo esclusivamente precauzionale, <strong>si suggerisce di limitare l&#8217;accesso degli uffici comunali<\/strong> ai casi effettivamente improcrastinabili, privilegiano la comunicazione telefonica o a mezzo mail.<\/p>\n<p>L\u2019<strong>Ufficio Relazioni con il Pubblico <\/strong>\u00e8 a disposizione per qualsiasi informazione ai seguenti contatti<strong>:<\/strong><\/p>\n<ul>\n<li>tel 0776828219<\/li>\n<li>mail <a href=\"mailto:urp@comune.sora.fr.it\">urp@comune.sora.fr.it<\/a><\/li>\n<\/ul>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Per la miglior tutela della cittadinanza e a titolo esclusivamente precauzionale, si suggerisce di limitare l&#8217;accesso degli uffici comunali ai casi effettivamente improcrastinabili, privilegiano la comunicazione telefonica o a mezzo [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-1818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uffici comunali, si consiglia di limitare gli accessi - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uffici comunali, si consiglia di limitare gli accessi - Sora\" \/>\n<meta property=\"og:description\" content=\"Per la miglior tutela della cittadinanza e a titolo esclusivamente precauzionale, si suggerisce di limitare l&#8217;accesso degli uffici comunali ai casi effettivamente improcrastinabili, privilegiano la comunicazione telefonica o a mezzo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T13:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"327\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Uffici comunali, si consiglia di limitare gli accessi\",\"datePublished\":\"2020-03-06T13:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/\"},\"wordCount\":60,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/municipio-1.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/\",\"name\":\"Uffici comunali, si consiglia di limitare gli accessi - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/municipio-1.jpg\",\"datePublished\":\"2020-03-06T13:30:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/municipio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2019\\\/10\\\/municipio-1.jpg\",\"width\":327,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/06\\\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uffici comunali, si consiglia di limitare gli accessi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uffici comunali, si consiglia di limitare gli accessi - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/","og_locale":"it_IT","og_type":"article","og_title":"Uffici comunali, si consiglia di limitare gli accessi - Sora","og_description":"Per la miglior tutela della cittadinanza e a titolo esclusivamente precauzionale, si suggerisce di limitare l&#8217;accesso degli uffici comunali ai casi effettivamente improcrastinabili, privilegiano la comunicazione telefonica o a mezzo [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-06T13:30:06+00:00","og_image":[{"width":327,"height":514,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Uffici comunali, si consiglia di limitare gli accessi","datePublished":"2020-03-06T13:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/"},"wordCount":60,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/","url":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/","name":"Uffici comunali, si consiglia di limitare gli accessi - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg","datePublished":"2020-03-06T13:30:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2019\/10\/municipio-1.jpg","width":327,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/06\/uffici-comunali-si-consiglia-di-limitare-gli-accessi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Uffici comunali, si consiglia di limitare gli accessi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1818"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1818\/revisions"}],"predecessor-version":[{"id":1819,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1818\/revisions\/1819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1668"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}