{"id":1822,"date":"2020-03-10T17:36:12","date_gmt":"2020-03-10T16:36:12","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1822"},"modified":"2020-03-10T17:36:12","modified_gmt":"2020-03-10T16:36:12","slug":"emergenza-coronavirus-le-disposizioni-del-sindaco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/","title":{"rendered":"Emergenza Coronavirus, le disposizioni del Sindaco"},"content":{"rendered":"<p><span style=\"color: #008000\"><strong>\u00a0&#8211; TRIBUTI COMUNALI &#8211;\u00a0<\/strong><\/span><\/p>\n<p>E\u2019 in via elaborazione il provvedimento per la sospensione a far data da oggi 10 marzo 2020 e fino al 3 aprile e salvo ulteriori misure governative, delle attivit\u00e0 istruttorie e del versamento relativo ai tributi comunali.<\/p>\n<p><span style=\"color: #800000\"><strong>\u00a0&#8211; PIANIFICAZIONE E GESTIONE DEL TERRITORIO &#8211;\u00a0<\/strong><\/span><!--more--><\/p>\n<p>E\u2019 sospesa l\u2019attivit\u00e0 di ricevimento degli utenti e dei professionisti, tuttavia le eventuali istanze possono essere trasmesse all\u2019Ente attraverso la pec <a href=\"mailto:comunesora@pec.it\">comunesora@pec.it<\/a>, precisando l\u2019oggetto e il servizio a cui sono destinate.<\/p>\n<p>Non subir\u00e0 interruzioni, invece, l\u2019attivit\u00e0 dell\u2019Ufficio di Vigilanza che si svolger\u00e0 con l\u2019adozione delle opportune e necessarie precauzioni.<\/p>\n<p>Tutte le sedi comunali, compreso il Cimitero, sono state dotate di appositi dispencer disinfettanti e sono stati delimitati gli spazi per la tutela del lavoratore e dell\u2019utenza, come prescritto dai vari decreti. Inoltre, tutti gli edifici comunali, saranno oggetto di operazione di sanificazione nei prossimi giorni. Per quanto concerne le scuole si stanno completando le operazione di distribuzione dei dispencer disinfettanti.<\/p>\n<p><strong>\u00a0<span style=\"color: #000080\">&#8211; SERVIZI SOCIALI &#8211;\u00a0<\/span><\/strong><\/p>\n<p>E\u2019 attivo il servizio <strong>\u201cspesa a domicilio\u201d<\/strong> organizzato dall\u2019Assessorato ai Servizi Sociali.<\/p>\n<p>Categorie interessate:<\/p>\n<ul>\n<li>Persone anziane over 70 che vivono da sole o con problemi di deambulazione<\/li>\n<li>Persone affette da malattie croniche invalidanti o immunodepresse adeguatamente certificate<\/li>\n<li>In quarantena<\/li>\n<\/ul>\n<p><strong>possono richiedere il servizio<\/strong> telefonando allo <strong>0776828036<\/strong>, a questo numero risponderanno\u00a0 gli assistenti sociali del comune che organizzeranno <strong>\u201cla spesa a domicilio\u201d<\/strong>.<\/p>\n<p>In maniera istituzionale\u00a0 ed\u00a0 esclusiva, per evitare eventuali fraintendimenti o truffe,\u00a0 \u00e8 necessario chiarire che questa iniziativa \u00e8 attuata dal Comune mediante\u00a0 <strong>l\u2019Ufficio dei Servizi Sociali<\/strong>.<\/p>\n<p><strong>Ribadiamo che solo il Comune pu\u00f2 erogare questo servizio.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><span style=\"color: #ff0000\"><strong>\u00a0&#8211; ATTIVITA\u2019 PRODUTTIVE &#8211;\u00a0<\/strong><\/span><\/p>\n<p><strong>Si richiama integralmente quanto prescritto dal DCPM 9 marzo 2020<\/strong><\/p>\n<ul>\n<li><strong>Ristoranti e bar<\/strong><\/li>\n<\/ul>\n<p>Sono consentite le attivit\u00e0 di ristorazione e bar dalle ore 6.00 alle ore 18.00, con obbligo, a carico del gestore, di predisporre le condizioni per garantire la possibilit\u00e0 del rispetto della distanza di sicurezza interpersonale di almeno un metro. In caso di violazione, la sanzione prevista \u00e8 la sospensione dell&#8217;attivit\u00e0. Sono consentite le attivit\u00e0 commerciali diverse da ristorazione e bar a condizione che il gestore garantisca un accesso con modalit\u00e0 contingentate o comunque idonee a evitare assembramenti di persone, tenuto conto delle dimensioni e delle caratteristiche dei locali aperti al pubblico, e tali da garantire ai frequentatori la possibilit\u00e0 di rispettare la distanza di almeno un metro tra i visitatori. In caso di violazione, la sanzione prevista \u00e8 la sospensione dell&#8217;attivit\u00e0. In presenza di condizioni strutturali o organizzative che non consentano il rispetto della distanza di sicurezza interpersonale di un metro, tali attivit\u00e0 dovranno essere chiuse.<\/p>\n<ul>\n<li><strong>Medie e gradi strutture di vendita nei festivi e prefestivi <u>(eccetto farmacie, para farmacie e punti vendita generi alimentari\u00b0)<\/u><\/strong><\/li>\n<\/ul>\n<p>Nelle giornate festive e prefestive sono chiuse le medie e grandi strutture di vendita, nonch\u00e9 gli esercizi commerciali presenti all&#8217;interno dei centri commerciali e dei mercati. Nei giorni feriali, il gestore deve comunque predisporre le condizioni per garantire la possibilit\u00e0 del rispetto della distanza di sicurezza interpersonale di un metro. La sanzione prevista per il mancato rispetto \u00e8 la sospensione dell&#8217;attivit\u00e0. In presenza di condizioni strutturali o organizzative che non consentano il rispetto della distanza di sicurezza interpersonale di un metro, tali strutture dovranno essere chiuse. La chiusura non \u00e8 disposta per farmacie, parafarmacie e punti vendita di generi alimentari, il cui gestore \u00e8 comunque sempre chiamato a garantire il rispetto della distanza di sicurezza interpersonale di un metro, pena la sospensione dell&#8217;attivit\u00e0 in caso di violazione.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Si ribadisce che per una corretta, univoca\u00a0 ed efficacie informazione alla cittadinanza \u00e8 stato deciso di diramare quotidianamente alle ore 12.00 circa, salvo il sopraggiungere di nuove circostanze, un bollettino riepilogativo della situazione e degli eventuali provvedimenti adottati e\/o da adottare. Pertanto, si invita la cittadinanza a seguire i canali ufficiali: sito web istituzionale, pagina facebook del Comune di Sora e la sezione \u201cemergenze\u201d dell\u2019app Comunicacity<\/strong><\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>\u00a0&#8211; TRIBUTI COMUNALI &#8211;\u00a0 E\u2019 in via elaborazione il provvedimento per la sospensione a far data da oggi 10 marzo 2020 e fino al 3 aprile e salvo ulteriori misure [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-1822","post","type-post","status-publish","format-standard","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergenza Coronavirus, le disposizioni del Sindaco - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza Coronavirus, le disposizioni del Sindaco - Sora\" \/>\n<meta property=\"og:description\" content=\"\u00a0&#8211; TRIBUTI COMUNALI &#8211;\u00a0 E\u2019 in via elaborazione il provvedimento per la sospensione a far data da oggi 10 marzo 2020 e fino al 3 aprile e salvo ulteriori misure [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T16:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Emergenza Coronavirus, le disposizioni del Sindaco\",\"datePublished\":\"2020-03-10T16:36:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/\"},\"wordCount\":635,\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/\",\"name\":\"Emergenza Coronavirus, le disposizioni del Sindaco - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"datePublished\":\"2020-03-10T16:36:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/10\\\/emergenza-coronavirus-le-disposizioni-del-sindaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergenza Coronavirus, le disposizioni del Sindaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergenza Coronavirus, le disposizioni del Sindaco - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza Coronavirus, le disposizioni del Sindaco - Sora","og_description":"\u00a0&#8211; TRIBUTI COMUNALI &#8211;\u00a0 E\u2019 in via elaborazione il provvedimento per la sospensione a far data da oggi 10 marzo 2020 e fino al 3 aprile e salvo ulteriori misure [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-10T16:36:12+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sora\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png","height":600,"width":1200,"type":""}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Emergenza Coronavirus, le disposizioni del Sindaco","datePublished":"2020-03-10T16:36:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/"},"wordCount":635,"articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/","url":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/","name":"Emergenza Coronavirus, le disposizioni del Sindaco - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"datePublished":"2020-03-10T16:36:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/10\/emergenza-coronavirus-le-disposizioni-del-sindaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Emergenza Coronavirus, le disposizioni del Sindaco"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1822"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1822\/revisions"}],"predecessor-version":[{"id":1823,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1822\/revisions\/1823"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}