{"id":1865,"date":"2020-03-20T13:57:56","date_gmt":"2020-03-20T12:57:56","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1865"},"modified":"2020-03-20T13:57:56","modified_gmt":"2020-03-20T12:57:56","slug":"opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/","title":{"rendered":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0."},"content":{"rendered":"<p>E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente<br \/>\nL\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-1865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora\" \/>\n<meta property=\"og:description\" content=\"E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T12:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0.\",\"datePublished\":\"2020-03-20T12:57:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/\"},\"wordCount\":293,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/sanificazione.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/\",\"name\":\"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/sanificazione.jpg\",\"datePublished\":\"2020-03-20T12:57:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/sanificazione.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/sanificazione.jpg\",\"width\":744,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/03\\\/20\\\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/","og_locale":"it_IT","og_type":"article","og_title":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora","og_description":"E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-20T12:57:56+00:00","og_image":[{"width":744,"height":744,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0.","datePublished":"2020-03-20T12:57:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/"},"wordCount":293,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/","url":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/","name":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0. - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg","datePublished":"2020-03-20T12:57:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/sanificazione.jpg","width":744,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/03\/20\/opera-di-sanificazione-e-in-via-di-organizzazione-una-seconda-fase-di-sanificazione-delle-strade-e-dei-vicoli-della-citta-in-collaborazione-con-la-coldiretti-e-unopportunit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"OPERA DI SANIFICAZIONE E\u2019 in via di organizzazione una seconda fase di sanificazione delle strade e dei vicoli della Citt\u00e0 in collaborazione con la Coldiretti. E\u2019 un\u2019opportunit\u00e0 resa disponibile dalla Prefettura. La Coldiretti mette a disposizione trattori e nebulizzatori chiedendo solo la copertura economica di carburante e prodotti sanificanti. Nei prossimi giorni verranno dunque nuovamente sanificate le vie cittadine in stretta collaborazione tra Coldiretti e societ\u00e0 Ambiente L\u2019azione sanificatrice dei mastelli della differenziata annunciata per gioved\u00ec 19 marzo ha subito ritardi a causa di malfunzionamento del nebulizzatore e a causa di rallentamenti di reperimento da parte della soc. Ambiente di Ipoclorito di sodio. Nella notte tra il 20 e il 21 marzo si provveder\u00e0 alla sanificazione dei mastelli. Si partir\u00e0 da via Marsicana, via Pontrinio, via Roma, via Torino, via Borgo S. Nicola, p.zza Risorgimento, via Conte Canofari e poi a seguire tutte le altre zone della Citt\u00e0."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1865"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1865\/revisions"}],"predecessor-version":[{"id":1867,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1865\/revisions\/1867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1866"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}