{"id":1969,"date":"2020-05-04T17:46:36","date_gmt":"2020-05-04T15:46:36","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1969"},"modified":"2020-05-04T17:46:36","modified_gmt":"2020-05-04T15:46:36","slug":"apertura-cimitero-comunale-lordinanza-del-sindaco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/","title":{"rendered":"Apertura Cimitero Comunale, l&#8217;ordinanza del Sindaco"},"content":{"rendered":"<p>Con ordinanza sindacale n. 598 del 04\/05\/2020 il Primo Cittadino ha stabilito:<\/p>\n<ol>\n<li>La riapertura del Cimitero Comunale dal <strong>05.2020<\/strong> tutti i giorni inclusi i festivi nella seguente fascia oraria:<\/li>\n<\/ol>\n<p><strong>dalle ore 8.00 alle ore 13.00<\/strong><\/p>\n<p><strong>dalle ore 14.30 alle ore 18.00<\/strong><\/p>\n<ol start=\"2\">\n<li>L\u2019accesso al Cimitero per garantire la sicurezza ai cittadini e il controllo degli ingressi, \u00e8 consentito solo attraverso l\u2019ingresso principale;<\/li>\n<li>l\u2019apertura alle imprese per lavori edili, previa autorizzazione,\u00a0 dal luned\u00ec al venerd\u00ec dalle ore 8.00 alle ore 17.30;<\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><strong>ALLE SEGUENTI CONDIZIONI<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Per l\u2019accesso al Cimitero Comunale :<\/strong><\/p>\n<ul>\n<li>si potr\u00e0 avere accesso al luogo sacro esclusivamente attraverso l\u2019ingresso principale, rimanendo inibiti gli altri accessi di servizio, salvo che per mezzi di emergenza e sanitari;<\/li>\n<li>l\u2019accesso \u00e8 contingentato all\u2019ingresso, dove sar\u00e0 consentita la frequentazione contemporanea per un numero massimo <strong><u>pari a 20 visitatori<\/u><\/strong>,avvicendate dal personale preposto;<\/li>\n<li>ai cittadini impossibilitati alla mobilit\u00e0 autonoma, \u00e8 consentito l\u2019accesso con un accompagnatore;<\/li>\n<li>\u00c8 <strong><u>obbligatorio<\/u><\/strong> indossare la mascherina protettiva eccetto soggetti con forme di disabilit\u00e0 non compatibili con l\u2019uso continuativo della stessa e bambini di et\u00e0 inferiore ai 6 anni, nel rispetto di ogni altra misura di sicurezza sanitaria delle intervenute disposizioni di legge;<\/li>\n<li>La permanenza all\u2019interno \u00e8 consentita per un massimo di <strong>20 minuti, <\/strong>salvo deroghe legate alla impossibilit\u00e0 di poter svolgere le debite azioni nei tempi prescritti;<\/li>\n<li>\u00e8 fatto <strong><u>obbligo<\/u><\/strong> ai visitatori di osservare <strong>la distanza minima di metri 1 (uno) da altre persone<\/strong>;<\/li>\n<li><strong>\u00e8 vietato l\u2019assembramento<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>DISPONE <\/strong><\/p>\n<p>Per ogni altra attivit\u00e0 relativa a OPERAZIONI di TUMULAZIONE e\/o ESTUMULAZIONE e celebrazioni delle cerimonie funebri si rimanda a quanto prescritto dal DPCM del 26 aprile 2020, quali norme inderogabili.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Con ordinanza sindacale n. 598 del 04\/05\/2020 il Primo Cittadino ha stabilito: La riapertura del Cimitero Comunale dal 05.2020 tutti i giorni inclusi i festivi nella seguente fascia oraria: dalle [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-1969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apertura Cimitero Comunale, l&#039;ordinanza del Sindaco - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apertura Cimitero Comunale, l&#039;ordinanza del Sindaco - Sora\" \/>\n<meta property=\"og:description\" content=\"Con ordinanza sindacale n. 598 del 04\/05\/2020 il Primo Cittadino ha stabilito: La riapertura del Cimitero Comunale dal 05.2020 tutti i giorni inclusi i festivi nella seguente fascia oraria: dalle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T15:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"213\" \/>\n\t<meta property=\"og:image:height\" content=\"236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Apertura Cimitero Comunale, l&#8217;ordinanza del Sindaco\",\"datePublished\":\"2020-05-04T15:46:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/\"},\"wordCount\":261,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/\",\"name\":\"Apertura Cimitero Comunale, l'ordinanza del Sindaco - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"datePublished\":\"2020-05-04T15:46:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"width\":213,\"height\":236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/04\\\/apertura-cimitero-comunale-lordinanza-del-sindaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apertura Cimitero Comunale, l&#8217;ordinanza del Sindaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apertura Cimitero Comunale, l'ordinanza del Sindaco - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/","og_locale":"it_IT","og_type":"article","og_title":"Apertura Cimitero Comunale, l'ordinanza del Sindaco - Sora","og_description":"Con ordinanza sindacale n. 598 del 04\/05\/2020 il Primo Cittadino ha stabilito: La riapertura del Cimitero Comunale dal 05.2020 tutti i giorni inclusi i festivi nella seguente fascia oraria: dalle [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-04T15:46:36+00:00","og_image":[{"width":213,"height":236,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Apertura Cimitero Comunale, l&#8217;ordinanza del Sindaco","datePublished":"2020-05-04T15:46:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/"},"wordCount":261,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/","url":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/","name":"Apertura Cimitero Comunale, l'ordinanza del Sindaco - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","datePublished":"2020-05-04T15:46:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","width":213,"height":236},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/04\/apertura-cimitero-comunale-lordinanza-del-sindaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Apertura Cimitero Comunale, l&#8217;ordinanza del Sindaco"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1969"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1969\/revisions"}],"predecessor-version":[{"id":1970,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1969\/revisions\/1970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1871"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}