{"id":1973,"date":"2020-05-11T16:16:34","date_gmt":"2020-05-11T14:16:34","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1973"},"modified":"2020-05-11T18:09:47","modified_gmt":"2020-05-11T16:09:47","slug":"giovedi-14-maggio-interruzione-energia-elettrica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/","title":{"rendered":"Gioved\u00ec 14 maggio, interruzione energia elettrica"},"content":{"rendered":"<p>e-distribuzione comunica che <strong>gioved\u00ec 14 maggio dalle ore 10.00 alle ore 16.30<\/strong> si verificher\u00e0 <strong>un&#8217;interruzione dell&#8217;energia elettrica<\/strong> per effettuare lavori sugli impianti.<\/p>\n<p><strong>Le vie interessate (intervalli dei civici &#8220;da &#8220;a&#8221; raggruppati per pari e\/o dispari) sono<\/strong>:<\/p>\n<ul>\n<li>via U. Carrara da 8 a 10, da 14 a 16, 20,da 24 a 26<\/li>\n<li>p.zza A. La Rocca 4, da 8 a 8a, da 22 a 26<\/li>\n<li>via V. Emanuele III 26, da 30 a 36, 40<\/li>\n<li>via F. Loffreda, 12, da 16a a 20, 30<\/li>\n<li>via U. Carrara da 9a a 15, 41, snc, snc<\/li>\n<li>via F. Loffreda \u00a03, 11, da 17 a 19<\/li>\n<li>via V. Emanuele III da 47 a 47a<\/li>\n<li>vicolo Tuzi da 3 a 5, da 5b a7<\/li>\n<li>p.zza S. Restituta da 10 a 14<\/li>\n<li>via Quinto Valerio da 2 a 14<\/li>\n<li>Corso Volsci 70, da 74 a 76<\/li>\n<li>vicolo Tuzi 10, da 16 a 18<\/li>\n<li>Lungoliri Mazzini 27, 33<\/li>\n<li>p.zza A. La Rocca a. 2, snc<\/li>\n<li>via V. Emanuele III snc<\/li>\n<li>Lungoliri Mazzini snc<\/li>\n<li>p.zza A. La Rocca 1\/2, 7<\/li>\n<li>via Quinto Valerio 1<\/li>\n<li>p.zza S. Restituta snc<\/li>\n<li>p.zza A. La Rocca 5<\/li>\n<li>p.zza A. La Rocca snc<\/li>\n<li>Corso Volsci 95, 99<\/li>\n<li>p.zza Maier Ross 5<\/li>\n<li>via F. Loffreda \u00a0snc<\/li>\n<li>Corso Volsci, snc<\/li>\n<li>via Tuzi 15<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>e-distribuzione comunica che gioved\u00ec 14 maggio dalle ore 10.00 alle ore 16.30 si verificher\u00e0 un&#8217;interruzione dell&#8217;energia elettrica per effettuare lavori sugli impianti. Le vie interessate (intervalli dei civici &#8220;da &#8220;a&#8221; [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora\" \/>\n<meta property=\"og:description\" content=\"e-distribuzione comunica che gioved\u00ec 14 maggio dalle ore 10.00 alle ore 16.30 si verificher\u00e0 un&#8217;interruzione dell&#8217;energia elettrica per effettuare lavori sugli impianti. Le vie interessate (intervalli dei civici &#8220;da &#8220;a&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-11T14:16:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-11T16:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"1755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Gioved\u00ec 14 maggio, interruzione energia elettrica\",\"datePublished\":\"2020-05-11T14:16:34+00:00\",\"dateModified\":\"2020-05-11T16:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/\"},\"wordCount\":172,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/05\\\/interruzione-energia-14-maggio_page-0001-1.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/\",\"name\":\"Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/05\\\/interruzione-energia-14-maggio_page-0001-1.jpg\",\"datePublished\":\"2020-05-11T14:16:34+00:00\",\"dateModified\":\"2020-05-11T16:09:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/05\\\/interruzione-energia-14-maggio_page-0001-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/05\\\/interruzione-energia-14-maggio_page-0001-1.jpg\",\"width\":1241,\"height\":1755},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/11\\\/giovedi-14-maggio-interruzione-energia-elettrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gioved\u00ec 14 maggio, interruzione energia elettrica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/","og_locale":"it_IT","og_type":"article","og_title":"Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora","og_description":"e-distribuzione comunica che gioved\u00ec 14 maggio dalle ore 10.00 alle ore 16.30 si verificher\u00e0 un&#8217;interruzione dell&#8217;energia elettrica per effettuare lavori sugli impianti. Le vie interessate (intervalli dei civici &#8220;da &#8220;a&#8221; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-11T14:16:34+00:00","article_modified_time":"2020-05-11T16:09:47+00:00","og_image":[{"width":1241,"height":1755,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Gioved\u00ec 14 maggio, interruzione energia elettrica","datePublished":"2020-05-11T14:16:34+00:00","dateModified":"2020-05-11T16:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/"},"wordCount":172,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/","url":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/","name":"Gioved\u00ec 14 maggio, interruzione energia elettrica - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg","datePublished":"2020-05-11T14:16:34+00:00","dateModified":"2020-05-11T16:09:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/05\/interruzione-energia-14-maggio_page-0001-1.jpg","width":1241,"height":1755},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/11\/giovedi-14-maggio-interruzione-energia-elettrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Gioved\u00ec 14 maggio, interruzione energia elettrica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1973"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1973\/revisions"}],"predecessor-version":[{"id":1977,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1973\/revisions\/1977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1974"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}