{"id":1991,"date":"2020-05-17T22:19:08","date_gmt":"2020-05-17T20:19:08","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=1991"},"modified":"2020-05-17T22:19:52","modified_gmt":"2020-05-17T20:19:52","slug":"emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/","title":{"rendered":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#8217;"},"content":{"rendered":"<p>UFFICI COMUNALI<\/p>\n<p>Con il prosieguo della fase 2, anche l\u2019accesso al Comune da parte dei cittadini avverr\u00e0 in piena sicurezza. A tal fine si rende necessaria la comunicazione di tutte le indispensabili misure prese a difesa e tutela della salute sia dei cittadini che dei dipendenti.<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udc65<\/span><\/span>1. Tutti i cittadini dovranno munirsi dei dispositivi di sicurezza (mascherine e guanti)<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udcd1<\/span><\/span>2. Tutti gli uffici ricevono il pubblico esclusivamente previo appuntamento da concordare telefonando o inviando una mail. I numeri e gli indirizzi sono pubblicati nella sezione \u201ccontatti\u201d del sito\u00a0<a href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.comune.sora.fr%2F%3Ffbclid%3DIwAR3CRX78vBHQLCbktQyXA9OTn5SE81E5aAn3NtOxe0RX_Mrdg5TtjKqYU3E&amp;h=AT1H53TAQI8bzozagZvpkUCNGcMvq-AmANdVH96N87WThVZlqESZMrsxyjGV-753BWJHdevnaQFAK7wTPYz3unEf4nfo-4wspcL2Awr2D-jKfkTnbXFz4PMxHNFggx3yUOg2dukBcePHuDMQemBRCz47BDdSmkKP2THvG00y_YqHSyuzCewDrIkGAeQF0h_AwFZaOKRaOHzXAfaUsT9VWYlkCxdPi37F4B6uURNFhSQzCjapI5JJOvIIVkUCjYwljQudAp881zzHlnkIcWkhczB5yvwZTz6jq80pq1LQfecx4EOaSg5eqkd1yWUjH7tJNQoqPX_O5UCeHXDKkLBTxTL3ScAvamLLRrIB4VCT68pLAilnoCb6iYL0XPuR5-laqXfPSEuWIYNieANaD9Hhd14moyY07AjSl708pX_tMMqQc-hLh61O__oavWtRbLkJHNNA88lZtykWibhFoEN1qvfBz_jvANKhFPa4sZwnI0A4NuW6ZXA1SRHP5qoXwAgjB63IIqYu6SxNAW_9lqmFiyIZAw8MP2GYI7ONuG2xZQ6mHbD5iJwj-_JHqczW2GJydLYxnZwPx2vyCdInIXr7RL0dXgLY29ENdQuwguFLgWdQDt8Q_225boNC_qgt\" target=\"_blank\" rel=\"noopener nofollow noreferrer\" data-ft=\"{&quot;tn&quot;:&quot;-U&quot;}\" data-lynx-mode=\"async\">www.comune.sora.fr.<\/a><br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\uddde\ufe0f<\/span><\/span>3. La posta o altra documentazione in arrivo, pu\u00f2 essere depositata presso l\u2019Ufficio Protocollo dell\u2019Ente sito all\u2019ingresso del palazzo Municipale senza prendere appuntamento.<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udcc3<\/span><\/span>4. Il ritiro gli atti (es. atti giudiziari, ecc) per i quali non \u00e8 possibile l\u2019invio tramite mail o pec, deve avvenire concordando un appuntamento con gli uffici competenti ovvero contattando l\u2019Ufficio Relazioni con il Pubblico<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udd1c<\/span><\/span>5. Le segnalazioni dei disservizi (lampioni spenti, buche sul manto stradale, ecc\u2026), devono essere inoltrate al servizio delle manutenzioni contattando il 0776828627 scrivendo una mail a serviziomanutenzione@comune.sora.fr.it<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udcbb<\/span><\/span>6. Per conoscere lo stato di un\u2019istanza o di una richiesta inoltrata agli uffici o servizi del Comune \u00e8 possibile contattare telefonicamente o attraverso una mail i responsabili dei procedimenti che rilasceranno le informazioni necessarie.<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\u270d\ufe0f<\/span><\/span>7. Per qualsiasi informazione \u00e8 disponibile l\u2019Ufficio Relazioni con il Pubblico al tel 0776828219 o all\u2019indirizzo mail urp@comune.sora.fr.it dal luned\u00ec al venerd\u00ec dalle ore 8.00 alle 14.00 e il luned\u00ec e gioved\u00ec dalle ore 15.00 alle ore 17.00.<\/p>\n<p><span class=\"_5mfr\"><span class=\"_6qdm\">\ud83c\udf33<\/span><\/span>RIAPERTURE PARCHI COMUNALI<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83c\udf33<\/span><\/span><br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83c\udf3f<\/span><\/span>Mercoled\u00ec 20 maggio sar\u00e0 riaperto il Parco \u201cS. Chiara\u201d<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83c\udf40<\/span><\/span>Lunedi 25 maggio sar\u00e0 riaperto il Parco \u201cA. Valente\u201d<\/p>\n<p><span class=\"_5mfr\"><span class=\"_6qdm\">\u27a1\ufe0f<\/span><\/span>ORARI DI APERTURA E CHIUSURA DELLE ATTIVITA\u2019 COMMERCIALI\u00a0<span class=\"_5mfr\"><span class=\"_6qdm\">\u2b05\ufe0f<\/span><\/span><br \/>\n\u2022 Esercizi di vicinato alimentare e non alimentare dalle ore 6.00 alle ore 21.30<br \/>\n\u2022 Medie e grandi strutture di vendita, centri commerciali dalle ore 6.00 alle ore 21.30<br \/>\n\u2022 Tabaccherie dalle ore 6.00 alle ore 21.30<br \/>\n\u2022 Attivit\u00e0 di somministrazione di alimenti e bevande, comprese le attivit\u00e0 artigianali, sul posto e per asporto (bar, ristoranti, paninerie, rosticcerie, piadinerie) dalle ore 6.00 alle ore 24.00<br \/>\n\u2022 Attivit\u00e0 di cura della persona (estetisti, parrucchieri) dalle ore 6.00 alle ore 21.30<br \/>\nL\u2019evolversi della situazione epidemiologica ed il carattere particolarmente diffuso dell\u2019epidemia che ha interessato il territorio del Comune di Sora rende necessario adottare provvedimenti che riducano la possibilit\u00e0 di creare assembramenti nei luoghi pubblici e privati durante il periodo di vigenza delle misure di contenimento del COVID-19 pertanto:<\/p>\n<p><span class=\"_5mfr\"><span class=\"_6qdm\">\u26d4<\/span><\/span>\u2022 E\u2019 sospeso, presso gli esercizi di somministrazione di alimenti e bevande, lo svolgimento di esecuzioni musicali, piccoli intrattenimenti e trattenimenti danzanti ed eventi comunque denominanti .<br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\u26d4<\/span><\/span>\u2022 Sono sospese tutte le manifestazioni e gli eventi pubblici, commerciali, fieristici, legati alle festivit\u00e0 e alle tradizioni del territorio<\/p>\n<p><span class=\"_5mfr\"><span class=\"_6qdm\">\ud83e\uddc0<\/span><\/span>MERCATO SETTIMANALE\u00a0<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83e\udd69<\/span><\/span><br \/>\n<span class=\"_5mfr\"><span class=\"_6qdm\">\ud83d\udd1c<\/span><\/span>Gioved\u00ec 21 maggio 2020 riprender\u00e0 il mercato settimanale solo per i banchi alimentari e vivaisti<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>UFFICI COMUNALI Con il prosieguo della fase 2, anche l\u2019accesso al Comune da parte dei cittadini avverr\u00e0 in piena sicurezza. A tal fine si rende necessaria la comunicazione di tutte [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":98,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-1991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#039; - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#039; - Sora\" \/>\n<meta property=\"og:description\" content=\"UFFICI COMUNALI Con il prosieguo della fase 2, anche l\u2019accesso al Comune da parte dei cittadini avverr\u00e0 in piena sicurezza. A tal fine si rende necessaria la comunicazione di tutte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-17T20:19:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T20:19:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#8217;\",\"datePublished\":\"2020-05-17T20:19:08+00:00\",\"dateModified\":\"2020-05-17T20:19:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/\"},\"wordCount\":460,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/IconaAvviso_1.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/\",\"name\":\"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA' - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/IconaAvviso_1.jpg\",\"datePublished\":\"2020-05-17T20:19:08+00:00\",\"dateModified\":\"2020-05-17T20:19:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/IconaAvviso_1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/02\\\/IconaAvviso_1.jpg\",\"width\":310,\"height\":328},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/05\\\/17\\\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA' - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/","og_locale":"it_IT","og_type":"article","og_title":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA' - Sora","og_description":"UFFICI COMUNALI Con il prosieguo della fase 2, anche l\u2019accesso al Comune da parte dei cittadini avverr\u00e0 in piena sicurezza. A tal fine si rende necessaria la comunicazione di tutte [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-17T20:19:08+00:00","article_modified_time":"2020-05-17T20:19:52+00:00","og_image":[{"width":310,"height":328,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#8217;","datePublished":"2020-05-17T20:19:08+00:00","dateModified":"2020-05-17T20:19:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/"},"wordCount":460,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/","url":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/","name":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA' - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg","datePublished":"2020-05-17T20:19:08+00:00","dateModified":"2020-05-17T20:19:52+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/02\/IconaAvviso_1.jpg","width":310,"height":328},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/05\/17\/emergenza-covid-19-le-nuove-regole-dal-18-maggio-per-la-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"EMERGENZA COVID 19, LE NUOVE REGOLE DAL 18 MAGGIO PER LA CITTA&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=1991"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1991\/revisions"}],"predecessor-version":[{"id":1993,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/1991\/revisions\/1993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/98"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=1991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=1991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}