{"id":2024,"date":"2020-06-04T17:05:46","date_gmt":"2020-06-04T15:05:46","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2024"},"modified":"2020-06-04T17:05:46","modified_gmt":"2020-06-04T15:05:46","slug":"allerta-meteo-attivato-il-centro-operativo-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/","title":{"rendered":"Allerta meteo, attivato il Centro Operativo Comunale"},"content":{"rendered":"<p><strong>Il Sindaco Roberto De Donatis, con ordinanza del 04\/06\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.)<\/strong>, a partire dalle ore 20,00 del 04\/06\/2020, al fine di fronteggiare i rischi della segnalata allerta \u201cARANCIONE\u201d.<br \/>\nIl predetto C.O.C. trova ubicazione in Sora, Lungo Liri Matteucci n .1 presso il Comando di Polizia Locale e sar\u00e0 reperibile al numero telefonico: 3397128114 dalle ore 20,00.<\/p>\n<p>Sono attivate le seguenti Funzioni di Supporto:<\/p>\n<p>FUNZIONE AMMINISTRATIVA E COORDINAMENTO DELLE FUNZIONI<\/p>\n<p>SINDACO<\/p>\n<p>Arch. Roberto De Donatis;<\/p>\n<p>FUNZIONE DI SUPPORTO 1\u00a0 &#8211; TECNICA E PIANIFICAZIONE;<\/p>\n<p>Arch. Pio Porretta;<\/p>\n<p>FUNZIONE DI SUPPORTO 3 \u2013 VOLONTARIATO E PROTEZIONE CIVILE;<\/p>\n<p>sig. Giovanni Paolucci;<\/p>\n<p>FUNZIONE DI SUPPORTO 4 \u2013 MATERIALI E MEZZI;<\/p>\n<p>Geom. Giovanni Di\u00a0 Carlo;<\/p>\n<p>FUNZIONE DI SUPPORTO 5 \u2013 FORNITURE DI SERVIZI CON DITTE ESTERNE;<\/p>\n<p>Geom. Domenico Morsilli<\/p>\n<p>FUNZIONE DI SUPPORTO 7 \u2013 STRUTTURE OPERATIVE LOCALI, VIABILITA\u2019<\/p>\n<p>Dott. Paolo Rossi<\/p>\n<p>Le singole Funzioni di Supporto del C.O.C., nell\u2019ambito delle proprie competenze, si attiveranno per il coinvolgimento immediato di tutti gli Organi preposti interessati, delle Forze dell\u2019Ordine, degli Enti e delle Associazioni di Volontariato.<br \/>\nL\u2019attivazione del C.O.C. di cui alla presente ordinanza, nell\u2019immediato, viene comunicata a tutti i referenti delle funzioni attivate.;<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Sindaco Roberto De Donatis, con ordinanza del 04\/06\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), a partire dalle ore 20,00 del 04\/06\/2020, al fine di fronteggiare i rischi [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":1871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-2024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allerta meteo, attivato il Centro Operativo Comunale - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allerta meteo, attivato il Centro Operativo Comunale - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Sindaco Roberto De Donatis, con ordinanza del 04\/06\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), a partire dalle ore 20,00 del 04\/06\/2020, al fine di fronteggiare i rischi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T15:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"213\" \/>\n\t<meta property=\"og:image:height\" content=\"236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Allerta meteo, attivato il Centro Operativo Comunale\",\"datePublished\":\"2020-06-04T15:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/\"},\"wordCount\":197,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/\",\"name\":\"Allerta meteo, attivato il Centro Operativo Comunale - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"datePublished\":\"2020-06-04T15:05:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/03\\\/ordinanza.jpeg\",\"width\":213,\"height\":236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/06\\\/04\\\/allerta-meteo-attivato-il-centro-operativo-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allerta meteo, attivato il Centro Operativo Comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allerta meteo, attivato il Centro Operativo Comunale - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Allerta meteo, attivato il Centro Operativo Comunale - Sora","og_description":"Il Sindaco Roberto De Donatis, con ordinanza del 04\/06\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), a partire dalle ore 20,00 del 04\/06\/2020, al fine di fronteggiare i rischi [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-04T15:05:46+00:00","og_image":[{"width":213,"height":236,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Allerta meteo, attivato il Centro Operativo Comunale","datePublished":"2020-06-04T15:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/"},"wordCount":197,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/","url":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/","name":"Allerta meteo, attivato il Centro Operativo Comunale - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","datePublished":"2020-06-04T15:05:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/03\/ordinanza.jpeg","width":213,"height":236},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/06\/04\/allerta-meteo-attivato-il-centro-operativo-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Allerta meteo, attivato il Centro Operativo Comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2024"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2024\/revisions"}],"predecessor-version":[{"id":2025,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2024\/revisions\/2025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/1871"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}