{"id":2096,"date":"2020-10-14T11:54:15","date_gmt":"2020-10-14T09:54:15","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2096"},"modified":"2020-10-14T11:54:25","modified_gmt":"2020-10-14T09:54:25","slug":"lunedi-19-ottovbre-il-via-alla-refezione-scolastica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/","title":{"rendered":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica"},"content":{"rendered":"<p>E&#8217; fissato per <strong>luned\u00ec 19 ottobre 2020 l&#8217;inizio del servizio di refezione scolastica<\/strong> nei tre Istituti Comprensivi cittadini.<\/p>\n<p>Sar\u00e0 la ditta \u201cItaca\u201d ad espletare il servizio, nel rispetto delle \u00a0indicazioni operative della Regione Lazio del 3.09.2020 per la distribuzione e consumazione dei pasti a scuola, per la salvaguardia degli aspetti di sicurezza alimentare e nutrizionale nella ristorazione scolastica nel corso dell\u2019emergenza Covid-19, documento che tiene conto tra l\u2019altro del decreto del MIUR del 26.06.2020 \u201cAdozione del Documento per la pianificazione delle attivit\u00e0 scolastiche, educative e formative in tutte le Istituzione del Sistema nazionale di Istruzione per l\u2019anno scolastico 2020-2021\u201d, e che \u00e8 stato aggiornato\u00a0 alle indicazioni\/disposizioni contenute ne1 \u201cProtocollo d\u2019Intesa per garantire l\u2019avvio dell\u2019anno scolastico nel rispetto delle regole di sicurezza per il contenimento della diffusione di COVID 19\u201d di cui al Decreto n. 87 del 06-08- 2020 del Ministero dell\u2019Istruzione.<\/p>\n<p>Nel\u00a0<a href=\"https:\/\/www.comune.sora.fr.it\/servizio-di-refezione-scolastica-il-via-lunedi-19-ottobre\/\">link<\/a> tutte le info necessarie per accedere al servizio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; fissato per luned\u00ec 19 ottobre 2020 l&#8217;inizio del servizio di refezione scolastica nei tre Istituti Comprensivi cittadini. Sar\u00e0 la ditta \u201cItaca\u201d ad espletare il servizio, nel rispetto delle \u00a0indicazioni [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":2097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora\" \/>\n<meta property=\"og:description\" content=\"E&#8217; fissato per luned\u00ec 19 ottobre 2020 l&#8217;inizio del servizio di refezione scolastica nei tre Istituti Comprensivi cittadini. Sar\u00e0 la ditta \u201cItaca\u201d ad espletare il servizio, nel rispetto delle \u00a0indicazioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T09:54:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T09:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Luned\u00ec 19 ottovbre, il via alla refezione scolastica\",\"datePublished\":\"2020-10-14T09:54:15+00:00\",\"dateModified\":\"2020-10-14T09:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/\"},\"wordCount\":159,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/10\\\/mensa.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/\",\"name\":\"Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/10\\\/mensa.jpg\",\"datePublished\":\"2020-10-14T09:54:15+00:00\",\"dateModified\":\"2020-10-14T09:54:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/10\\\/mensa.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2020\\\/10\\\/mensa.jpg\",\"width\":280,\"height\":148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luned\u00ec 19 ottovbre, il via alla refezione scolastica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/","og_locale":"it_IT","og_type":"article","og_title":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora","og_description":"E&#8217; fissato per luned\u00ec 19 ottobre 2020 l&#8217;inizio del servizio di refezione scolastica nei tre Istituti Comprensivi cittadini. Sar\u00e0 la ditta \u201cItaca\u201d ad espletare il servizio, nel rispetto delle \u00a0indicazioni [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-14T09:54:15+00:00","article_modified_time":"2020-10-14T09:54:25+00:00","og_image":[{"width":280,"height":148,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica","datePublished":"2020-10-14T09:54:15+00:00","dateModified":"2020-10-14T09:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/"},"wordCount":159,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/","url":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/","name":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg","datePublished":"2020-10-14T09:54:15+00:00","dateModified":"2020-10-14T09:54:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2020\/10\/mensa.jpg","width":280,"height":148},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/lunedi-19-ottovbre-il-via-alla-refezione-scolastica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Luned\u00ec 19 ottovbre, il via alla refezione scolastica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"predecessor-version":[{"id":2098,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2096\/revisions\/2098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/2097"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}