{"id":2099,"date":"2020-10-14T19:01:25","date_gmt":"2020-10-14T17:01:25","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2099"},"modified":"2020-10-14T19:01:25","modified_gmt":"2020-10-14T17:01:25","slug":"allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/","title":{"rendered":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre"},"content":{"rendered":"<div dir=\"auto\">Il Sindaco Roberto De Donatis, con ordinanza del 14\/10\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), dalle 00,00 del 15\/10\/2020, al fine di fronteggiare i rischi della segnalata allerta \u201cARANCIONE\u201d. Il C.O.C. ha sede a Sora, Lungo Liri Matteucci n .1 presso il Comando di Polizia Locale e sar\u00e0 reperibile al numero telefonico: 3397128114.<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Sindaco Roberto De Donatis, con ordinanza del 14\/10\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), dalle 00,00 del 15\/10\/2020, al fine di fronteggiare i rischi della segnalata allerta [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-2099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Sindaco Roberto De Donatis, con ordinanza del 14\/10\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), dalle 00,00 del 15\/10\/2020, al fine di fronteggiare i rischi della segnalata allerta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T17:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre\",\"datePublished\":\"2020-10-14T17:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/\"},\"wordCount\":66,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/10\\\/allertameteo-300x132.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/\",\"name\":\"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/10\\\/allertameteo-300x132.jpg\",\"datePublished\":\"2020-10-14T17:01:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/10\\\/allertameteo-300x132.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/10\\\/allertameteo-300x132.jpg\",\"width\":300,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2020\\\/10\\\/14\\\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora","og_description":"Il Sindaco Roberto De Donatis, con ordinanza del 14\/10\/2020 ha disposto l\u2019attivazione del Centro Operativo Comunale (C.O.C.), dalle 00,00 del 15\/10\/2020, al fine di fronteggiare i rischi della segnalata allerta [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-14T17:01:25+00:00","og_image":[{"width":300,"height":132,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre","datePublished":"2020-10-14T17:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/"},"wordCount":66,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/","url":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/","name":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg","datePublished":"2020-10-14T17:01:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/10\/allertameteo-300x132.jpg","width":300,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2020\/10\/14\/allerta-meteo-attivato-il-c-o-c-dalla-mezzanotte-del-15-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Allerta meteo, attivato il C.O.C dalla mezzanotte del 15 ottobre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2099"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2099\/revisions"}],"predecessor-version":[{"id":2100,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2099\/revisions\/2100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/923"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}