{"id":2283,"date":"2021-09-17T13:58:16","date_gmt":"2021-09-17T11:58:16","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2283"},"modified":"2021-09-17T13:58:16","modified_gmt":"2021-09-17T11:58:16","slug":"tesserini-venatori-ritiro-presso-lurp","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/","title":{"rendered":"Tesserini venatori ritiro presso l&#8217;URP"},"content":{"rendered":"<p>A partire dalle <strong>ore 15.30 di venerd\u00ec 17 settembre 2021<\/strong> sar\u00e0 possibile ritirare i tesserini venatori presso il l&#8217;<strong>ufficio Relazioni con il Pubblico<\/strong> del Comune di Sora in Corso Volsci, 111 con accesso diretto sul Corso stesso.<\/p>\n<p>Il tesserino si riferisce alla stagione di caccia 2021\/2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partire dalle ore 15.30 di venerd\u00ec 17 settembre 2021 sar\u00e0 possibile ritirare i tesserini venatori presso il l&#8217;ufficio Relazioni con il Pubblico del Comune di Sora in Corso Volsci, [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":2284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tesserini venatori ritiro presso l&#039;URP - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tesserini venatori ritiro presso l&#039;URP - Sora\" \/>\n<meta property=\"og:description\" content=\"A partire dalle ore 15.30 di venerd\u00ec 17 settembre 2021 sar\u00e0 possibile ritirare i tesserini venatori presso il l&#8217;ufficio Relazioni con il Pubblico del Comune di Sora in Corso Volsci, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T11:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Tesserini venatori ritiro presso l&#8217;URP\",\"datePublished\":\"2021-09-17T11:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/\"},\"wordCount\":46,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/09\\\/tesserino-venatorio.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/\",\"name\":\"Tesserini venatori ritiro presso l'URP - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/09\\\/tesserino-venatorio.jpg\",\"datePublished\":\"2021-09-17T11:58:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/09\\\/tesserino-venatorio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/09\\\/tesserino-venatorio.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/09\\\/17\\\/tesserini-venatori-ritiro-presso-lurp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tesserini venatori ritiro presso l&#8217;URP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tesserini venatori ritiro presso l'URP - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/","og_locale":"it_IT","og_type":"article","og_title":"Tesserini venatori ritiro presso l'URP - Sora","og_description":"A partire dalle ore 15.30 di venerd\u00ec 17 settembre 2021 sar\u00e0 possibile ritirare i tesserini venatori presso il l&#8217;ufficio Relazioni con il Pubblico del Comune di Sora in Corso Volsci, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-17T11:58:16+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Tesserini venatori ritiro presso l&#8217;URP","datePublished":"2021-09-17T11:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/"},"wordCount":46,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/","url":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/","name":"Tesserini venatori ritiro presso l'URP - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg","datePublished":"2021-09-17T11:58:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/09\/tesserino-venatorio.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2021\/09\/17\/tesserini-venatori-ritiro-presso-lurp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Tesserini venatori ritiro presso l&#8217;URP"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2283"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2283\/revisions"}],"predecessor-version":[{"id":2285,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2283\/revisions\/2285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/2284"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}