{"id":2403,"date":"2021-11-11T17:39:45","date_gmt":"2021-11-11T16:39:45","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2403"},"modified":"2021-11-11T17:39:45","modified_gmt":"2021-11-11T16:39:45","slug":"nuovo-codice-della-strada","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/","title":{"rendered":"Nuovo codice della strada"},"content":{"rendered":"<p>Con la <a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2021\/11\/09\/21G00170\/sg\">legge 9 novembre 2021, n. 156\u00a0\u00a0<\/a> sono entrate in vigore le nuove norme del codice della strada.<\/p>\n<p>Tra le novit\u00e0 introdotte sono previste: <strong>nuove\u00a0regole per i parcheggi per disabili e parcheggi rosa, per la circolazione dei monopattini elettrici; viene introdotto il divieto di pubblicit\u00e0 sessista o discriminatoria e l&#8217;obbligo di trasparenza sui proventi delle multe.\u00a0 \u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la legge 9 novembre 2021, n. 156\u00a0\u00a0 sono entrate in vigore le nuove norme del codice della strada. Tra le novit\u00e0 introdotte sono previste: nuove\u00a0regole per i parcheggi per [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":2404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo codice della strada - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo codice della strada - Sora\" \/>\n<meta property=\"og:description\" content=\"Con la legge 9 novembre 2021, n. 156\u00a0\u00a0 sono entrate in vigore le nuove norme del codice della strada. Tra le novit\u00e0 introdotte sono previste: nuove\u00a0regole per i parcheggi per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T16:39:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Nuovo codice della strada\",\"datePublished\":\"2021-11-11T16:39:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/\"},\"wordCount\":59,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/11\\\/codice-della-strada.jpeg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/\",\"name\":\"Nuovo codice della strada - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/11\\\/codice-della-strada.jpeg\",\"datePublished\":\"2021-11-11T16:39:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/11\\\/codice-della-strada.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/11\\\/codice-della-strada.jpeg\",\"width\":1080,\"height\":1523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2021\\\/11\\\/11\\\/nuovo-codice-della-strada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo codice della strada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo codice della strada - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo codice della strada - Sora","og_description":"Con la legge 9 novembre 2021, n. 156\u00a0\u00a0 sono entrate in vigore le nuove norme del codice della strada. Tra le novit\u00e0 introdotte sono previste: nuove\u00a0regole per i parcheggi per [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-11T16:39:45+00:00","og_image":[{"width":1080,"height":1523,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Nuovo codice della strada","datePublished":"2021-11-11T16:39:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/"},"wordCount":59,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/","url":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/","name":"Nuovo codice della strada - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg","datePublished":"2021-11-11T16:39:45+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/11\/codice-della-strada.jpeg","width":1080,"height":1523},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2021\/11\/11\/nuovo-codice-della-strada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Nuovo codice della strada"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"predecessor-version":[{"id":2405,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2403\/revisions\/2405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/2404"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}