{"id":2453,"date":"2022-01-17T08:45:36","date_gmt":"2022-01-17T07:45:36","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=2453"},"modified":"2022-01-17T08:45:36","modified_gmt":"2022-01-17T07:45:36","slug":"divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/","title":{"rendered":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2433\" src=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png\" alt=\"\" width=\"222\" height=\"223\" srcset=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png 222w, https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata-150x150.png 150w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/>Con ordinanza\u00a0<a href=\"https:\/\/sora.trasparenza-valutazione-merito.it\/web\/trasparenza\/papca-ap?p_p_id=jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet&amp;p_p_lifecycle=2&amp;p_p_state=pop_up&amp;p_p_mode=view&amp;p_p_resource_id=downloadAllegato&amp;p_p_cacheability=cacheLevelPage&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_downloadSigned=false&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_id=6972208&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_action=mostraDettaglio&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_fromAction=recuperaDettaglio\">n.6 del 13\/01\/2022<\/a>\u00a0si dispone il divieto di transito sui passaggi a livello della linea ferroviaria Sora-Roccasecca, situati nelle strade comunali e nei giorni ed orari rispettivamente indicati:<br \/>\n<strong>1) PL al km ferroviario 28+957 \u2013 Via Edoardo Facchini<\/strong><br \/>\ndal giorno 18\/01\/2022 al giorno 22\/01\/2022, dalle ore 22 alle ore 5 successive;<br \/>\n<strong>2)<\/strong>\u00a0<strong>PL al km ferroviario 28+646 \u2013 Via Costantinopoli<\/strong><br \/>\ndal giorno 18\/01\/2022 al giorno 22\/01\/2022, dalle ore 22 alle ore 5 successive;<br \/>\n<strong>3) PL al km ferroviario 27+648 \u2013 Via Pozzo Pantano<\/strong><br \/>\ndal giorno 19\/01\/2022 al giorno 27\/01\/2022, dalle ore 22 alle ore 5 successive;<br \/>\n<strong>4)<\/strong>\u00a0<strong>PL al km ferroviario 26+809 \u2013 Via Ponte Olmo<\/strong><br \/>\ndal giorno 21\/01\/2022 al giorno 29\/01\/2022, dalle ore 22 alle ore 5 successive;<\/p>\n<p>per seguire lavori riguardanti la sicurezza dell\u2019esercizio ferroviario che prevedono la chiusura dei passaggi a livello suindicati.<br \/>\nIl traffico veicolare e pedonale \u00e8 deviato in percorsi alternati<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con ordinanza\u00a0n.6 del 13\/01\/2022\u00a0si dispone il divieto di transito sui passaggi a livello della linea ferroviaria Sora-Roccasecca, situati nelle strade comunali e nei giorni ed orari rispettivamente indicati: 1) PL [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2453","post","type-post","status-publish","format-standard","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora\" \/>\n<meta property=\"og:description\" content=\"Con ordinanza\u00a0n.6 del 13\/01\/2022\u00a0si dispone il divieto di transito sui passaggi a livello della linea ferroviaria Sora-Roccasecca, situati nelle strade comunali e nei giorni ed orari rispettivamente indicati: 1) PL [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-17T07:45:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Divieto di transito, dal 18\\\/01\\\/2022 al 29\\\/01\\\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA\",\"datePublished\":\"2022-01-17T07:45:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/\"},\"wordCount\":132,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/12\\\/divieto-di-fermata.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/\",\"name\":\"Divieto di transito, dal 18\\\/01\\\/2022 al 29\\\/01\\\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/12\\\/divieto-di-fermata.png\",\"datePublished\":\"2022-01-17T07:45:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/12\\\/divieto-di-fermata.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2021\\\/12\\\/divieto-di-fermata.png\",\"width\":222,\"height\":223},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2022\\\/01\\\/17\\\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divieto di transito, dal 18\\\/01\\\/2022 al 29\\\/01\\\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/","og_locale":"it_IT","og_type":"article","og_title":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora","og_description":"Con ordinanza\u00a0n.6 del 13\/01\/2022\u00a0si dispone il divieto di transito sui passaggi a livello della linea ferroviaria Sora-Roccasecca, situati nelle strade comunali e nei giorni ed orari rispettivamente indicati: 1) PL [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-01-17T07:45:36+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png","type":"","width":"","height":""}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA","datePublished":"2022-01-17T07:45:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/"},"wordCount":132,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/","url":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/","name":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png","datePublished":"2022-01-17T07:45:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2021\/12\/divieto-di-fermata.png","width":222,"height":223},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2022\/01\/17\/divieto-di-transito-dal-18-01-2022-al-29-01-2022-sui-passaggi-a-livello-della-linea-ferroviaria-sora-roccasecca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Divieto di transito, dal 18\/01\/2022 al 29\/01\/2022, sui passaggi a livello della linea ferroviaria SORA-ROCCASECCA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=2453"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2453\/revisions"}],"predecessor-version":[{"id":2454,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/2453\/revisions\/2454"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=2453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=2453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=2453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}