{"id":366,"date":"2018-04-13T12:44:57","date_gmt":"2018-04-13T10:44:57","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=366"},"modified":"2018-04-13T13:51:33","modified_gmt":"2018-04-13T11:51:33","slug":"convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/","title":{"rendered":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00"},"content":{"rendered":"<p>Convocazione del Consiglio Comunale di Sora <strong>VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\u00a0<\/strong><span style=\"font-size: 1rem\">ordine del giorno:<\/span><\/p>\n<p>1. Comunicazioni del Sindaco.<\/p>\n<p>2. Programma delle collaborazioni autonome ex art.46 D.L. 112\/2008.<\/p>\n<p>3. D.M. delle Infrastrutture e trasporti dell\u201911.11.2011 \u2013 Programma triennale dei lavori Pubblici 2018 \u2013 2020 ed elenco annuale 2018 \u2013 approvazione.<\/p>\n<p>4. Ricognizione aree per edilizia residenziale pubblica.<\/p>\n<p>5. Approvazione Bilancio di previsione 2018 \u2013 2020.<\/p>\n<p><a href=\"https:\/\/sora.trasparenza-valutazione-merito.it\/web\/trasparenza\/papca-ap?p_p_id=jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet&amp;p_p_lifecycle=2&amp;p_p_state=pop_up&amp;p_p_mode=view&amp;p_p_resource_id=downloadAllegato&amp;p_p_cacheability=cacheLevelPage&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_downloadSigned=true&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_id=1403477&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_action=mostraDettaglio&amp;_jcitygovalbopubblicazioni_WAR_jcitygovalbiportlet_fromAction=recuperaDettaglio\">CONVOCAZIONE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\u00a0ordine del giorno: 1. Comunicazioni del Sindaco. 2. Programma delle collaborazioni autonome ex art.46 D.L. 112\/2008. 3. D.M. [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora\" \/>\n<meta property=\"og:description\" content=\"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\u00a0ordine del giorno: 1. Comunicazioni del Sindaco. 2. Programma delle collaborazioni autonome ex art.46 D.L. 112\/2008. 3. D.M. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-13T10:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-13T11:51:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\",\"datePublished\":\"2018-04-13T10:44:57+00:00\",\"dateModified\":\"2018-04-13T11:51:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/\"},\"wordCount\":61,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/\",\"name\":\"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"datePublished\":\"2018-04-13T10:44:57+00:00\",\"dateModified\":\"2018-04-13T11:51:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"width\":400,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/04\\\/13\\\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora","og_description":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00\u00a0ordine del giorno: 1. Comunicazioni del Sindaco. 2. Programma delle collaborazioni autonome ex art.46 D.L. 112\/2008. 3. D.M. [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-13T10:44:57+00:00","article_modified_time":"2018-04-13T11:51:33+00:00","og_image":[{"width":400,"height":277,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00","datePublished":"2018-04-13T10:44:57+00:00","dateModified":"2018-04-13T11:51:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/"},"wordCount":61,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/","url":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/","name":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00 - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","datePublished":"2018-04-13T10:44:57+00:00","dateModified":"2018-04-13T11:51:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","width":400,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/04\/13\/convocazione-del-consiglio-comunale-di-sora-venerdi-20-aprile-2018-alle-ore-1500\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Convocazione del Consiglio Comunale di Sora VENERDI\u2019 20 APRILE 2018 ALLE ORE 15,00"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"predecessor-version":[{"id":369,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/366\/revisions\/369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}