{"id":726,"date":"2018-07-05T15:11:16","date_gmt":"2018-07-05T13:11:16","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=726"},"modified":"2018-07-05T15:11:16","modified_gmt":"2018-07-05T13:11:16","slug":"sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/","title":{"rendered":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica"},"content":{"rendered":"<p>Sabato 7\u00a0luglio alle\u00a0ore 21,00, in piazza S. Giovanni, nell&#8217;ambito della Mostra d&#8217;Arte Cinematografica, si terr\u00e0 la commemorazione della nascita di Vittorio De Sica con l&#8217;esibizione dell&#8217;ORCHESTRA DA CAMERA DI ROMA,\u00a0voce recitante FEDERICO MANTOVA, direttore VINCENZO MARIOZZI, le\u00a0 musiche di Nino Rota, Ennio Morricone, Nicola Piovani.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 7\u00a0luglio alle\u00a0ore 21,00, in piazza S. Giovanni, nell&#8217;ambito della Mostra d&#8217;Arte Cinematografica, si terr\u00e0 la commemorazione della nascita di Vittorio De Sica con l&#8217;esibizione dell&#8217;ORCHESTRA DA CAMERA DI ROMA,\u00a0voce [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora\" \/>\n<meta property=\"og:description\" content=\"Sabato 7\u00a0luglio alle\u00a0ore 21,00, in piazza S. Giovanni, nell&#8217;ambito della Mostra d&#8217;Arte Cinematografica, si terr\u00e0 la commemorazione della nascita di Vittorio De Sica con l&#8217;esibizione dell&#8217;ORCHESTRA DA CAMERA DI ROMA,\u00a0voce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-05T13:11:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"210\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica\",\"datePublished\":\"2018-07-05T13:11:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/\"},\"wordCount\":58,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/06\\\/locandina-de-sica-210x300.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/\",\"name\":\"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/06\\\/locandina-de-sica-210x300.jpg\",\"datePublished\":\"2018-07-05T13:11:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/06\\\/locandina-de-sica-210x300.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/06\\\/locandina-de-sica-210x300.jpg\",\"width\":210,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/07\\\/05\\\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/","og_locale":"it_IT","og_type":"article","og_title":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora","og_description":"Sabato 7\u00a0luglio alle\u00a0ore 21,00, in piazza S. Giovanni, nell&#8217;ambito della Mostra d&#8217;Arte Cinematografica, si terr\u00e0 la commemorazione della nascita di Vittorio De Sica con l&#8217;esibizione dell&#8217;ORCHESTRA DA CAMERA DI ROMA,\u00a0voce [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-07-05T13:11:16+00:00","og_image":[{"width":210,"height":300,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica","datePublished":"2018-07-05T13:11:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/"},"wordCount":58,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/","url":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/","name":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg","datePublished":"2018-07-05T13:11:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/06\/locandina-de-sica-210x300.jpg","width":210,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/07\/05\/sabato-7-luglio-ore-2100-p-zza-s-giovanni-commemorazione-nascita-v-de-sica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Sabato 7 luglio ore 21,00, p.zza S. Giovanni commemorazione nascita V. De Sica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"predecessor-version":[{"id":727,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/726\/revisions\/727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/624"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}