{"id":809,"date":"2018-08-02T11:28:54","date_gmt":"2018-08-02T09:28:54","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=809"},"modified":"2018-08-02T11:28:54","modified_gmt":"2018-08-02T09:28:54","slug":"sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/","title":{"rendered":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Sabato 04 agosto 2018, per il trasporto e montaggio macchina dell\u2019Assunta, con apposita <a href=\"http:\/\/ore 08.00 alle ore 12.00 del 04 agosto 2018 : - L\u2019istituzione del divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni ambo i lati spazio antistante l\u2019ingresso della Cattedrale.-\">ordinanza<\/a>, dalle ore 08.00 alle ore 12.00 \u00e8 istituito il divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni ambo i lati spazio antistante l\u2019ingresso della Cattedrale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sabato 04 agosto 2018, per il trasporto e montaggio macchina dell\u2019Assunta, con apposita ordinanza, dalle ore 08.00 alle ore 12.00 \u00e8 istituito il divieto di sosta e di fermata [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Sabato 04 agosto 2018, per il trasporto e montaggio macchina dell\u2019Assunta, con apposita ordinanza, dalle ore 08.00 alle ore 12.00 \u00e8 istituito il divieto di sosta e di fermata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-02T09:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni\",\"datePublished\":\"2018-08-02T09:28:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/\",\"name\":\"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"datePublished\":\"2018-08-02T09:28:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/paletta-stop-traffico.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/08\\\/02\\\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/","og_locale":"it_IT","og_type":"article","og_title":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora","og_description":"&nbsp; Sabato 04 agosto 2018, per il trasporto e montaggio macchina dell\u2019Assunta, con apposita ordinanza, dalle ore 08.00 alle ore 12.00 \u00e8 istituito il divieto di sosta e di fermata [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-08-02T09:28:54+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni","datePublished":"2018-08-02T09:28:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/","url":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/","name":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","datePublished":"2018-08-02T09:28:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/paletta-stop-traffico.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/08\/02\/sabato-04-agosto-2018-dalle-08-00-alle-12-00-divieto-di-sosta-e-di-fermata-con-lobbligo-della-rimozione-in-via-filippo-corridoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Sabato 04 agosto 2018 dalle 08.00 alle 12.00 divieto di sosta e di fermata con l\u2019obbligo della rimozione in Via Filippo Corridoni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=809"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/809\/revisions"}],"predecessor-version":[{"id":810,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/809\/revisions\/810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/281"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}