{"id":951,"date":"2018-10-29T13:05:48","date_gmt":"2018-10-29T12:05:48","guid":{"rendered":"https:\/\/comunicacity.net\/sora\/?p=951"},"modified":"2018-10-29T13:05:48","modified_gmt":"2018-10-29T12:05:48","slug":"consiglio-comunale-lunedi-29-ottobre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/","title":{"rendered":"Consiglio Comunale luned\u00ec 29 ottobre"},"content":{"rendered":"<p>Il Presidente del Consilgio Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in 1\u00b0 convocazione, per il giorno\u00a0LUNEDI\u201d 29 OTTOBRE 2018 ALLE ORE17,30\u00a0e, in caso di mancanza del numero legale, in 2\u00b0 convocazione, per il giorno marted\u00ec 30 ottobre 2018 alle ore 19,30 perla trattazione del seguente ordine del giorno:<\/p>\n<ol>\n<li>Interrogazione presentata dal Consigliere Fabrizio Pintori, n. 30474 dell08.10.2018, avente ad oggetto: \u201cGestione e incentivazione delle adozioni dei cani presenti nei canili convenzionati con il Comune di Sora \u2014 Convenzioni con Associazioni di volontariato\u201d.<\/li>\n<li>Interrogazione presentata dal Consigliere Fabrizio Pintori, n. 31968 del 22.10.2018, avente ad oggetto: \u201cImpianti di comunicazioni elettroniche, antenne per la telefonia mobile e le trasmissioni radioelettriche\u201d.<\/li>\n<li>Regolamento perla disciplina delle procedure di sdemanializzazione terreni.<\/li>\n<li>Regolamento sui permessi a costruire convenzionati.<\/li>\n<li>Scioglimento Convenzione Centrale Unica di Committenza (C.U.C.) &#8211; Comune di Sora e Comune di Santopadre, ai sensi dell\u2019art. 31 della Convenzione.<\/li>\n<li>Adesione alla Stazione Unica Appaltante della Provincia di Frosinone<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente del Consilgio Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in 1\u00b0 convocazione, [&hellip;]<\/p>\n","protected":false},"author":250,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consiglio Comunale luned\u00ec 29 ottobre - Sora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consiglio Comunale luned\u00ec 29 ottobre - Sora\" \/>\n<meta property=\"og:description\" content=\"Il Presidente del Consilgio Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in 1\u00b0 convocazione, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-29T12:05:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csardellitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"csardellitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/\"},\"author\":{\"name\":\"csardellitti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"headline\":\"Consiglio Comunale luned\u00ec 29 ottobre\",\"datePublished\":\"2018-10-29T12:05:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/\"},\"wordCount\":166,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/\",\"name\":\"Consiglio Comunale luned\u00ec 29 ottobre - Sora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"datePublished\":\"2018-10-29T12:05:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/wp-content\\\/uploads\\\/sites\\\/119\\\/2018\\\/04\\\/sala-consiliare.jpg\",\"width\":400,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/2018\\\/10\\\/29\\\/consiglio-comunale-lunedi-29-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consiglio Comunale luned\u00ec 29 ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/\",\"name\":\"Sora\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/#\\\/schema\\\/person\\\/fe998e4889c2b40cb2efb49a7e4cc5bd\",\"name\":\"csardellitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g\",\"caption\":\"csardellitti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sora\\\/author\\\/csardellitti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consiglio Comunale luned\u00ec 29 ottobre - Sora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"Consiglio Comunale luned\u00ec 29 ottobre - Sora","og_description":"Il Presidente del Consilgio Antonio Lecce ha disposto la convocazione del Consiglio Comunale di Sora in seduta pubblica, straordinaria, presso la sala consiliare ubicata in Corso Volsci, in 1\u00b0 convocazione, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/","og_site_name":"Sora","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-10-29T12:05:48+00:00","og_image":[{"width":400,"height":277,"url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","type":"image\/jpeg"}],"author":"csardellitti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"csardellitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/"},"author":{"name":"csardellitti","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"headline":"Consiglio Comunale luned\u00ec 29 ottobre","datePublished":"2018-10-29T12:05:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/"},"wordCount":166,"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/","url":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/","name":"Consiglio Comunale luned\u00ec 29 ottobre - Sora","isPartOf":{"@id":"https:\/\/comunicacity.net\/sora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","datePublished":"2018-10-29T12:05:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#primaryimage","url":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","contentUrl":"https:\/\/comunicacity.net\/sora\/wp-content\/uploads\/sites\/119\/2018\/04\/sala-consiliare.jpg","width":400,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sora\/2018\/10\/29\/consiglio-comunale-lunedi-29-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sora\/"},{"@type":"ListItem","position":2,"name":"Consiglio Comunale luned\u00ec 29 ottobre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sora\/#website","url":"https:\/\/comunicacity.net\/sora\/","name":"Sora","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sora\/#\/schema\/person\/fe998e4889c2b40cb2efb49a7e4cc5bd","name":"csardellitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd32938f30280a396859171f58dc0eafc461825a55feb527e43da7ebcfc5684d?s=96&d=mm&r=g","caption":"csardellitti"},"url":"https:\/\/comunicacity.net\/sora\/author\/csardellitti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"predecessor-version":[{"id":952,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/posts\/951\/revisions\/952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sora\/wp-json\/wp\/v2\/tags?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}