{"id":1874,"date":"2019-01-23T12:02:36","date_gmt":"2019-01-23T11:02:36","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=1874"},"modified":"2019-01-23T12:02:36","modified_gmt":"2019-01-23T11:02:36","slug":"proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/","title":{"rendered":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0"},"content":{"rendered":"<p>Si comunica che con deliberazione della Giunta Comunale n. 4 adottata in data 21\/01\/2019 sono stati posticipati al 28\/02\/2019 i termini per il versamento, relativamente all\u2019anno 2019, della tassa per l\u2019occupazione di spazi ed aree pubbliche e imposta sulla pubblicit\u00e0.<br \/>\nSi precisa altres\u00ec che anche per le occupazioni temporanee di suolo pubblico effettuate e conclusesi prima del 28\/02\/2019, la scadenza di pagamento viene fissata al 28\/02\/2019.<br \/>\nSar\u00e0 cura dell\u2019Ufficio Tributi inviare a domicilio i modelli di versamento compilati per le occupazioni permanenti e imposta sulla pubblicit\u00e0, mentre per le occupazioni temporanee conclusesi prima del 28\/02\/2019 gli interessati sono tenuti a rivolgersi a Punto Comune per richiedere l\u2019importo da versare.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1875\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/01\/PROROGA-TOSAP-E-IMPOSTA-SULLA-PUBBLICITA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/01\/PROROGA-TOSAP-E-IMPOSTA-SULLA-PUBBLICITA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>PROROGA TOSAP E IMPOSTA SULLA PUBBLICITA'<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che con deliberazione della Giunta Comunale n. 4 adottata in data 21\/01\/2019 sono stati posticipati al 28\/02\/2019 i termini per il versamento, relativamente all\u2019anno 2019, della tassa per [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tributi-e-finanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica che con deliberazione della Giunta Comunale n. 4 adottata in data 21\/01\/2019 sono stati posticipati al 28\/02\/2019 i termini per il versamento, relativamente all\u2019anno 2019, della tassa per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-23T11:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"100\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0\",\"datePublished\":\"2019-01-23T11:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/\"},\"wordCount\":120,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2015\\\/12\\\/sorianonelcimino100x100.jpg\",\"articleSection\":[\"Tributi e Finanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/\",\"name\":\"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2015\\\/12\\\/sorianonelcimino100x100.jpg\",\"datePublished\":\"2019-01-23T11:02:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2015\\\/12\\\/sorianonelcimino100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2015\\\/12\\\/sorianonelcimino100x100.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/01\\\/23\\\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/","og_locale":"it_IT","og_type":"article","og_title":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino","og_description":"Si comunica che con deliberazione della Giunta Comunale n. 4 adottata in data 21\/01\/2019 sono stati posticipati al 28\/02\/2019 i termini per il versamento, relativamente all\u2019anno 2019, della tassa per [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-23T11:02:36+00:00","og_image":[{"width":100,"height":100,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0","datePublished":"2019-01-23T11:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/"},"wordCount":120,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg","articleSection":["Tributi e Finanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/","name":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg","datePublished":"2019-01-23T11:02:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2015\/12\/sorianonelcimino100x100.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/01\/23\/proroga-termini-di-versamento-tassa-occupazione-spazi-ed-aree-pubbliche-ed-imposta-sulla-pubblicita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Proroga termini di versamento tassa occupazione spazi ed aree pubbliche ed imposta sulla pubblicit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=1874"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1874\/revisions"}],"predecessor-version":[{"id":1876,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1874\/revisions\/1876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=1874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=1874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=1874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}