{"id":1893,"date":"2019-03-21T17:17:28","date_gmt":"2019-03-21T16:17:28","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=1893"},"modified":"2019-03-21T17:17:46","modified_gmt":"2019-03-21T16:17:46","slug":"ecostazione-informatizzata-per-i-non-residenti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/","title":{"rendered":"Ecostazione informatizzata per i non residenti"},"content":{"rendered":"<p>Si comunica che da <strong>sabato 6 Aprile 2019<\/strong> sar\u00e0 disponibile una <strong>ecostazione a Soriano nel Cimino<\/strong>.<\/p>\n<p>Un nuovo servizio di <strong>raccolta differenziata<\/strong> dei rifiuti riservata per tutti gli intestatari della <strong>Tari<\/strong> (Tributo Servizio Rifiuti) non residenti nel Comune di Soriano nel Cimino.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa ecostazione consentir\u00e0 di <strong>conferire rifiuti opportunamente differenziati di tutte le tipologie<\/strong> (vetro e lattine, carta e cartone, umido, plastica, secco non riciclabile), offrendo la possibilit\u00e0 di gettare i rifiuti <strong>tutti i giorni a qualsiasi ora<\/strong> indipendentemente dal calendario di raccolta porta a porta, vigente in tutto il territorio comunale.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 un servizio che non sostituisce la raccolta porta a porta, bens\u00ec la integra andando incontro alle esigenze di chi \u00e8 <strong>proprietario di una seconda casa<\/strong> nel nostro Comune e, non risiedendo quotidianamente sul territorio, non pu\u00f2 seguire il calendario settimanale previsto.<\/p>\n<p>&nbsp;<\/p>\n<p>I conferimenti presso l\u2019ecostazione sono <strong>totalmente gratuiti<\/strong> e l\u2019accesso al servizio sar\u00e0 possibile esclusivamente attraverso l\u2019utilizzo della <strong>tessera sanitaria dell\u2019intestatario Tari<\/strong> (Tributo Servizio Rifiuti) dell\u2019abitazione. La Sua tessera \u00e8 gi\u00e0 stata abilitata.<\/p>\n<p>&nbsp;<\/p>\n<p>Per conferire i rifiuti baster\u00e0 inserire la tessera sanitaria nello spazio indicato e selezionare il tipo di rifiuto da conferire. A quel punto si aprir\u00e0 il portello corrispondente dove gettare il rifiuto.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ecostazione \u00e8 situata presso il <strong>parcheggio di fronte all\u2019ingresso del Cimitero<\/strong> (lato nuovo &#8211; S.P. Colonnetta) ed \u00e8 videosorvegliata.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Vademecum per il C<\/em><\/strong><strong><em>ORRETTO <\/em><\/strong><strong><em>U<\/em><\/strong><strong><em>TILIZZO DELL<\/em><\/strong><strong><em>\u2019Ecostazione I<\/em><\/strong><strong><em>NFORMATIZZATA<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><strong>I rifiuti vanno conferiti differenziati per tipologia<\/strong>;<\/li>\n<li>strisciare la tessera sanitaria (gi\u00e0 abilitata) nell\u2019apposito dispositivo di lettura;<\/li>\n<li>un segnale acustico segnaler\u00e0 l\u2019attivazione dell\u2019Isola;<\/li>\n<li>appoggiare o sfiorare un dito sulla fotocellula di ogni bocchetta che si intende aprire;<\/li>\n<li>le bocchette selezionate al punto 4 si apriranno in ordine dal numero 1 al numero 6;<\/li>\n<li>gettare i propri rifiuti differenziati all\u2019interno dei cassonetti;<\/li>\n<li>a fine conferimento ritirare lo scontrino;<\/li>\n<li>se necessario ripetere i punti 2, 3 e 4;<\/li>\n<li>Per segnalare un guasto o un malfunzionamento chiamare il numero 0761742219-0761742236<\/li>\n<\/ol>\n<p>o scrivere all\u2019indirizzo email ambiente@comune.sorianonelcimino.vt.it<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ASSESSORE ALL\u2019AMBIENTE<\/p>\n<p>Piero Nicolamme<\/p>\n<p>&nbsp;<\/p>\n<p>IL SINDACO<\/p>\n<p>Fabio Menicacci<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che da sabato 6 Aprile 2019 sar\u00e0 disponibile una ecostazione a Soriano nel Cimino. Un nuovo servizio di raccolta differenziata dei rifiuti riservata per tutti gli intestatari della [&hellip;]<\/p>\n","protected":false},"author":85,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1893","post","type-post","status-publish","format-standard","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecostazione informatizzata per i non residenti - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecostazione informatizzata per i non residenti - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica che da sabato 6 Aprile 2019 sar\u00e0 disponibile una ecostazione a Soriano nel Cimino. Un nuovo servizio di raccolta differenziata dei rifiuti riservata per tutti gli intestatari della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-21T16:17:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-21T16:17:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"mauriziocapponi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mauriziocapponi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/\"},\"author\":{\"name\":\"mauriziocapponi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/a945395c30b3d254d278414dccc818f3\"},\"headline\":\"Ecostazione informatizzata per i non residenti\",\"datePublished\":\"2019-03-21T16:17:28+00:00\",\"dateModified\":\"2019-03-21T16:17:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/\"},\"wordCount\":352,\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/\",\"name\":\"Ecostazione informatizzata per i non residenti - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"datePublished\":\"2019-03-21T16:17:28+00:00\",\"dateModified\":\"2019-03-21T16:17:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/a945395c30b3d254d278414dccc818f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/03\\\/21\\\/ecostazione-informatizzata-per-i-non-residenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecostazione informatizzata per i non residenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/a945395c30b3d254d278414dccc818f3\",\"name\":\"mauriziocapponi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g\",\"caption\":\"mauriziocapponi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/mauriziocapponi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecostazione informatizzata per i non residenti - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/","og_locale":"it_IT","og_type":"article","og_title":"Ecostazione informatizzata per i non residenti - Soriano nel Cimino","og_description":"Si comunica che da sabato 6 Aprile 2019 sar\u00e0 disponibile una ecostazione a Soriano nel Cimino. Un nuovo servizio di raccolta differenziata dei rifiuti riservata per tutti gli intestatari della [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-03-21T16:17:28+00:00","article_modified_time":"2019-03-21T16:17:46+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png","height":600,"width":1200,"type":""}],"author":"mauriziocapponi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mauriziocapponi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/"},"author":{"name":"mauriziocapponi","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/a945395c30b3d254d278414dccc818f3"},"headline":"Ecostazione informatizzata per i non residenti","datePublished":"2019-03-21T16:17:28+00:00","dateModified":"2019-03-21T16:17:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/"},"wordCount":352,"articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/","name":"Ecostazione informatizzata per i non residenti - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"datePublished":"2019-03-21T16:17:28+00:00","dateModified":"2019-03-21T16:17:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/a945395c30b3d254d278414dccc818f3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/03\/21\/ecostazione-informatizzata-per-i-non-residenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Ecostazione informatizzata per i non residenti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/a945395c30b3d254d278414dccc818f3","name":"mauriziocapponi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1f1f1fe11c7d831c7f11c8dda5b9cbef2deccbed143023e7b7bd7c27db8f0e6?s=96&d=mm&r=g","caption":"mauriziocapponi"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/mauriziocapponi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=1893"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1893\/revisions"}],"predecessor-version":[{"id":1894,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1893\/revisions\/1894"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=1893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=1893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=1893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}