{"id":1912,"date":"2019-05-16T15:07:18","date_gmt":"2019-05-16T13:07:18","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=1912"},"modified":"2019-05-16T15:07:18","modified_gmt":"2019-05-16T13:07:18","slug":"interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/","title":{"rendered":"Interruzione erogazione acqua &#8211; Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019"},"content":{"rendered":"<p>Si comunica che luned\u00ec 20 maggio, in via 5 giugno, dalle 8,30 fino a termine dei lavori (circa le 14), inizieranno le operazioni di collegamento della nuova condotta idrica in sostituzione di quella esistente.\u00a0In caso di maltempo i lavori saranno eseguiti la mattina di marted\u00ec 21\u00a0maggio.<\/p>\n<p><strong>Per tutta la durata dei lavori si rende necessario interrompere l\u2019erogazione dell\u2019acqua potabile presso le seguenti vie: Ospedale Vecchio, Conce, Galleria, Monaci, 8 marzo, Fossatello e zone limitrofe.<\/strong><\/p>\n<p>Al ripristino del flusso idrico potrebbe verificarsi un intorbidimento momentaneo dell\u2019acqua.<\/p>\n<p>TALETE SPA<\/p>\n<p><em>Fonte: <a href=\"http:\/\/www.comune.sorianonelcimino.vt.it\/archivio10_notizie-e-comunicati_0_864.html\" target=\"_blank\" rel=\"noopener\">Sito Comune di Soriano Nel Cimino<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che luned\u00ec 20 maggio, in via 5 giugno, dalle 8,30 fino a termine dei lavori (circa le 14), inizieranno le operazioni di collegamento della nuova condotta idrica in [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":1913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"Si comunica che luned\u00ec 20 maggio, in via 5 giugno, dalle 8,30 fino a termine dei lavori (circa le 14), inizieranno le operazioni di collegamento della nuova condotta idrica in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-16T13:07:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Interruzione erogazione acqua &#8211; Lavori di manutenzione su condotte idriche 20\\\/21 Maggio 2019\",\"datePublished\":\"2019-05-16T13:07:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/\"},\"wordCount\":104,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/\",\"name\":\"Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\\\/21 Maggio 2019 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"datePublished\":\"2019-05-16T13:07:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2019\\\/05\\\/acqua-rubinetto-talete.jpg\",\"width\":300,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2019\\\/05\\\/16\\\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interruzione erogazione acqua &#8211; Lavori di manutenzione su condotte idriche 20\\\/21 Maggio 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019 - Soriano nel Cimino","og_description":"Si comunica che luned\u00ec 20 maggio, in via 5 giugno, dalle 8,30 fino a termine dei lavori (circa le 14), inizieranno le operazioni di collegamento della nuova condotta idrica in [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-16T13:07:18+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Interruzione erogazione acqua &#8211; Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019","datePublished":"2019-05-16T13:07:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/"},"wordCount":104,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/","name":"Interruzione erogazione acqua - Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","datePublished":"2019-05-16T13:07:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2019\/05\/acqua-rubinetto-talete.jpg","width":300,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2019\/05\/16\/interruzione-erogazione-acqua-lavori-di-manutenzione-su-condotte-idriche-20-21-maggio-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Interruzione erogazione acqua &#8211; Lavori di manutenzione su condotte idriche 20\/21 Maggio 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/1912\/revisions\/1914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}