{"id":2179,"date":"2020-05-19T18:57:49","date_gmt":"2020-05-19T16:57:49","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2179"},"modified":"2020-05-20T06:56:44","modified_gmt":"2020-05-20T04:56:44","slug":"avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/","title":{"rendered":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda"},"content":{"rendered":"<p style=\"text-align: center\"><strong>AVVISO PUBBLICO<\/strong><\/p>\n<p>IL SINDACO<\/p>\n<p>In questo momento di grande difficolt\u00e0 economica e sociale dovuta all&#8217;emergenza\u00a0 sanitaria, \u00e8 priorit\u00e0 per L&#8217;Amministrazione Comunale, a causa delle difficolta economiche dovute all\u2019emergenza epidemiologica COVID19, promuovere delle misure a sostegno del tessuto economico del Paese. In tal senso si pone la Deliberazione della Giunta Comunale nr.66 del 15.05.2020 con la quale si evidenzia la volont\u00e0 di ristorare gli operatori economici della limitazione all&#8217;uso degli spazi imposta dalle misure sanitarie e di prevenzione del Coronavirus. L\u2019Amministrazione\u00a0 ha dato indirizzo agli Uffici competenti\u00a0 di avviare le pi\u00f9 opportune procedure per consentire e\/o ampliare in via straordinaria l&#8217;occupazione di suolo pubblico per l&#8217;esercizio di somministrazione di cibi e bevande ed attivit\u00e0 artigianali di pizzeria e paninoteca al fine anche, di\u00a0 migliorare la qualit\u00e0\u00a0 dello spazio pubblico del Paese nel rispetto dei distanziamenti e contingentamenti previsti dalle vigenti normative sanitarie.<br \/>\nRitenuto che \u00e8 a tal fine necessario che gli operatori economici manifestino le loro reali esigenze per una valutazione complessiva dei bisogni e per dare immediato riscontro a tutte le necessit\u00e0 contemperandone gli interessi.<\/p>\n<p style=\"text-align: center\"><strong>RENDE NOTO<\/strong><\/p>\n<p style=\"text-align: left\">Ai titolari di pubblici esercizi ed attivit\u00e0 artigianali di pizzeria e paninoteca che operano sul territorio del Comune di Soriano nel Cimino chiunque interessato di presentare, <strong>entro il 25 Maggio 2020 <\/strong>domanda di occupazione temporanea\u00a0 di suolo pubblico ovvero ampliamento di una occupazione gi\u00e0 esistente per la ricezione della clientela per periodo temporale che deve intendersi ricompreso dal <strong>22 maggio\u00a0 2020 al 30 ottobre 2020 <\/strong>Le domande che perverranno successivamente a tale data saranno prese in esame ove residui suolo pubblico disponibile.<br \/>\nL&#8217;operatore dovr\u00e0\u00a0 presentare una\u00a0 richiesta secondo lo schema allegato al presente avviso.<br \/>\nE\u2019 disposta l\u2019esenzione dal pagamento della TOSAP.<br \/>\nL&#8217;occupazione di suolo pubblico temporaneo delle aree in concessione a bar e ristoranti sar\u00e0 consentito previa verifica delle esigenze di sicurezza pubblica, senza comportare in alcun modo intralcio alla viabilit\u00e0 e nel rispetto delle norme igienico sanitarie disposte dalla ASL di Viterbo.<\/p>\n<p style=\"text-align: right\">\nIl Sindaco<br \/>\nFabio Menicacci<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2180\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/modello-occupazione-suolo-pubblico-COVID19.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/modello-occupazione-suolo-pubblico-COVID19.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>modello occupazione suolo pubblico COVID19<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2181\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/modello-occupazione-suolo-pubblico-COVID19.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/modello-occupazione-suolo-pubblico-COVID19.docx', '_system'); return false;\"><i class='icon attachment'><\/i>modello occupazione suolo pubblico COVID19<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2186\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/Avviso-tosap-covid.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/Avviso-tosap-covid.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso tosap covid<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AVVISO PUBBLICO IL SINDACO In questo momento di grande difficolt\u00e0 economica e sociale dovuta all&#8217;emergenza\u00a0 sanitaria, \u00e8 priorit\u00e0 per L&#8217;Amministrazione Comunale, a causa delle difficolta economiche dovute all\u2019emergenza epidemiologica COVID19, [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"AVVISO PUBBLICO IL SINDACO In questo momento di grande difficolt\u00e0 economica e sociale dovuta all&#8217;emergenza\u00a0 sanitaria, \u00e8 priorit\u00e0 per L&#8217;Amministrazione Comunale, a causa delle difficolta economiche dovute all\u2019emergenza epidemiologica COVID19, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T16:57:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T04:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda\",\"datePublished\":\"2020-05-19T16:57:49+00:00\",\"dateModified\":\"2020-05-20T04:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/\"},\"wordCount\":335,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/05\\\/ristorante-bar-tavolo-all-aperto.jpg\",\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/\",\"name\":\"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/05\\\/ristorante-bar-tavolo-all-aperto.jpg\",\"datePublished\":\"2020-05-19T16:57:49+00:00\",\"dateModified\":\"2020-05-20T04:56:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/05\\\/ristorante-bar-tavolo-all-aperto.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/05\\\/ristorante-bar-tavolo-all-aperto.jpg\",\"width\":660,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/05\\\/19\\\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino","og_description":"AVVISO PUBBLICO IL SINDACO In questo momento di grande difficolt\u00e0 economica e sociale dovuta all&#8217;emergenza\u00a0 sanitaria, \u00e8 priorit\u00e0 per L&#8217;Amministrazione Comunale, a causa delle difficolta economiche dovute all\u2019emergenza epidemiologica COVID19, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-19T16:57:49+00:00","article_modified_time":"2020-05-20T04:56:44+00:00","og_image":[{"width":660,"height":368,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg","type":"image\/jpeg"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda","datePublished":"2020-05-19T16:57:49+00:00","dateModified":"2020-05-20T04:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/"},"wordCount":335,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg","articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/","name":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg","datePublished":"2020-05-19T16:57:49+00:00","dateModified":"2020-05-20T04:56:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/05\/ristorante-bar-tavolo-all-aperto.jpg","width":660,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/05\/19\/avviso-pubblico-per-richiesta-e-ampliamento-suolo-pubblico-per-consentire-il-distanziamento-sociale-come-presentare-domanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico per richiesta e ampliamento suolo pubblico per consentire il distanziamento sociale: come presentare domanda"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2179"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2179\/revisions"}],"predecessor-version":[{"id":2187,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2179\/revisions\/2187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2183"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}