{"id":2200,"date":"2020-06-01T15:14:39","date_gmt":"2020-06-01T13:14:39","guid":{"rendered":"https:\/\/comunicacity.net\/sorianonelcimino\/?p=2200"},"modified":"2020-06-01T15:14:39","modified_gmt":"2020-06-01T13:14:39","slug":"erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/","title":{"rendered":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#8217;anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020"},"content":{"rendered":"<p>La Regione Lazio, con Deliberazione n 118 del 24\/03\/20 ed in attuazione del decreto del Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca n. 1178\/2019, ammette al beneficio delle borse di studio A. S. 2019\/20 gli studenti residenti nella Regione Lazio frequentanti gli Istituti secondari di secondo grado statali e paritari o i primi tre anni (quarti anni esclusi) di un percorso triennale di IeFP, appartenenti a famiglie con ISEE non superiore ad euro 15.748,78.<\/p>\n<blockquote><p><em>Sono stati riaperti i termini per la raccolta delle domande relative all&#8217;erogazione delle borse di studio di cui al <a href=\"http:\/\/www.regione.lazio.it\/rl_istruzione_giovani\/?vw=contenutidettaglio&amp;id=620\">d. lgs. 63\/2017<\/a> &#8211; annualit\u00e0 2019\/20.<\/p>\n<p>Potranno presentare domanda gli studenti residenti nella Regione Lazio frequentanti gli Istituti secondari di secondo grado statali e paritari e appartenenti a famiglie con ISEE (Indicatore della Situazione Economica Equivalente) non superiore a euro 15.748,78.<\/p>\n<p>Le famiglie interessate dovranno recarsi presso il Comune di residenza per la compilazione delle domande<strong> entro e non oltre il 19 giugno 2020.<\/strong><\/em><\/p><\/blockquote>\n<p><strong> REQUISITI DI ACCESSO:<\/strong><br \/>\n1) essere residenti nel Comune di Soriano nel Cimino;<br \/>\n2) frequentare, nell\u2019anno scolastico in corso (2019\/20), scuole superiori (dal I al V anno) statali o paritarie, o i primi tre anni di\u00a0 un percorso triennale di IeFP;<br \/>\n3) attestazione ISEE (Indicatore della Situazione Economica Equivalente) del nucleo familiare non superiore ad \u20ac 15.748,78, desunta dall\u2019ultima attestazione ISEE in corso di validit\u00e0. Per ultima attestazione ISEE in corso di validit\u00e0 si intende sia la nuova attestazione ISEE 2020 sia quella del 2019, scaduta il 31\/12\/2019 (ma che era in corso di validit\u00e0 all\u2019inizio dell\u2019anno scolastico 2019\/20).<\/p>\n<p><strong>DOCUMENTI<\/strong>:<br \/>\nDomanda (su apposita modulistica fornita dal comune) corredata di copia del documento valido del richiedente e dello studente;<br \/>\nattestazione Indicatore della Situazione Economica Equivalente (I.S.E.E.) come punto 3 dei requisiti.<\/p>\n<p><strong>MODALITA\u2019 DI PRESENTAZIONE DELLE DOMANDE:<\/strong><br \/>\nLa domanda \u00e8 presentata da uno dei genitori o da chi ne ha la rappresentanza legale o dagli stessi studenti se maggiorenni. Le domande andranno redatte in forma chiara e leggibile su appositi modelli disponibili presso il Front Office \u201cPunto Comune\u201d o scaricati direttamente dal sito del comune e potranno essere presentate:<br \/>\n&#8211;\u00a0\u00a0 \u00a0a mano presso l\u2019Ufficio protocollo del Comune;<br \/>\n&#8211;\u00a0\u00a0 \u00a0tramite raccomandata postale A\/R entro il termine di scadenza del bando;<br \/>\n&#8211;\u00a0\u00a0 \u00a0per Posta Elettronica Certificata (PEC) all\u2019indirizzo puntocomunesoriano@pec.it;<br \/>\n&#8211;\u00a0\u00a0 \u00a0per Posta Elettronica all\u2019indirizzo email: politichesociali@comune.sorianonelcimino.vt.it<\/p>\n<p>Si informa che le domande incomplete non saranno prese in considerazione. Per informazioni rivolgersi al Servizio Pubblica Istruzione\u00a0 &#8211; Comune di Soriano nel Cimino\u00a0 &#8211; al seguente numero telefonico\u00a0 0761\/742236\/17.<br \/>\nTERMINE ULTIMO PER LA PRESENTAZIONE DELLE ISTANZE E\u2019 IL GIORNO 15 MAGGIO 2020.<br \/>\nSoriano nel Cimino, 27\/04\/20<\/p>\n<p>IL RESPONSABILE DEL SERVIZIO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 ASSESSORE PUBBLICA ISTRUZIONE<br \/>\nDott MAURIZIO CAPPONI\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 CHIANI RACHELE<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2202\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/Allegato_A_MODELLO_DOMANDA_BORSA_DI_STUDIO_IOSTUDIO.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/Allegato_A_MODELLO_DOMANDA_BORSA_DI_STUDIO_IOSTUDIO.docx', '_system'); return false;\"><i class='icon attachment'><\/i>Allegato_A_MODELLO_DOMANDA_BORSA_DI_STUDIO_IOSTUDIO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2203\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/BANDO-AS-2019-E-20.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/BANDO-AS-2019-E-20.docx', '_system'); return false;\"><i class='icon attachment'><\/i>BANDO AS 2019 E 20<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio, con Deliberazione n 118 del 24\/03\/20 ed in attuazione del decreto del Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca n. 1178\/2019, ammette al beneficio delle borse di studio [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":2201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-2200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#039;anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020 - Soriano nel Cimino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#039;anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020 - Soriano nel Cimino\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio, con Deliberazione n 118 del 24\/03\/20 ed in attuazione del decreto del Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca n. 1178\/2019, ammette al beneficio delle borse di studio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Soriano nel Cimino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T13:14:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"406\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ComuneSoriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComuneSoriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/\"},\"author\":{\"name\":\"ComuneSoriano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"headline\":\"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#8217;anno scolastico 2019\\\/2020. Bando prorogato fino al 19\\\/06\\\/2020\",\"datePublished\":\"2020-06-01T13:14:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/\"},\"wordCount\":453,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/io_studio_Borse_studenti.png\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/\",\"name\":\"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l'anno scolastico 2019\\\/2020. Bando prorogato fino al 19\\\/06\\\/2020 - Soriano nel Cimino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/io_studio_Borse_studenti.png\",\"datePublished\":\"2020-06-01T13:14:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/io_studio_Borse_studenti.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2020\\\/06\\\/io_studio_Borse_studenti.png\",\"width\":406,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/2020\\\/06\\\/01\\\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#8217;anno scolastico 2019\\\/2020. Bando prorogato fino al 19\\\/06\\\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/\",\"name\":\"Soriano nel Cimino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/#\\\/schema\\\/person\\\/4366190ed67a4511e18b5a9219a488a3\",\"name\":\"ComuneSoriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g\",\"caption\":\"ComuneSoriano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sorianonelcimino\\\/author\\\/lauraevangelista\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l'anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020 - Soriano nel Cimino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l'anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020 - Soriano nel Cimino","og_description":"La Regione Lazio, con Deliberazione n 118 del 24\/03\/20 ed in attuazione del decreto del Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca n. 1178\/2019, ammette al beneficio delle borse di studio [&hellip;]","og_url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/","og_site_name":"Soriano nel Cimino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-01T13:14:39+00:00","og_image":[{"width":406,"height":406,"url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png","type":"image\/png"}],"author":"ComuneSoriano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ComuneSoriano","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/"},"author":{"name":"ComuneSoriano","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"headline":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#8217;anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020","datePublished":"2020-06-01T13:14:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/"},"wordCount":453,"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/","url":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/","name":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l'anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020 - Soriano nel Cimino","isPartOf":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png","datePublished":"2020-06-01T13:14:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png","contentUrl":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-content\/uploads\/sites\/46\/2020\/06\/io_studio_Borse_studenti.png","width":406,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/2020\/06\/01\/erogazione-borse-di-studio-in-favore-degli-studenti-delle-scuole-secondarie-di-secondo-grado-statali-e-paritarie-per-lanno-scolastico-2019-2020-bando-prorogato-fino-al-19-06-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sorianonelcimino\/"},{"@type":"ListItem","position":2,"name":"Erogazione borse di studio in favore degli studenti delle scuole secondarie di secondo grado statali e paritarie per l&#8217;anno scolastico 2019\/2020. Bando prorogato fino al 19\/06\/2020"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#website","url":"https:\/\/comunicacity.net\/sorianonelcimino\/","name":"Soriano nel Cimino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sorianonelcimino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sorianonelcimino\/#\/schema\/person\/4366190ed67a4511e18b5a9219a488a3","name":"ComuneSoriano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84f8609e22d53106c74ac4964b3adc4a2ded6d688c0e1bdac46f7cd639b8b21e?s=96&d=mm&r=g","caption":"ComuneSoriano"},"url":"https:\/\/comunicacity.net\/sorianonelcimino\/author\/lauraevangelista\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/comments?post=2200"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2200\/revisions"}],"predecessor-version":[{"id":2204,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/posts\/2200\/revisions\/2204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media\/2201"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/media?parent=2200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/categories?post=2200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sorianonelcimino\/wp-json\/wp\/v2\/tags?post=2200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}